{"id":9145,"date":"2021-04-27T14:58:38","date_gmt":"2021-04-27T19:58:38","guid":{"rendered":"https:\/\/niixer.com\/?p=9145"},"modified":"2021-04-27T14:58:40","modified_gmt":"2021-04-27T19:58:40","slug":"videojuego-explorer-world-como-modelo-educativo","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/","title":{"rendered":"Videojuego Explorer world  como modelo educativo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Explorer world un videojuego desarrollado con <a href=\"https:\/\/unity.com\/\">Unity<\/a> donde explicara partes del mundo y sus caracter\u00edsticas mas destacables de cada una.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Unity como motor de juegos<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-logo-1024x544.png\" alt=\"\" class=\"wp-image-9192\" width=\"222\" height=\"118\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-logo-1024x544.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-logo-300x160.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-logo-768x408.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-logo-1536x817.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-logo-2048x1089.png 2048w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-logo-390x205.png 390w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar \u00bfQue es Unity? &#8220;<a href=\"https:\/\/unity.com\/\">Unity<\/a> es un motor de videojuegos multiplataforma creado por la compa\u00f1\u00eda de Unity Technologies; el cual est\u00e1 disponible para desarrollar en los sistemas operativos conocidos como Windows, Linux y Mac\u00a0 Os&#8221;. A partir de esta definici\u00f3n de que es Unity hablaremos de los elementos o los assets como es conocido dentro de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Unity_(motor_de_videojuego)\">Unity<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Assets para los juegos<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-asset-store-website-1024x540.jpg\" alt=\"unity assets store\" class=\"wp-image-9193\" width=\"655\" height=\"345\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-asset-store-website-1024x540.jpg 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-asset-store-website-300x158.jpg 300w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-asset-store-website-768x405.jpg 768w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-asset-store-website-1536x810.jpg 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-asset-store-website-390x205.jpg 390w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/unity-asset-store-website.jpg 1600w\" sizes=\"auto, (max-width: 655px) 100vw, 655px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Los Assets o modelos para la creaci\u00f3n de los juegos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar lugar con <a href=\"https:\/\/es.wikipedia.org\/wiki\/Unity_(motor_de_videojuego)\">Unity<\/a> ofrece el servicio de tienda de <a href=\"https:\/\/assetstore.unity.com\/\">assets  <\/a>(Los assets son representaciones de modelos 3D, archivos de audio entre otros que Unity soporta). Ya que estos <a href=\"https:\/\/assetstore.unity.com\/\">assets <\/a>hacen que la ambientaci\u00f3n y los los objetos que tienen los videojuegos den un toque de realismo sobre lo que se est\u00e1 jugando, por lo tanto entre m\u00e1s real sean los modelos y las adecuaciones de cada nivel, as\u00ed mismo ser\u00e1 mucho mejor para el juego en relaci\u00f3n usuario y el juego.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Los sistemas de part\u00edculas como mecanismo para ambientar<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/PartSysEffectPanel.png\" alt=\"unity- sistema de particulas\" class=\"wp-image-9194\" width=\"344\" height=\"158\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/PartSysEffectPanel.png 405w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/PartSysEffectPanel-300x138.png 300w\" sizes=\"auto, (max-width: 344px) 100vw, 344px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En segundo lugar y adem\u00e1s de trabajar con los modelos tambi\u00e9n para dar una buena ambientaci\u00f3n es necesario usar lo que se conoce como <a href=\"https:\/\/docs.unity3d.com\/es\/530\/Manual\/ParticleSystems.html#:~:text=En%20un%20juego%203D%2C%20la,con%20una%20figura%20bien%20definida.\">sistemas de part\u00edculas<\/a>. Con todo esto los efectos de part\u00edculas  ofrecen que la experiencia de que el videojuego sea m\u00e1s realista de forma en que se dise\u00f1a los escenarios; En realidad los sistemas de part\u00edculas pueden ser utilizados para simular l\u00edquidos, frio, oscuridad, fuego o luz en todo el juego para que en consecuencia de los efectos el juego tenga una apariencia mucho m\u00e1s realista.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Builds asi como mecanismo para interactuar en las plataformas<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/IL2CPP-1-1024x993.png\" alt=\"unity- build\" class=\"wp-image-9195\" width=\"216\" height=\"209\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/IL2CPP-1-1024x993.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/IL2CPP-1-300x291.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/IL2CPP-1-768x745.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/IL2CPP-1.png 1260w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma unity nos ofrece la facilidad de que todos los videojuegos que dise\u00f1emos en la plataforma los podemos construir para las distintas plataformas en los que se podr\u00e1 ejecutar tales como: para computador aplicaciones stand alone y en html, dispositivos ios adem\u00e1s de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Android\">android<\/a>, <a href=\"https:\/\/es.wikipedia.org\/wiki\/Apple_TV\">apple tv<\/a>,<a href=\"https:\/\/es.wikipedia.org\/wiki\/Xbox_One\"> microsoft xbox one<\/a>, <a href=\"https:\/\/es.wikipedia.org\/wiki\/PlayStation_4\">sony playstation 4<\/a> y <a href=\"https:\/\/es.wikipedia.org\/wiki\/PlayStation_Vita\">ps vita<\/a>, hasta para televisores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente y como resultado a el uso de todas estas herramientas como lo son los <a href=\"https:\/\/unity3d.com\/es\/quick-guide-to-unity-asset-store\">assets<\/a>, los sistemas de part\u00edculas, modelos y con el uso de scripts se pudo hacer realidad el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Videojuego\">videojuego <\/a>explorer world mediante la combinaci\u00f3n de todos estos elementos se dio vida al videojuego en donde  seguramente todo funciona con todo de forma en que con los modelos se ambiento parte del videojuego, tambi\u00e9n para los sistemas de part\u00edculas para\u00a0dar el efecto de realismo en cada nivel por ejemplo el viento que hace en el polo norte, adem\u00e1s de los efectos cada vez se colisionaba y\/o interactuaba el jugador con alg\u00fan material y los <a href=\"https:\/\/es.wikipedia.org\/wiki\/Script\">scripts <\/a>para que todas las funcionalidades que eran necesarias para darle un sentido al videojuego. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado a la combinaci\u00f3n de todo lo anteriormente mencionado se logro la realizaci\u00f3n de un videojuego o en el caso de explorer world es una magia de mezclar una serie objetos con sus funcionalidades para darle una finalidad y un objetivo de interacci\u00f3n entre el videojuego y el usuario final que es quien probar\u00e1 nuestra creaci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/8tyUDBFGQNh0ZmD6kUfr3HOVlrmELEEMdgSqdCGfn2xNGSNml20nyY7LlcgNMPvKT52lRiJJ4AZtDu7rq-u_YjIL9MaeySdDoguxfWOP3TFIMiyjQ4EVmiMW7tvD7jy4djdB_78O\" alt=\"\" width=\"711\" height=\"278\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor<\/strong>: <a href=\"https:\/\/niixer.com\/?s=gustavo+delgado\">Gustavo Andres Delgado Guzman<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor<\/strong>: <a href=\"https:\/\/niixer.com\/\">Carlos Pinz\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo<\/strong>: UCMV-8<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad: Universidad Central<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">FUENTES:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Unity. (2020). <em>En wikipedia.<\/em> [Fotograf\u00eda].&nbsp;<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Unity. (2020). <em>En wikipedia.<\/em> [Fotograf\u00eda]. <a href=\"https:\/\/es.wikipedia.org\/wiki\/Unity_(motor_de_videojuego)\">https:\/\/es.wikipedia.org\/wiki\/Unity_(motor_de_videojuego)<\/a><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Unity. (2020). <em>En wikipedia<\/em>.&nbsp;<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><a href=\"https:\/\/es.wikipedia.org\/wiki\/Unity_(motor_de_videojuego)\">https:\/\/es.wikipedia.org\/wiki\/Unity_(motor_de_videojuego)<\/a><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-318171a5-e142-4134-a896-62b11edb03b5\"><em>Technologies, U. (2021). Unity &#8211; Manual: Sistema de Part\u00edculas. En unity. [Fotograf\u00eda].&nbsp;<\/em><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Technologies, U. (2021). Unity - Manual: Build project. En unity. [Fotograf\u00eda].\n <a href=\"https:\/\/docs.unity3d.com\/es\/2018.4\/Manual\/PartSysUsage.html\">https:\/\/docs.unity3d.com\/es\/2018.4\/Manual\/PartSysUsage.html<\/a>.&nbsp;&nbsp;<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-318171a5-e142-4134-a896-62b11edb03b5\"><em>Technologies, U. (2021). Unity &#8211; Manual: Build Project. En unity. [Fotograf\u00eda].&nbsp;<\/em><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Technologies, U. (2021). Unity - Manual: Build project. En unity. [Fotograf\u00eda]. <a href=\"https:\/\/docs.unity3d.com\/es\/2018.4\/Manual\/IL2CPP-BuildingProject.html\">https:\/\/docs.unity3d.com\/es\/2018.4\/Manual\/IL2CPP-BuildingProject.html<\/a>&nbsp;&nbsp;<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-318171a5-e142-4134-a896-62b11edb03b5\"><em>Technologies, U. (2021). Unity &#8211; Manual: Asset Store. En unity. [Fotograf\u00eda].&nbsp;<\/em><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Technologies, U. (2021). Unity - Manual: Unity Asset Store. En unity. [Fotograf\u00eda].&nbsp; <a href=\"https:\/\/unity3d.com\/es\/quick-guide-to-unity-asset-store\">https:\/\/unity3d.com\/es\/quick-guide-to-unity-asset-store<\/a>&nbsp;<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"block-318171a5-e142-4134-a896-62b11edb03b5\"><em>Delgado.G. Explorer World documentaci\u00f3n. En unity. [Fotograf\u00eda].&nbsp;<\/em><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Delgado, G. Explorer World documentaci\u00f3n [Documente]. [Fotograf\u00eda].&nbsp;<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Explorer world un videojuego desarrollado con Unity donde explicara partes del mundo y sus caracter\u00edsticas mas destacables de cada una. Unity como motor de juegos En primer lugar \u00bfQue es Unity? &#8220;Unity es un motor de videojuegos multiplataforma creado por la compa\u00f1\u00eda de Unity Technologies; el cual est\u00e1 disponible paraSeguir Leyendo<\/p>\n","protected":false},"author":49,"featured_media":9197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[77],"tags":[268,515,214,836,66],"class_list":["post-9145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videojuegos","tag-educacion","tag-industria-de-videojuegos","tag-unity","tag-unity-3d","tag-videojuegos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Videojuego Explorer world como modelo educativo &#8211; Videojuegos<\/title>\n<meta name=\"description\" content=\"Explorer world un videojuego desarrollado con Unity donde explicara partes del mundo y sus caracter\u00edsticas mas destacables de cada una.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Videojuego Explorer world como modelo educativo &#8211; Videojuegos\" \/>\n<meta property=\"og:description\" content=\"Explorer world un videojuego desarrollado con Unity donde explicara partes del mundo y sus caracter\u00edsticas mas destacables de cada una.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-27T19:58:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-27T19:58:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/Captura-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gustavo Andres Delgado Guzman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Andres Delgado Guzman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Videojuego Explorer world como modelo educativo &#8211; Videojuegos","description":"Explorer world un videojuego desarrollado con Unity donde explicara partes del mundo y sus caracter\u00edsticas mas destacables de cada una.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/","og_locale":"es_ES","og_type":"article","og_title":"Videojuego Explorer world como modelo educativo &#8211; Videojuegos","og_description":"Explorer world un videojuego desarrollado con Unity donde explicara partes del mundo y sus caracter\u00edsticas mas destacables de cada una.","og_url":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2021-04-27T19:58:38+00:00","article_modified_time":"2021-04-27T19:58:40+00:00","og_image":[{"width":1150,"height":451,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/Captura-5.png","type":"image\/png"}],"author":"Gustavo Andres Delgado Guzman","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gustavo Andres Delgado Guzman","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/"},"author":{"name":"Gustavo Andres Delgado Guzman","@id":"https:\/\/niixer.com\/#\/schema\/person\/39aa180b0494de69778ebb748fb8f216"},"headline":"Videojuego Explorer world como modelo educativo","datePublished":"2021-04-27T19:58:38+00:00","dateModified":"2021-04-27T19:58:40+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/"},"wordCount":639,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/Captura-5.png","keywords":["educaci\u00f3n","industria de videojuegos","Unity","Unity 3D","Videojuegos"],"articleSection":["Videojuegos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/","url":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/","name":"Videojuego Explorer world como modelo educativo &#8211; Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/Captura-5.png","datePublished":"2021-04-27T19:58:38+00:00","dateModified":"2021-04-27T19:58:40+00:00","description":"Explorer world un videojuego desarrollado con Unity donde explicara partes del mundo y sus caracter\u00edsticas mas destacables de cada una.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/Captura-5.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/04\/Captura-5.png","width":1150,"height":451,"caption":"videojuego explorer world"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2021\/04\/27\/videojuego-explorer-world-como-modelo-educativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Videojuego Explorer world como modelo educativo"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/39aa180b0494de69778ebb748fb8f216","name":"Gustavo Andres Delgado Guzman","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/50790e18fad1c81f1c93dd052df85bac55e1c76476abff80c7155289bf240c53?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50790e18fad1c81f1c93dd052df85bac55e1c76476abff80c7155289bf240c53?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50790e18fad1c81f1c93dd052df85bac55e1c76476abff80c7155289bf240c53?s=96&d=mm&r=g","caption":"Gustavo Andres Delgado Guzman"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/gdelgadog1\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/9145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=9145"}],"version-history":[{"count":3,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/9145\/revisions"}],"predecessor-version":[{"id":9198,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/9145\/revisions\/9198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/9197"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=9145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=9145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=9145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}