{"id":78448,"date":"2026-02-27T00:42:00","date_gmt":"2026-02-27T05:42:00","guid":{"rendered":"https:\/\/niixer.com\/?p=78448"},"modified":"2026-02-27T00:43:24","modified_gmt":"2026-02-27T05:43:24","slug":"modelado-de-cascanueces","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/","title":{"rendered":"Modelado de Cascanueces"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Paso a paso\u00a0\u00a0<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><a href=\"https:\/\/niixer.com\/index.php\/2025\/11\/26\/modelado-3d-y-animacion-creacion-mundo-navideno-tematico-inspirado-en-mcdonalds\/\">Modelado<\/a> de la Estructura Base Cuerpo (Cilindro): <\/strong><br><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Agrega un cilindro. En Modo Edici\u00f3n, escala en el eje Z (S + Z) para darle altura.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"693\" height=\"409\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-730.png\" alt=\"cuerpo\" class=\"wp-image-79888\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-730.png 693w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-730-300x177.png 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><a href=\"https:\/\/niixer.com\/index.php\/2021\/05\/29\/guia-del-modelado-de-una-cabeza-en-blender\/\">Cabeza<\/a>:<\/strong> <\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Duplica el cuerpo (Shift + D), mu\u00e9velo hacia arriba y reduce su tama\u00f1o general.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"841\" height=\"559\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-737.png\" alt=\"caveza\" class=\"wp-image-79896\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-737.png 841w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-737-300x199.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-737-768x510.png 768w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Extremidades: <\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Crea un cilindro nuevo para la pierna. Para los brazos, usa otro cilindro y r\u00f3talo 90 grados.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"828\" height=\"511\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-738.png\" alt=\"brazo y pierna\" class=\"wp-image-79899\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-738.png 828w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-738-300x185.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-738-768x474.png 768w\" sizes=\"auto, (max-width: 828px) 100vw, 828px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><a href=\"https:\/\/niixer.com\/index.php\/2021\/08\/18\/ray-tracing-mas-alla-de-reflejos-bonitos-en-video-juegos\/\">Reflejo<\/a>: <\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para no trabajar doble, selecciona la pierna, ve a la <a href=\"https:\/\/www.oboticario.com.co\/collections\/maquillaje-pestanina\">pesta\u00f1a<\/a> de Modificadores (icono de llave inglesa), a\u00f1ade un\u00a0Mirror\u00a0(Espejo) y selecciona el cuerpo central como &#8220;Mirror\u00a0Object&#8221;. Repite con el brazo.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"811\" height=\"523\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-734.png\" alt=\"Espejo\" class=\"wp-image-79895\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-734.png 811w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-734-300x193.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-734-768x495.png 768w\" sizes=\"auto, (max-width: 811px) 100vw, 811px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Refinamiento de Formas (Bevel\u00a0y Extrusiones) Bordes Suaves: <\/strong><br><br><br><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selecciona los aros de bordes (Alt + Clic) de la cabeza y el cuerpo. Presiona\u00a0Ctrl\u00a0+ B y desliza el rat\u00f3n para crear un bisel. Usa la rueda del rat\u00f3n para a\u00f1adir segmentos y que se vea redondeado.\u00a0<\/li>\n<\/ul>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"865\" height=\"511\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-741.png\" alt=\"bordes\" class=\"wp-image-79901\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-741.png 865w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-741-300x177.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-741-768x454.png 768w\" sizes=\"auto, (max-width: 865px) 100vw, 865px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>El <a href=\"https:\/\/www.velez.com.co\/outlet\/cinturones\">Cintur\u00f3n<\/a>: <\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selecciona el anillo de caras en medio del cuerpo. Presiona Shift + D para duplicarlas, luego P >\u00a0Selection\u00a0para separarlo como un objeto nuevo. Entra en edici\u00f3n de ese nuevo objeto y usa Alt + S para inflarlo un poco hacia afuera.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"901\" height=\"450\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-733.png\" alt=\"cinturon\" class=\"wp-image-79889\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-733.png 901w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-733-300x150.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-733-768x384.png 768w\" sizes=\"auto, (max-width: 901px) 100vw, 901px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Hombreras: <\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Selecciona la cara superior del brazo, haz una extrusi\u00f3n peque\u00f1a (E), <a href=\"https:\/\/niixer.com\/index.php\/2025\/08\/20\/simulacion-multiescala-computacion-grafica\/\">escala<\/a> hacia afuera (S) y extruye de nuevo hacia arriba para dar volumen.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"622\" height=\"528\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-748.png\" alt=\"hombreras\" class=\"wp-image-79920\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-748.png 622w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-748-300x255.png 300w\" sizes=\"auto, (max-width: 622px) 100vw, 622px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong><a href=\"https:\/\/www.velez.com.co\/outlet\/zapatos\">Zapatos<\/a>:\u00a0<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Usa una\u00a0Esfera, c\u00f3rtala por la mitad en modo edici\u00f3n, rellena la base con\u00a0<strong>F<\/strong>\u00a0y deforma un poco hacia adelante para darle forma de bota.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"481\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-739.png\" alt=\"zapatos\" class=\"wp-image-79898\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-739.png 769w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-739-300x188.png 300w\" sizes=\"auto, (max-width: 769px) 100vw, 769px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"691\" height=\"433\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-736.png\" alt=\"zapato hecho\" class=\"wp-image-79893\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-736.png 691w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-736-300x188.png 300w\" sizes=\"auto, (max-width: 691px) 100vw, 691px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Detalles<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Para los botones, se cre\u00f3 una esfera, se le ajusta el tama\u00f1o y se duplica, adem\u00e1s se sit\u00faan donde se quiere y se hace una modificaci\u00f3n a cada esfera, creando un <a href=\"https:\/\/niixer.com\/index.php\/2020\/12\/13\/leica-lanza-nueva-camara-sin-espejo-de-alta-calidad\/\">espejo<\/a>, para que queden exactamente a la misma distancia.\u00a0<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"322\" height=\"496\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-731.png\" alt=\"botones\" class=\"wp-image-79890\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-731.png 322w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-731-195x300.png 195w\" sizes=\"auto, (max-width: 322px) 100vw, 322px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para las manos, se cre\u00f3 una esfera, se le ajusta el tama\u00f1o y la posici\u00f3n, y se hace una modificaci\u00f3n a la esfera, creando un espejo, para que queden exactamente a la misma distancia.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"534\" height=\"585\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-732.png\" alt=\"manos\" class=\"wp-image-79892\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-732.png 534w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-732-274x300.png 274w\" sizes=\"auto, (max-width: 534px) 100vw, 534px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Resultado<\/strong>\u00a0<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"1024\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-735-605x1024.png\" alt=\"final\" class=\"wp-image-79894\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-735-605x1024.png 605w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-735-177x300.png 177w, https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/image-735.png 712w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conclusi\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El modelado de un cascanueces en Blender demuestra que la combinaci\u00f3n de formas geom\u00e9tricas b\u00e1sicas y modificadores avanzados, como el <strong>Mirror<\/strong> y el <strong>Subdivision Surface<\/strong>, permite crear estructuras complejas de manera eficiente. Este enfoque optimiza el flujo de trabajo al reducir la carga de modelado manual, asegurando una simetr\u00eda perfecta y una topolog\u00eda suavizada que es fundamental para el acabado profesional del activo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En \u00faltima instancia, este proceso evidencia que el dominio de las herramientas de transformaci\u00f3n y la edici\u00f3n de nodos de textura no solo enriquecen la est\u00e9tica del modelo, sino que tambi\u00e9n establecen las bases t\u00e9cnicas necesarias para una transici\u00f3n fluida hacia las etapas de animaci\u00f3n y renderizado final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n cabe resaltar que hay un video de apoyo que pueden utilizar para complementar y enriquecer m\u00e1s el modelado del cascanueces<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Como hacer un cascanueces en Blender\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/gDmjby5SGrA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cr\u00e9ditos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor<\/strong>: <a href=\"https:\/\/niixer.com\/?s=Juli\u00e1n+David+Garz\u00f3n+Fuquen\">Juli\u00e1n David Garz\u00f3n Fuquen<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor<\/strong>: <a href=\"https:\/\/niixer.com\/?s=Carlos+Iv\u00e1n+Pinz\u00f3n+Romero\">Magister Ingeniero Carlos Iv\u00e1n Pinz\u00f3n Romero<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo:<\/strong> <a href=\"https:\/\/niixer.com\/?s=UCMV-10\">UCMV-10<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad:<\/strong> <a href=\"https:\/\/www.ucentral.edu.co\/\">Universidad Central<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Grupo MARZA. (22 de diciembre de 2022). <em>Como hacer un cascanueces en Blender<\/em> [Video]. YouTube. <a href=\"https:\/\/www.youtube.com\/watch?v=gDmjby5SGrA\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.youtube.com\/watch?v=gDmjby5SGrA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paso a paso\u00a0\u00a0 Modelado de la Estructura Base Cuerpo (Cilindro): Cabeza: Extremidades: Reflejo: Refinamiento de Formas (Bevel\u00a0y Extrusiones) Bordes Suaves: El Cintur\u00f3n: Hombreras: Zapatos:\u00a0 Detalles Para las manos, se cre\u00f3 una esfera, se le ajusta el tama\u00f1o y la posici\u00f3n, y se hace una modificaci\u00f3n a la esfera, creando unSeguir Leyendo<\/p>\n","protected":false},"author":2059,"featured_media":79928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[4324],"tags":[473,1352],"class_list":["post-78448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-modelado-2","tag-blender","tag-modelado-3d"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modelado de Cascanueces &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos<\/title>\n<meta name=\"description\" content=\"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelado de Cascanueces\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelado de Cascanueces &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"og:description\" content=\"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelado de Cascanueces\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-27T05:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T05:43:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/Cascanueces.png\" \/>\n\t<meta property=\"og:image:width\" content=\"581\" \/>\n\t<meta property=\"og:image:height\" content=\"1117\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fuquen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fuquen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelado de Cascanueces &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelado de Cascanueces","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/","og_locale":"es_ES","og_type":"article","og_title":"Modelado de Cascanueces &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","og_description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelado de Cascanueces","og_url":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2026-02-27T05:42:00+00:00","article_modified_time":"2026-02-27T05:43:24+00:00","og_image":[{"width":581,"height":1117,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/Cascanueces.png","type":"image\/png"}],"author":"Fuquen","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fuquen","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/"},"author":{"name":"Fuquen","@id":"https:\/\/niixer.com\/#\/schema\/person\/d334b07a647ebbec0575d42e7ede6322"},"headline":"Modelado de Cascanueces","datePublished":"2026-02-27T05:42:00+00:00","dateModified":"2026-02-27T05:43:24+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/"},"wordCount":535,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/Cascanueces.png","keywords":["Blender","modelado 3D"],"articleSection":["MODELADO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/","url":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/","name":"Modelado de Cascanueces &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/Cascanueces.png","datePublished":"2026-02-27T05:42:00+00:00","dateModified":"2026-02-27T05:43:24+00:00","description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelado de Cascanueces","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/Cascanueces.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2026\/02\/Cascanueces.png","width":581,"height":1117},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2026\/02\/27\/modelado-de-cascanueces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Modelado de Cascanueces"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/d334b07a647ebbec0575d42e7ede6322","name":"Fuquen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0ff9d85abb4ddd69cb776aee700c43ba03de9beb5f1f16e0171c15a8d5965c93?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ff9d85abb4ddd69cb776aee700c43ba03de9beb5f1f16e0171c15a8d5965c93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ff9d85abb4ddd69cb776aee700c43ba03de9beb5f1f16e0171c15a8d5965c93?s=96&d=mm&r=g","caption":"Fuquen"},"url":"https:\/\/niixer.com\/index.php\/author\/jgarzonf\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/78448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/2059"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=78448"}],"version-history":[{"count":2,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/78448\/revisions"}],"predecessor-version":[{"id":79926,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/78448\/revisions\/79926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/79928"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=78448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=78448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=78448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}