{"id":73024,"date":"2025-11-26T14:51:53","date_gmt":"2025-11-26T19:51:53","guid":{"rendered":"https:\/\/niixer.com\/?p=73024"},"modified":"2025-11-26T21:09:03","modified_gmt":"2025-11-27T02:09:03","slug":"cortometraje-navideno-3d","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/","title":{"rendered":"El regalo imposible &#8211; Animaci\u00f3n Blender 3D"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>Introducci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto est\u00e1 basado en un contexto navide\u00f1o; sin embargo, se opt\u00f3 por algo diferente sin olvidar la tem\u00e1tica principal. Acorde con ese contexto, se tomaron marcas como referencia para, a partir de ah\u00ed, desarrollar una idea. En este caso, mi marca principal es Adidas; no obstante, propuse una segunda marca, Millonarios, con el fin de manejar una animaci\u00f3n l\u00f3gica y coordinada.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-1024x683.png\" alt=\"\" class=\"wp-image-74763\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-1024x683.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-300x200.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-768x512.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44.png 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El contexto gira en torno a que, despu\u00e9s de una mala temporada del equipo, ambas marcas colaboran para traer a Messi, quien es fichado en diciembre para la nueva temporada. El cortometraje consiste en la presentaci\u00f3n del jugador, la sala de prensa y otros escenarios relacionados con esta introducci\u00f3n. Todo el proyecto, en conjunto, se titula <strong>\u201cEl Regalo Imposible\u201d<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Durante este art\u00edculo se mostrar\u00e1 el procedimiento y la construcci\u00f3n de todo lo que incluy\u00f3 el cortometraje.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>PRIMER ESCENARIO<\/strong> &#8211; SALA DE PRENSA<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para este escenario comenzamos con dos factores primordiales para dar a entender que es Navidad. El primero es el <strong>\u00e1rbol de Navidad<\/strong>. Con <strong>Shift + A<\/strong> generamos una circunferencia, a la cual posteriormente le aplicamos sombreado suave mediante clic derecho. Luego, en las propiedades del objeto, nos encargamos de asignarle un material, a\u00f1adiendo un punto de<strong> iluminaci\u00f3n movi\u00e9ndolo<\/strong> con <strong>G+Y, G+X o G+Z<\/strong> al cual se le puede modificar el <strong>color o la textura<\/strong> seg\u00fan sea necesario (se dejan ambas opciones para mayor claridad).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este mismo procedimiento se realiz\u00f3 con otras tres esferas, para un total de cuatro, copiando el mismo estilo. La \u00fanica diferencia es que a cada una se le a\u00f1adi\u00f3 un color o una textura diferente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_37_23-1024x542.png\" alt=\"\" class=\"wp-image-74141\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_37_23-1024x542.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_37_23-300x159.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_37_23-768x407.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_37_23-1536x814.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_37_23-390x205.png 390w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_37_23.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_39_23-1024x542.png\" alt=\"\" class=\"wp-image-74140\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_39_23-1024x542.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_39_23-300x159.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_39_23-768x407.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_39_23-1536x814.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_39_23-390x205.png 390w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_39_23.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_41_32-3-1024x576.png\" alt=\"\" class=\"wp-image-74149\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_41_32-3-1024x576.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_41_32-3-300x169.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-12_11_2025-14_41_32-3.png 1340w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1561\" height=\"846\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CODIGO-DE-COLOR-AZUL-MILLONARIOS-Buscar-con-Google-Google-Chrome-12_11_2025-14_48_43-edited.png\" alt=\"\" class=\"wp-image-74156\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CODIGO-DE-COLOR-AZUL-MILLONARIOS-Buscar-con-Google-Google-Chrome-12_11_2025-14_48_43-edited.png 1561w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CODIGO-DE-COLOR-AZUL-MILLONARIOS-Buscar-con-Google-Google-Chrome-12_11_2025-14_48_43-edited-300x163.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CODIGO-DE-COLOR-AZUL-MILLONARIOS-Buscar-con-Google-Google-Chrome-12_11_2025-14_48_43-edited-1024x555.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CODIGO-DE-COLOR-AZUL-MILLONARIOS-Buscar-con-Google-Google-Chrome-12_11_2025-14_48_43-edited-768x416.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CODIGO-DE-COLOR-AZUL-MILLONARIOS-Buscar-con-Google-Google-Chrome-12_11_2025-14_48_43-edited-1536x832.png 1536w\" sizes=\"auto, (max-width: 1561px) 100vw, 1561px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_49_23-1024x542.png\" alt=\"\" class=\"wp-image-74157\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_49_23-1024x542.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_49_23-300x159.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_49_23-768x407.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_49_23.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1017\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_50_39.png\" alt=\"\" class=\"wp-image-74150\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_50_39.png 1920w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_50_39-300x159.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_50_39-1024x542.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_50_39-768x407.png 768w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_24-1024x542.png\" alt=\"\" class=\"wp-image-74158\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_24-1024x542.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_24-300x159.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_24-768x407.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_24.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_58-1024x542.png\" alt=\"\" class=\"wp-image-74159\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_58-1024x542.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_58-300x159.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_58-768x407.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_51_58.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1017\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_53_48.png\" alt=\"\" class=\"wp-image-74151\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_53_48.png 1920w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_53_48-300x159.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_53_48-1024x542.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-14_53_48-768x407.png 768w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ya teniendo las bolas de Navidad, continuamos con lo m\u00e1s importante: el \u00e1rbol. Para ello, se implement\u00f3 una extensi\u00f3n desde la secci\u00f3n de <strong>Preferencias<\/strong>. Buscamos <strong>Sapling Tree Gen<\/strong> y lo instalamos. Luego, con <strong>Shift + A<\/strong>, en el apartado de <strong>Curva<\/strong>, aparece como \u00faltima opci\u00f3n la extensi\u00f3n que descargamos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez implementado, se despliega una serie de opciones con las que podemos modificar la forma del \u00e1rbol; en este caso, se utiliz\u00f3 la forma <strong>Rectangle<\/strong>. R\u00e1pidamente se le asign\u00f3 un material con una textura o color tipo madera y se aplic\u00f3 un sombreado suave.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de esto, nos dirigimos a la secci\u00f3n de <strong>Shading<\/strong> con el fin de aplicar un degradado en las hojas, evitando que queden de un solo color. En esta secci\u00f3n aparece un panel donde se agrega un <strong>Color Ramp<\/strong> (con <strong>Shift + A<\/strong>) y se conecta al <strong>Base Color<\/strong>. Con ello configuramos el degradado y su intensidad.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"519\" data-id=\"74161\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Preferencias-12_11_2025-15_03_05.png\" alt=\"\" class=\"wp-image-74161\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Preferencias-12_11_2025-15_03_05.png 660w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Preferencias-12_11_2025-15_03_05-300x236.png 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"519\" data-id=\"74162\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Preferencias-12_11_2025-15_02_00.png\" alt=\"\" class=\"wp-image-74162\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Preferencias-12_11_2025-15_02_00.png 660w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Preferencias-12_11_2025-15_02_00-300x236.png 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"520\" data-id=\"74164\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ARBOL.png\" alt=\"\" class=\"wp-image-74164\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ARBOL.png 660w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ARBOL-300x236.png 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"519\" data-id=\"74163\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Preferencias-12_11_2025-15_03_13.png\" alt=\"\" class=\"wp-image-74163\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Preferencias-12_11_2025-15_03_13.png 660w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Preferencias-12_11_2025-15_03_13-300x236.png 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"583\" height=\"583\" data-id=\"74165\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_04_11.png\" alt=\"\" class=\"wp-image-74165\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_04_11.png 583w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_04_11-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_04_11-150x150.png 150w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"295\" height=\"597\" data-id=\"74166\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_05_24.png\" alt=\"\" class=\"wp-image-74166\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_05_24.png 295w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_05_24-148x300.png 148w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"394\" height=\"491\" data-id=\"74170\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_06_11.png\" alt=\"\" class=\"wp-image-74170\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_06_11.png 394w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_06_11-241x300.png 241w\" sizes=\"auto, (max-width: 394px) 100vw, 394px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"506\" height=\"506\" data-id=\"74167\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_04_56.png\" alt=\"\" class=\"wp-image-74167\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_04_56.png 506w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_04_56-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_04_56-150x150.png 150w\" sizes=\"auto, (max-width: 506px) 100vw, 506px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"669\" height=\"669\" data-id=\"74169\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_20_51.png\" alt=\"\" class=\"wp-image-74169\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_20_51.png 669w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_20_51-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_20_51-150x150.png 150w\" sizes=\"auto, (max-width: 669px) 100vw, 669px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"736\" height=\"469\" data-id=\"74168\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/codigo-color-cafe-arbol-de-navidad-Buscar-con-Google-Google-Chrome-12_11_2025-15_22_51.png\" alt=\"\" class=\"wp-image-74168\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/codigo-color-cafe-arbol-de-navidad-Buscar-con-Google-Google-Chrome-12_11_2025-15_22_51.png 736w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/codigo-color-cafe-arbol-de-navidad-Buscar-con-Google-Google-Chrome-12_11_2025-15_22_51-300x191.png 300w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"605\" data-id=\"74171\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_22_46.png\" alt=\"\" class=\"wp-image-74171\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_22_46.png 605w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_22_46-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_22_46-150x150.png 150w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"281\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_26_03.png\" alt=\"\" class=\"wp-image-74172\" style=\"width:451px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_26_03.png 500w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_26_03-300x169.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"822\" height=\"778\" data-id=\"74177\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_23_36.png\" alt=\"\" class=\"wp-image-74177\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_23_36.png 822w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_23_36-300x284.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_23_36-768x727.png 768w\" sizes=\"auto, (max-width: 822px) 100vw, 822px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" data-id=\"74175\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_24_15.png\" alt=\"\" class=\"wp-image-74175\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_24_15.png 801w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_24_15-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_24_15-150x150.png 150w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_24_15-768x768.png 768w\" sizes=\"auto, (max-width: 801px) 100vw, 801px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"317\" data-id=\"74174\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_26_53.png\" alt=\"\" class=\"wp-image-74174\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_26_53.png 771w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_26_53-300x123.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_26_53-768x316.png 768w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"226\" data-id=\"74173\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_28_04.png\" alt=\"\" class=\"wp-image-74173\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_28_04.png 226w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_28_04-150x150.png 150w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"764\" height=\"764\" data-id=\"74176\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_28_28.png\" alt=\"\" class=\"wp-image-74176\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_28_28.png 764w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_28_28-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_28_28-150x150.png 150w\" sizes=\"auto, (max-width: 764px) 100vw, 764px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"657\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_30_40.png\" alt=\"\" class=\"wp-image-74178\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_30_40.png 657w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_30_40-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_30_40-150x150.png 150w\" sizes=\"auto, (max-width: 657px) 100vw, 657px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para los detalles, empezamos duplicando la capa de hojas seg\u00fan el gusto. En cada capa se ajusta la <strong>dimensi\u00f3n<\/strong>, la <strong>altura<\/strong> y la <strong>rotaci\u00f3n<\/strong>; en este caso, la rotaci\u00f3n se realiza con <strong>R + Z<\/strong>.<br>Con esto listo, generamos las bolas y las luces de Navidad para el \u00e1rbol. Para ello, agrupamos los elementos (bolas y luces), ya que despu\u00e9s utilizaremos un sistema de part\u00edculas para distribuir estos detalles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos dirigimos a las propiedades de las hojas y agregamos un <strong>sistema de part\u00edculas<\/strong>, configur\u00e1ndolo en modo <strong>Hair<\/strong>. En la secci\u00f3n <strong>Render<\/strong>, seleccionamos <em>Object<\/em> y luego escogemos las bolas como el objeto instanciado. A partir de ah\u00ed ajustamos la escala y, en caso de necesitar un tama\u00f1o m\u00e1s peque\u00f1o, podemos modificar directamente las esferas que creamos inicialmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este mismo proceso se repite con las dem\u00e1s capas de hojas, de acuerdo con el gusto personal, tanto para las luces como para las esferas.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"638\" height=\"638\" data-id=\"74180\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_34_00.png\" alt=\"\" class=\"wp-image-74180\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_34_00.png 638w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_34_00-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_34_00-150x150.png 150w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"592\" height=\"592\" data-id=\"74179\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/DETALLES-FINALES.png\" alt=\"\" class=\"wp-image-74179\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/DETALLES-FINALES.png 592w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/DETALLES-FINALES-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/DETALLES-FINALES-150x150.png 150w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"695\" height=\"695\" data-id=\"74181\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_37_35.png\" alt=\"\" class=\"wp-image-74181\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_37_35.png 695w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_37_35-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_37_35-150x150.png 150w\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"662\" height=\"662\" data-id=\"74182\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_35_25.png\" alt=\"\" class=\"wp-image-74182\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_35_25.png 662w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_35_25-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_35_25-150x150.png 150w\" sizes=\"auto, (max-width: 662px) 100vw, 662px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"333\" height=\"366\" data-id=\"74183\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_38_58.png\" alt=\"\" class=\"wp-image-74183\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_38_58.png 333w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_38_58-273x300.png 273w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"774\" height=\"774\" data-id=\"74184\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_39_30.png\" alt=\"\" class=\"wp-image-74184\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_39_30.png 774w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_39_30-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_39_30-150x150.png 150w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_39_30-768x768.png 768w\" sizes=\"auto, (max-width: 774px) 100vw, 774px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"542\" data-id=\"74185\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_40_33-1024x542.png\" alt=\"\" class=\"wp-image-74185\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_40_33-1024x542.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_40_33-300x159.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_40_33-768x407.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_40_33-1536x814.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_40_33-390x205.png 390w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_40_33.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"606\" data-id=\"74190\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_41_16-1.png\" alt=\"\" class=\"wp-image-74190\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_41_16-1.png 330w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_41_16-1-163x300.png 163w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"313\" height=\"569\" data-id=\"74189\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_45_27-1.png\" alt=\"\" class=\"wp-image-74189\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_45_27-1.png 313w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_45_27-1-165x300.png 165w\" sizes=\"auto, (max-width: 313px) 100vw, 313px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"328\" height=\"478\" data-id=\"74191\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_42_08-1.png\" alt=\"\" class=\"wp-image-74191\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_42_08-1.png 328w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_42_08-1-206x300.png 206w\" sizes=\"auto, (max-width: 328px) 100vw, 328px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"705\" height=\"705\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_54_41.png\" alt=\"\" class=\"wp-image-74192\" style=\"width:449px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_54_41.png 705w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_54_41-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-15_54_41-150x150.png 150w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"331\" height=\"647\" data-id=\"74193\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/seccion.png\" alt=\"\" class=\"wp-image-74193\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/seccion.png 331w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/seccion-153x300.png 153w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"616\" height=\"616\" data-id=\"74194\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-16_00_43.png\" alt=\"\" class=\"wp-image-74194\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-16_00_43.png 616w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-16_00_43-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-C__Users_User_Downloads_MATERIALES.blend-Blender-4.5.4-LTS-12_11_2025-16_00_43-150x150.png 150w\" sizes=\"auto, (max-width: 616px) 100vw, 616px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Otra parte fundamental en el primer escenario es el mu\u00f1eco de nieve. Para crearlo, realizamos el mismo proceso de generaci\u00f3n de esferas utilizado en el \u00e1rbol de Navidad, con la diferencia de que aplicamos un <strong>suavizado menor<\/strong>. A partir de esto, generamos tres esferas de diferentes escalas y las ordenamos para formar la figura del mu\u00f1eco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para la escala general utilizamos la tecla <strong>S<\/strong>. Sin embargo, para el dise\u00f1o de los brazos fue necesario escalar en un eje espec\u00edfico para darles la forma correcta; lo mismo ocurri\u00f3 con el cono utilizado para la nariz. Todo esto se realiz\u00f3 de manera organizada usando <strong>S + Y<\/strong>, <strong>S + X<\/strong> y <strong>S + Z<\/strong>, seg\u00fan el eje que se necesitara modificar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"648\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MUNECO-NIEVE-C__Users_User_Downloads_MUNECO-NIEVE.blend1-Blender-4.5.4-LTS-26_11_2025-03_19_12-1024x648.png\" alt=\"\" class=\"wp-image-74195\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MUNECO-NIEVE-C__Users_User_Downloads_MUNECO-NIEVE.blend1-Blender-4.5.4-LTS-26_11_2025-03_19_12-1024x648.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MUNECO-NIEVE-C__Users_User_Downloads_MUNECO-NIEVE.blend1-Blender-4.5.4-LTS-26_11_2025-03_19_12-300x190.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MUNECO-NIEVE-C__Users_User_Downloads_MUNECO-NIEVE.blend1-Blender-4.5.4-LTS-26_11_2025-03_19_12-768x486.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MUNECO-NIEVE-C__Users_User_Downloads_MUNECO-NIEVE.blend1-Blender-4.5.4-LTS-26_11_2025-03_19_12.png 1253w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"575\" height=\"514\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-copia-C__Users_User_Downloads_MATERIALES-copia.blend-Blender-4.5.4-LTS-12_11_2025-16_22_17.png\" alt=\"\" class=\"wp-image-74196\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-copia-C__Users_User_Downloads_MATERIALES-copia.blend-Blender-4.5.4-LTS-12_11_2025-16_22_17.png 575w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/MATERIALES-copia-C__Users_User_Downloads_MATERIALES-copia.blend-Blender-4.5.4-LTS-12_11_2025-16_22_17-300x268.png 300w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para el dise\u00f1o de las paredes, buscando simular una sala de prensa, partimos del cubo predeterminado que genera Blender. A este cubo le realizamos modificaciones de dimensi\u00f3n para dejarlo largo, alto y delgado, utilizando el mismo m\u00e9todo empleado en el mu\u00f1eco de nieve: <strong>S + Z<\/strong>, <strong>S + Y<\/strong>, <strong>S + X<\/strong> y <strong>S<\/strong> sola para la escala general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez aseguradas las dimensiones, nos dirigimos a la secci\u00f3n de propiedades y, en lugar de asignar un color base, seleccionamos una <strong>imagen<\/strong>. Luego pasamos a la pesta\u00f1a <strong>UV Editing<\/strong> para ajustar la imagen \u00fanicamente en una cara. Para ello seleccionamos una cara mediante sus cuatro v\u00e9rtices, vamos al men\u00fa de UV y marcamos la cara como <strong>Costura (Seam)<\/strong>. En el panel de edici\u00f3n UV ajustamos la m\u00e1scara hasta que se adapte correctamente a las dimensiones del objeto. Despu\u00e9s buscamos una imagen adecuada y la aplicamos.<br>Posteriormente ubicamos un punto de luz y a la pared le a\u00f1adimos <strong>metalizado<\/strong> y <strong>suavizado<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para las dem\u00e1s paredes simplemente copiamos y pegamos el objeto, aplicamos rotaci\u00f3n y as\u00ed formamos la habitaci\u00f3n. En la pared central utilizamos una nueva imagen generada con ayuda de inteligencia artificial para simular la zona principal de prensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el piso y el techo, con <strong>Shift + A<\/strong> agregamos un <strong>plano<\/strong>, al cual le aplicamos color, suavizado y un leve efecto met\u00e1lico.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"419\" height=\"419\" data-id=\"74203\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_57_58-1.png\" alt=\"\" class=\"wp-image-74203\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_57_58-1.png 419w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_57_58-1-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_57_58-1-150x150.png 150w\" sizes=\"auto, (max-width: 419px) 100vw, 419px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"354\" height=\"354\" data-id=\"74204\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_57_48-1.png\" alt=\"\" class=\"wp-image-74204\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_57_48-1.png 354w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_57_48-1-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_57_48-1-150x150.png 150w\" sizes=\"auto, (max-width: 354px) 100vw, 354px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"394\" height=\"394\" data-id=\"74202\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/pareeeed-1.png\" alt=\"\" class=\"wp-image-74202\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/pareeeed-1.png 394w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/pareeeed-1-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/pareeeed-1-150x150.png 150w\" sizes=\"auto, (max-width: 394px) 100vw, 394px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"816\" height=\"816\" data-id=\"74205\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_58_46-1.png\" alt=\"\" class=\"wp-image-74205\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_58_46-1.png 816w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_58_46-1-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_58_46-1-150x150.png 150w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-03_58_46-1-768x768.png 768w\" sizes=\"auto, (max-width: 816px) 100vw, 816px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"593\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_01_00-1-1024x593.png\" alt=\"\" class=\"wp-image-74206\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_01_00-1-1024x593.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_01_00-1-300x174.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_01_00-1-768x445.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_01_00-1.png 1498w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-10 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"827\" height=\"437\" data-id=\"74207\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_02_30.png\" alt=\"\" class=\"wp-image-74207\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_02_30.png 827w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_02_30-300x159.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_02_30-768x406.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_02_30-390x205.png 390w\" sizes=\"auto, (max-width: 827px) 100vw, 827px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"774\" height=\"774\" data-id=\"74208\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/cuadrado.png\" alt=\"\" class=\"wp-image-74208\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/cuadrado.png 774w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/cuadrado-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/cuadrado-150x150.png 150w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/cuadrado-768x768.png 768w\" sizes=\"auto, (max-width: 774px) 100vw, 774px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"802\" height=\"537\" data-id=\"74210\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_03_20.png\" alt=\"\" class=\"wp-image-74210\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_03_20.png 802w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_03_20-300x201.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_03_20-768x514.png 768w\" sizes=\"auto, (max-width: 802px) 100vw, 802px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-11 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"335\" height=\"662\" data-id=\"74212\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_04_03-1.png\" alt=\"\" class=\"wp-image-74212\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_04_03-1.png 335w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_04_03-1-152x300.png 152w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"835\" height=\"853\" data-id=\"74211\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/millonarios-pared-textura-Buscar-con-Google-Google-Chrome-13_11_2025-04_05_18.png\" alt=\"\" class=\"wp-image-74211\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/millonarios-pared-textura-Buscar-con-Google-Google-Chrome-13_11_2025-04_05_18.png 835w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/millonarios-pared-textura-Buscar-con-Google-Google-Chrome-13_11_2025-04_05_18-294x300.png 294w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/millonarios-pared-textura-Buscar-con-Google-Google-Chrome-13_11_2025-04_05_18-768x785.png 768w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"562\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_07_57-1024x562.png\" alt=\"\" class=\"wp-image-74214\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_07_57-1024x562.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_07_57-300x165.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_07_57-768x421.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_07_57.png 1338w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-12 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"801\" height=\"801\" data-id=\"74217\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PLANO.png\" alt=\"\" class=\"wp-image-74217\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PLANO.png 801w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PLANO-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PLANO-150x150.png 150w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PLANO-768x768.png 768w\" sizes=\"auto, (max-width: 801px) 100vw, 801px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"694\" data-id=\"74216\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_11_02.png\" alt=\"\" class=\"wp-image-74216\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_11_02.png 694w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_11_02-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_11_02-150x150.png 150w\" sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" data-id=\"74215\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_14_04.png\" alt=\"\" class=\"wp-image-74215\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_14_04.png 640w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_14_04-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_14_04-150x150.png 150w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-13 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"757\" height=\"757\" data-id=\"74220\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/DOBLE-PARED.png\" alt=\"\" class=\"wp-image-74220\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/DOBLE-PARED.png 757w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/DOBLE-PARED-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/DOBLE-PARED-150x150.png 150w\" sizes=\"auto, (max-width: 757px) 100vw, 757px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"369\" data-id=\"74218\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Imagen-con-logos-Google-Chrome-13_11_2025-04_23_50.png\" alt=\"\" class=\"wp-image-74218\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Imagen-con-logos-Google-Chrome-13_11_2025-04_23_50.png 430w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Imagen-con-logos-Google-Chrome-13_11_2025-04_23_50-300x257.png 300w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"611\" height=\"611\" data-id=\"74219\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_23_34.png\" alt=\"\" class=\"wp-image-74219\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_23_34.png 611w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_23_34-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/no-guardado-Blender-4.5.4-LTS-13_11_2025-04_23_34-150x150.png 150w\" sizes=\"auto, (max-width: 611px) 100vw, 611px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"493\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_25_04-1024x493.png\" alt=\"\" class=\"wp-image-74221\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_25_04-1024x493.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_25_04-300x144.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_25_04-768x370.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_25_04-1536x739.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_25_04.png 1660w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ya con el escenario listo, importamos los archivos al proyecto principal. En este caso, como cada material fue creado en proyectos separados, los exportamos en formato <strong>.glb<\/strong> y luego los arrastramos al escenario de la sala de prensa. As\u00ed importamos tanto el mu\u00f1eco de nieve como el \u00e1rbol de Navidad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"442\" height=\"195\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Descargas-13_11_2025-04_25_39-1.png\" alt=\"\" class=\"wp-image-74225\" style=\"width:387px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Descargas-13_11_2025-04_25_39-1.png 442w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Descargas-13_11_2025-04_25_39-1-300x132.png 300w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-14 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"594\" height=\"239\" data-id=\"74226\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Visor-de-archivos-de-Blender-13_11_2025-04_29_19-1.png\" alt=\"\" class=\"wp-image-74226\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Visor-de-archivos-de-Blender-13_11_2025-04_29_19-1.png 594w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Visor-de-archivos-de-Blender-13_11_2025-04_29_19-1-300x121.png 300w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"722\" data-id=\"74227\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_26_31-1.png\" alt=\"\" class=\"wp-image-74227\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_26_31-1.png 722w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_26_31-1-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_26_31-1-150x150.png 150w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En este caso, con el \u00e1rbol, consider\u00e9 m\u00e1s acorde al ambiente aplicarle una textura blanca para darle un toque diferente y creativo al \u00e1rbol de Navidad.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-15 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"628\" data-id=\"74229\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_30_16-1-1024x628.png\" alt=\"\" class=\"wp-image-74229\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_30_16-1-1024x628.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_30_16-1-300x184.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_30_16-1-768x471.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_30_16-1.png 1395w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"590\" data-id=\"74230\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_41_17-1024x590.png\" alt=\"\" class=\"wp-image-74230\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_41_17-1024x590.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_41_17-300x173.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_41_17-768x443.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_41_17.png 1233w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte final y muy importante del primer escenario est\u00e1n los avatares, en este caso el de Messi y el m\u00edo. Ambos se realizaron en la p\u00e1gina <strong>Avaturn<\/strong>, donde se suben diferentes \u00e1ngulos del rostro y la plataforma genera un modelo editable. All\u00ed se pueden modificar prendas, cabello, posici\u00f3n y animaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En mi caso, el proceso fue sencillo: me tom\u00e9 las fotos con el celular y la p\u00e1gina las ley\u00f3 directamente mediante un c\u00f3digo QR que conectaba con la c\u00e1mara del dispositivo. Sin embargo, para el avatar de Messi fue mucho m\u00e1s complicado, ya que fue necesario buscar m\u00faltiples fotos en distintos \u00e1ngulos para lograr un dise\u00f1o coherente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez listos, descargamos ambos avatares en formato <strong>.glb<\/strong> e importamos los modelos a la escena. Inicialmente aparecieron muy peque\u00f1os, por lo que utilizamos <strong>S<\/strong> para escalar en general y <strong>G<\/strong> para posicionarlos acorde al escenario principal.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"588\" height=\"381\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_12_51-p.-m.png\" alt=\"\" class=\"wp-image-74233\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_12_51-p.-m.png 588w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_12_51-p.-m-300x194.png 300w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-16 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"869\" data-id=\"74237\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_30_46-p.-m-1024x869.png\" alt=\"\" class=\"wp-image-74237\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_30_46-p.-m-1024x869.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_30_46-p.-m-300x255.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_30_46-p.-m-768x652.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_30_46-p.-m.png 1030w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"826\" height=\"879\" data-id=\"74236\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_28_22-p.-m.png\" alt=\"\" class=\"wp-image-74236\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_28_22-p.-m.png 826w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_28_22-p.-m-282x300.png 282w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_28_22-p.-m-768x817.png 768w\" sizes=\"auto, (max-width: 826px) 100vw, 826px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"909\" height=\"942\" data-id=\"74235\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_30_05-p.-m.png\" alt=\"\" class=\"wp-image-74235\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_30_05-p.-m.png 909w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_30_05-p.-m-289x300.png 289w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_30_05-p.-m-768x796.png 768w\" sizes=\"auto, (max-width: 909px) 100vw, 909px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"638\" data-id=\"74234\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_32_09-p.-m-1024x638.png\" alt=\"\" class=\"wp-image-74234\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_32_09-p.-m-1024x638.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_32_09-p.-m-300x187.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_32_09-p.-m-768x478.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/messi-perfil-imagen-izquierda-Buscar-con-Google-Google-Chrome-12_11_2025-7_32_09-p.-m.png 1077w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"967\" height=\"925\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Avaturn-_-Realistic-avatar-creator-Google-Chrome-12_11_2025-7_00_45-p.-m.png\" alt=\"\" class=\"wp-image-74238\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Avaturn-_-Realistic-avatar-creator-Google-Chrome-12_11_2025-7_00_45-p.-m.png 967w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Avaturn-_-Realistic-avatar-creator-Google-Chrome-12_11_2025-7_00_45-p.-m-300x287.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Avaturn-_-Realistic-avatar-creator-Google-Chrome-12_11_2025-7_00_45-p.-m-768x735.png 768w\" sizes=\"auto, (max-width: 967px) 100vw, 967px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-17 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1017\" height=\"1017\" data-id=\"74239\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_54_10.png\" alt=\"\" class=\"wp-image-74239\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_54_10.png 1017w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_54_10-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_54_10-150x150.png 150w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_54_10-768x768.png 768w\" sizes=\"auto, (max-width: 1017px) 100vw, 1017px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1017\" height=\"1017\" data-id=\"74240\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_55_35.png\" alt=\"\" class=\"wp-image-74240\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_55_35.png 1017w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_55_35-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_55_35-150x150.png 150w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-04_55_35-768x768.png 768w\" sizes=\"auto, (max-width: 1017px) 100vw, 1017px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>SEGUNDO ESCENARIO<\/strong> &#8211; SALA DE ENTRENAMIENTO<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para el segundo escenario buscamos un estilo de gimnasio ya construido. Para ello acudimos a la p\u00e1gina <strong>Sketchfab<\/strong>, donde se pueden descargar diferentes modelos en formato <strong>.glb<\/strong>. En este caso, buscamos un escenario peque\u00f1o pero funcional, dando especial prioridad a que incluyera una caminadora.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"550\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Verificacion-en-dos-pasos-Para-proteger-tu-cuenta-Google-quiere-verificar-que-eres-tu-quien-esta-intentando-iniciar-sesion-Google-Chrome-12_11_2025-6_51_52-p.-m-1024x550.png\" alt=\"\" class=\"wp-image-74242\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Verificacion-en-dos-pasos-Para-proteger-tu-cuenta-Google-quiere-verificar-que-eres-tu-quien-esta-intentando-iniciar-sesion-Google-Chrome-12_11_2025-6_51_52-p.-m-1024x550.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Verificacion-en-dos-pasos-Para-proteger-tu-cuenta-Google-quiere-verificar-que-eres-tu-quien-esta-intentando-iniciar-sesion-Google-Chrome-12_11_2025-6_51_52-p.-m-300x161.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Verificacion-en-dos-pasos-Para-proteger-tu-cuenta-Google-quiere-verificar-que-eres-tu-quien-esta-intentando-iniciar-sesion-Google-Chrome-12_11_2025-6_51_52-p.-m-768x413.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Verificacion-en-dos-pasos-Para-proteger-tu-cuenta-Google-quiere-verificar-que-eres-tu-quien-esta-intentando-iniciar-sesion-Google-Chrome-12_11_2025-6_51_52-p.-m-1536x826.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Verificacion-en-dos-pasos-Para-proteger-tu-cuenta-Google-quiere-verificar-que-eres-tu-quien-esta-intentando-iniciar-sesion-Google-Chrome-12_11_2025-6_51_52-p.-m.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Generamos la importaci\u00f3n tanto del avatar de Messi con otra vestimenta como del gimnasio, ambos en formato <strong>.glb<\/strong>. Con esto, empezamos a modificar y escalar ambos objetos para que quedaran acorde a lo que busc\u00e1bamos. Luego procedimos a editar las paredes y, para darle un aspecto m\u00e1s profesional, copiamos el dise\u00f1o de una de las paredes del primer escenario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el resto del espacio, la edici\u00f3n se hizo de forma manual. En la secci\u00f3n de <strong>Pintar Textura<\/strong>, seleccionamos qu\u00e9 parte correspond\u00eda a cada color dentro del panel de pintura. A partir de esto, cambiamos la tonalidad a un azul m\u00e1s acorde con los colores del equipo.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-18 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"663\" data-id=\"74243\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_36_45-p.-m-1024x663.png\" alt=\"\" class=\"wp-image-74243\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_36_45-p.-m-1024x663.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_36_45-p.-m-300x194.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_36_45-p.-m-768x497.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_36_45-p.-m.png 1078w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"552\" data-id=\"74244\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_41_13-p.-m-1024x552.png\" alt=\"\" class=\"wp-image-74244\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_41_13-p.-m-1024x552.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_41_13-p.-m-300x162.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_41_13-p.-m-768x414.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_41_13-p.-m-1536x828.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Unsaved-Blender-4.5.4-LTS-12_11_2025-7_41_13-p.-m.png 1611w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-19 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"509\" data-id=\"74246\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_35_08-1024x509.png\" alt=\"\" class=\"wp-image-74246\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_35_08-1024x509.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_35_08-300x149.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_35_08-768x381.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_35_08.png 1337w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"985\" height=\"634\" data-id=\"74245\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_38_34.png\" alt=\"\" class=\"wp-image-74245\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_38_34.png 985w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_38_34-300x193.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_38_34-768x494.png 768w\" sizes=\"auto, (max-width: 985px) 100vw, 985px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-20 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"603\" data-id=\"74247\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_44_38-1024x603.png\" alt=\"\" class=\"wp-image-74247\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_44_38-1024x603.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_44_38-300x177.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_44_38-768x452.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_44_38.png 1407w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" data-id=\"74248\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_54_48-1024x613.png\" alt=\"\" class=\"wp-image-74248\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_54_48-1024x613.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_54_48-300x180.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_54_48-768x460.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-MESSI-ENTRENANDO-C__Users_User_Downloads_ESCENARIO-MESSI-ENTRENANDO.blend-Blender-4.5.4-LTS-21_11_2025-00_54_48.png 1105w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>TERCER ESCENARIO<\/strong> &#8211; ESTADIO<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para el tercer y \u00faltimo escenario, utilizamos la misma p\u00e1gina de donde obtuvimos el gimnasio para buscar un estadio. Con ello, realizamos otra importaci\u00f3n en formato <strong>.glb<\/strong>, esta vez de un <strong>Bal\u00f3n de Oro<\/strong>, el cual posteriormente duplicamos hasta tener 8. De igual forma importamos los logos de Adidas y Millonarios en formato <strong>.svg<\/strong> en la pagina <strong>worldvectorlogo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego generamos las escalas correspondientes; sin embargo, para los logos fue necesario, desde las propiedades del objeto, <strong>solidificar<\/strong> las partes seleccionadas. Esto se hizo con el fin de poder escalarlos correctamente y lograr que los logos tuvieran presencia en <strong>3D<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-21 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"648\" data-id=\"74250\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_20_51-1024x648.png\" alt=\"\" class=\"wp-image-74250\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_20_51-1024x648.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_20_51-300x190.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_20_51-768x486.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_20_51.png 1394w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"935\" height=\"932\" data-id=\"74249\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_21_11.png\" alt=\"\" class=\"wp-image-74249\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_21_11.png 935w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_21_11-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_21_11-150x150.png 150w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Newsfeed-Sketchfab-Google-Chrome-26_11_2025-05_21_11-768x766.png 768w\" sizes=\"auto, (max-width: 935px) 100vw, 935px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-22 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"477\" data-id=\"74252\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_40-1024x477.png\" alt=\"\" class=\"wp-image-74252\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_40-1024x477.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_40-300x140.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_40-768x358.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_40.png 1404w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"456\" data-id=\"74251\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_48-1024x456.png\" alt=\"\" class=\"wp-image-74251\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_48-1024x456.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_48-300x134.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_48-768x342.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Results-for-adidas-\u2014-Worldvectorlogo-Google-Chrome-26_11_2025-05_17_48.png 1244w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-23 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"766\" data-id=\"74258\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_20_18-1.png\" alt=\"\" class=\"wp-image-74258\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_20_18-1.png 609w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_20_18-1-239x300.png 239w\" sizes=\"auto, (max-width: 609px) 100vw, 609px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"695\" data-id=\"74259\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_41_59-1.png\" alt=\"\" class=\"wp-image-74259\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_41_59-1.png 721w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_41_59-1-300x289.png 300w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"328\" height=\"671\" data-id=\"74257\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_42_25-1.png\" alt=\"\" class=\"wp-image-74257\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_42_25-1.png 328w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_42_25-1-147x300.png 147w\" sizes=\"auto, (max-width: 328px) 100vw, 328px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"140\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Visor-de-archivos-de-Blender-23_11_2025-17_20_26-1.png\" alt=\"\" class=\"wp-image-74260\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Visor-de-archivos-de-Blender-23_11_2025-17_20_26-1.png 567w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Visor-de-archivos-de-Blender-23_11_2025-17_20_26-1-300x74.png 300w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-24 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"448\" data-id=\"74266\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_42_47-1-1024x448.png\" alt=\"\" class=\"wp-image-74266\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_42_47-1-1024x448.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_42_47-1-300x131.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_42_47-1-768x336.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_42_47-1-1536x671.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_42_47-1.png 1835w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"638\" data-id=\"74264\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_44_47-1.png\" alt=\"\" class=\"wp-image-74264\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_44_47-1.png 684w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_44_47-1-300x280.png 300w\" sizes=\"auto, (max-width: 684px) 100vw, 684px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"715\" data-id=\"74265\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_46_07.png\" alt=\"\" class=\"wp-image-74265\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_46_07.png 719w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_46_07-300x298.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_46_07-150x150.png 150w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-25 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"474\" data-id=\"74268\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_48_11.png\" alt=\"\" class=\"wp-image-74268\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_48_11.png 418w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-17_48_11-265x300.png 265w\" sizes=\"auto, (max-width: 418px) 100vw, 418px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"416\" height=\"365\" data-id=\"74267\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-18_06_46.png\" alt=\"\" class=\"wp-image-74267\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-18_06_46.png 416w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESTADIO-C__Users_User_Downloads_ESTADIO.blend-Blender-4.5.4-LTS-23_11_2025-18_06_46-300x263.png 300w\" sizes=\"auto, (max-width: 416px) 100vw, 416px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CONFIGURACI\u00d3N Y ANIMACI\u00d3N DE LAS C\u00c1MARAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el tema de c\u00e1maras, manejamos diferentes opciones para determinar cu\u00e1l era la m\u00e1s adecuada en cada momento de la grabaci\u00f3n. Se prob\u00f3 utilizando una <strong>curva<\/strong> y asign\u00e1ndole la c\u00e1mara. Esto se configur\u00f3 desde las <strong>propiedades del objeto (c\u00e1mara)<\/strong>, en el apartado de <strong>Restricciones<\/strong>. All\u00ed se aplicaron dos procesos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Seleccionar trayectoria<\/strong>, donde se elige la curva para que la c\u00e1mara la siga.<\/li>\n\n\n\n<li><strong>Enfocar un objeto<\/strong>, opci\u00f3n que s\u00ed se utiliz\u00f3 con bastante frecuencia en todas las grabaciones.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de esto, realizamos una serie de movimientos en fotogramas espec\u00edficos. Para lograrlo, se marc\u00f3 el punto de partida y el punto final del movimiento, y se registraron los cambios presionando la tecla <strong>I<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro aspecto importante fue el <strong>cambio de c\u00e1maras<\/strong>, el cual se ejecuta con <strong>CTRL + B<\/strong>, especificando en qu\u00e9 momentos cada c\u00e1mara ser\u00eda la principal. En total, contando los tres escenarios, se utilizaron aproximadamente <strong>10 c\u00e1maras<\/strong> para los cambios de escena y animaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-26 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"997\" data-id=\"74459\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CAM-1024x997.png\" alt=\"\" class=\"wp-image-74459\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CAM-1024x997.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CAM-300x292.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CAM-768x747.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/CAM.png 1045w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"714\" height=\"1017\" data-id=\"74461\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-10_59_39.png\" alt=\"\" class=\"wp-image-74461\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-10_59_39.png 714w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-10_59_39-211x300.png 211w\" sizes=\"auto, (max-width: 714px) 100vw, 714px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"331\" height=\"308\" data-id=\"74460\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-10_57_21.png\" alt=\"\" class=\"wp-image-74460\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-10_57_21.png 331w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-10_57_21-300x279.png 300w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-27 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"344\" height=\"327\" data-id=\"74463\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_00_42.png\" alt=\"\" class=\"wp-image-74463\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_00_42.png 344w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_00_42-300x285.png 300w\" sizes=\"auto, (max-width: 344px) 100vw, 344px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"714\" height=\"1017\" data-id=\"74462\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-10_59_39-1.png\" alt=\"\" class=\"wp-image-74462\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-10_59_39-1.png 714w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-10_59_39-1-211x300.png 211w\" sizes=\"auto, (max-width: 714px) 100vw, 714px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"673\" data-id=\"74464\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_02_40-1024x673.png\" alt=\"\" class=\"wp-image-74464\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_02_40-1024x673.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_02_40-300x197.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_02_40-768x505.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_02_40.png 1328w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"676\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PRIMORDIAL-1024x676.png\" alt=\"\" class=\"wp-image-74465\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PRIMORDIAL-1024x676.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PRIMORDIAL-300x198.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PRIMORDIAL-768x507.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/PRIMORDIAL.png 1203w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ANIMACI\u00d3N AVATARES<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para la animaci\u00f3n de los avatares utilizamos el mismo procedimiento que con las c\u00e1maras, seleccionando por fotogramas (frames) el inicio y el final de cada movimiento y registr\u00e1ndolos con la tecla <strong>I<\/strong>. Era fundamental lograr que ambos avatares se mantuvieran en sincron\u00eda y que sus movimientos fueran sim\u00e9tricos.<br>Para ello seleccionamos la <strong>armadura (armature)<\/strong> que el avatar trae por defecto. Sin embargo, es importante aclarar que esto solo ocurre si el avatar se descarga <strong>con animaci\u00f3n<\/strong>; de lo contrario, ser\u00e1 necesario crear el esqueleto manualmente. A continuaci\u00f3n se describe tambi\u00e9n ese proceso, en caso de que el personaje no lo incluya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con <strong>Shift + A<\/strong> seleccionamos la opci\u00f3n <strong>Armature (Esqueleto)<\/strong>. Blender genera una figura base que debe colocarse en la parte central e inferior del personaje. Luego, en las propiedades del esqueleto, seleccionamos la opci\u00f3n donde especificamos el <strong>Armature<\/strong> principal, y a partir de all\u00ed ajustamos el esqueleto en una <strong>pose en T (T-Pose)<\/strong> para que coincida con la figura del avatar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s, utilizando la tecla <strong>S<\/strong>, escalamos la armadura para que coincida con las dimensiones del avatar y la alineamos correctamente. Finalmente, seleccionamos tanto el esqueleto como el avatar en T-Pose y aplicamos la opci\u00f3n <strong>Parent &gt; With Automatic Weights (Asignar con influencias autom\u00e1ticas)<\/strong>, logrando as\u00ed que el modelo quede completamente vinculado al esqueleto.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-28 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"648\" height=\"757\" data-id=\"74476\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/esqueleto.png\" alt=\"\" class=\"wp-image-74476\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/esqueleto.png 648w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/esqueleto-257x300.png 257w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"416\" data-id=\"74475\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_56_52.png\" alt=\"\" class=\"wp-image-74475\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_56_52.png 472w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_56_52-300x264.png 300w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"830\" data-id=\"74477\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_57_56.png\" alt=\"\" class=\"wp-image-74477\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_57_56.png 660w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_57_56-239x300.png 239w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-29 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1017\" data-id=\"74478\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_59_16.png\" alt=\"\" class=\"wp-image-74478\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_59_16.png 724w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-11_59_16-214x300.png 214w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"754\" height=\"921\" data-id=\"74479\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-12_00_59.png\" alt=\"\" class=\"wp-image-74479\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-12_00_59.png 754w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-12_00_59-246x300.png 246w\" sizes=\"auto, (max-width: 754px) 100vw, 754px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"581\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-12_01_37-1024x581.png\" alt=\"\" class=\"wp-image-74480\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-12_01_37-1024x581.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-12_01_37-300x170.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-12_01_37-768x436.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-13_11_2025-12_01_37.png 1502w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"553\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-14_21_42-1024x553.png\" alt=\"\" class=\"wp-image-74481\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-14_21_42-1024x553.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-14_21_42-300x162.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-14_21_42-768x415.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-14_21_42.png 1470w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-30 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"833\" data-id=\"74483\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-15_32_42.png\" alt=\"\" class=\"wp-image-74483\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-15_32_42.png 726w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-15_32_42-261x300.png 261w\" sizes=\"auto, (max-width: 726px) 100vw, 726px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"502\" data-id=\"74482\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_33_29-1024x502.png\" alt=\"\" class=\"wp-image-74482\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_33_29-1024x502.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_33_29-300x147.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_33_29-768x377.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_33_29.png 1129w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"610\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_52_52-1024x610.png\" alt=\"\" class=\"wp-image-74485\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_52_52-1024x610.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_52_52-300x179.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_52_52-768x457.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_52_52-1536x914.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-17_11_2025-16_52_52.png 1554w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ULTIMOS DETALLES<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-26_11_2025-00_33_59-1024x613.png\" alt=\"\" class=\"wp-image-74487\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-26_11_2025-00_33_59-1024x613.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-26_11_2025-00_33_59-300x180.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-26_11_2025-00_33_59-768x460.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ESCENARIO-SALA-DE-PRENSA-C__Users_User_Downloads_ESCENARIO-SALA-DE-PRENSA.blend-Blender-4.5.4-LTS-26_11_2025-00_33_59.png 1507w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>EDICI\u00d3N<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ya en la secci\u00f3n de edici\u00f3n, tanto el texto como los cr\u00e9ditos, efectos y m\u00fasica se agregaron de forma externa por medio de <strong>Wondershare Filmora<\/strong>, obteniendo un resultado final con una duraci\u00f3n total de <strong>1 minuto y 43 segundos<\/strong>.<br>A continuaci\u00f3n se mostrar\u00e1 un video explicativo sobre la tem\u00e1tica, el procedimiento realizado y el resultado final.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas gracias por la atenci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"555\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Wondershare-Filmora-26_11_2025-11_15_37-1024x555.png\" alt=\"\" class=\"wp-image-74491\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Wondershare-Filmora-26_11_2025-11_15_37-1024x555.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Wondershare-Filmora-26_11_2025-11_15_37-300x163.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Wondershare-Filmora-26_11_2025-11_15_37-768x416.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Wondershare-Filmora-26_11_2025-11_15_37-1536x832.png 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/Wondershare-Filmora-26_11_2025-11_15_37.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>VIDEO EXPLICATIVO<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"VIDEO EXPLICATIVO - UN REGALO IMPOSIBLE\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/4bDAVpornH4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>RESULTADO FINAL<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"UN REGALO IMPOSIBLE - Animaci\u00f3n blender\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/hqRWc3Yz44Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Cr\u00e9ditos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor<\/strong>:&nbsp;<a href=\"https:\/\/niixer.com\/?s=joan+jimenez\">Joan Sebastian Jimenez Wilches<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor<\/strong>:&nbsp;<a href=\"https:\/\/niixer.com\/?s=Carlos+Iv%C3%A1n+Pinz%C3%B3n+Romero#google_vignette\">Mg. Carlos Iv\u00e1n Pinz\u00f3n Romero<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo<\/strong>:&nbsp;<a href=\"https:\/\/niixer.com\/?s=CG-20252\">CG-20252<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad<\/strong>:&nbsp;<a href=\"https:\/\/niixer.com\/?s=Universidad+Central\">Universidad Central<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Referencias<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Results for millonarios \u2014 Worldvectorlogo. (2025). Worldvectorlogo.com. https:\/\/worldvectorlogo.com\/search\/millonarios<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>\u200cResults for adidas \u2014 Worldvectorlogo. (2025). Worldvectorlogo.com. https:\/\/worldvectorlogo.com\/search\/adidas<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>\u200cSketchfab. (n.d.). Premio Ballon D\u2019Or &#8211; Download Free 3D model by El_Misiones_Baller. https:\/\/sketchfab.com\/3d-models\/premio-ballon-dor-eda6a888bc6249ec9ff8068c55c1529d<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Sign in. (n.d.). ElevenLabs. https:\/\/elevenlabs.io\/app\/sign-in?redirect=%2Fapp%2Fspeech-synthesis%2Ftext-to-speech%3Fhistory_voice_id%3DXb7hH8MSUJpSbSDYk0k2<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Pixabay. (n.d.). Free Navidad Musica Sound Effects download &#8211; Pixabay. https:\/\/pixabay.com\/es\/sound-effects\/search\/navidad%20musica\/<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Sam Tinnesz. (2017, July 21). Sam Tinnesz &#8211; Legends Are Made [Official Audio] [Video]. YouTube. https:\/\/www.youtube.com\/watch?v=EKVZrbitbd8<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Avaturn | Realistic avatar creator. (n.d.). https:\/\/hub.avaturn.me\/login<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Avaturn | Realistic avatar creator. (n.d.). https:\/\/hub.avaturn.me\/login<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Alejandro de Costas. (2024, November 19). C\u00f3mo poner texturas en Blender f\u00e1cil &#8211; Tutorial para aplicar una textura paso a paso y sencillo [Video]. YouTube. https:\/\/www.youtube.com\/watch?v=Nx9yWd8t6kA<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Brontes 3D Academy. (2024, December 13). Como hacer un \u00c1rbol de Navidad con Part\u00edculas en Blender 4.3 [Video]. YouTube. https:\/\/www.youtube.com\/watch?v=91f9t1lPapU<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Sketchfab. (n.d.). Estadio Morelos &#8211; Download Free 3D model by metalex. https:\/\/sketchfab.com\/3d-models\/estadio-morelos-045a8056ade74171a78c5348bc057f06<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Sketchfab. (n.d.). Modular Gym &#8211; Download Free 3D model by Kristen Brown (@kristnbrown). https:\/\/sketchfab.com\/3d-models\/modular-gym-86e8cc43d76c44e3925e625fdab155f3<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Logo de Millonarios y Adidas. (2025, November 26). ChatGPT. https:\/\/chatgpt.com\/s\/m_69274925e8c88191b482c675b7e79abb<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>(2025). Espncdn.com. https:\/\/a.espncdn.com\/combiner\/i?img=\/i\/headshots\/soccer\/players\/full\/45843.png&amp;w=350&amp;h=254<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Free AI Voice Generator &amp; Voice Agents Platform | ElevenLabs. (2025). ElevenLabs. https:\/\/elevenlabs.io\/app\/speech-synthesis\/text-to-speech?history_voice_id=Xb7hH8MSUJpSbSDYk0k2<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>Pixabay. (2025). Pixabay.com. https:\/\/pixabay.com\/es\/sound-effects\/search\/navidad%20musica\/\u200c<\/em><\/p>\n\n\n\n<p class=\"has-cm-color-4-background-color has-background wp-block-paragraph\"><em>(2025). Youtube.com. https:\/\/www.youtube.com\/watch?v=EKVZrbitbd8&amp;list=PLxVUQ6vCSF-wLjCphN5bqP5f7xvYoDFFi&amp;index=6<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Introducci\u00f3n El proyecto est\u00e1 basado en un contexto navide\u00f1o; sin embargo, se opt\u00f3 por algo diferente sin olvidar la tem\u00e1tica principal. Acorde con ese contexto, se tomaron marcas como referencia para, a partir de ah\u00ed, desarrollar una idea. En este caso, mi marca principal es Adidas; no obstante, propuse unaSeguir Leyendo<\/p>\n","protected":false},"author":1935,"featured_media":74801,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1768],"tags":[1144,3111,1310,665,4240],"class_list":["post-73024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-animacion","tag-animacion-3d","tag-avatares","tag-blender-3d","tag-navidad","tag-texturas-3d"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cortometraje Navide\u00f1o 3D: Creaci\u00f3n de Escenarios, Modelado y Edici\u00f3n Profesional<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo se realiz\u00f3 un cortometraje navide\u00f1o 3D con escenarios, modelos .glb y .svg, animaci\u00f3n de avatares y edici\u00f3n profesional en Filmora.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cortometraje Navide\u00f1o 3D: Creaci\u00f3n de Escenarios, Modelado y Edici\u00f3n Profesional\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo se realiz\u00f3 un cortometraje navide\u00f1o 3D con escenarios, modelos .glb y .svg, animaci\u00f3n de avatares y edici\u00f3n profesional en Filmora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T19:51:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T02:09:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-1-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Joan Jimenez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joan Jimenez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"32 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cortometraje Navide\u00f1o 3D: Creaci\u00f3n de Escenarios, Modelado y Edici\u00f3n Profesional","description":"Descubre c\u00f3mo se realiz\u00f3 un cortometraje navide\u00f1o 3D con escenarios, modelos .glb y .svg, animaci\u00f3n de avatares y edici\u00f3n profesional en Filmora.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/","og_locale":"es_ES","og_type":"article","og_title":"Cortometraje Navide\u00f1o 3D: Creaci\u00f3n de Escenarios, Modelado y Edici\u00f3n Profesional","og_description":"Descubre c\u00f3mo se realiz\u00f3 un cortometraje navide\u00f1o 3D con escenarios, modelos .glb y .svg, animaci\u00f3n de avatares y edici\u00f3n profesional en Filmora.","og_url":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2025-11-26T19:51:53+00:00","article_modified_time":"2025-11-27T02:09:03+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-1-1024x683.png","type":"image\/png"}],"author":"Joan Jimenez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Joan Jimenez","Tiempo de lectura":"32 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/"},"author":{"name":"Joan Jimenez","@id":"https:\/\/niixer.com\/#\/schema\/person\/d75c43ab9e74b638c62731e26a538938"},"headline":"El regalo imposible &#8211; Animaci\u00f3n Blender 3D","datePublished":"2025-11-26T19:51:53+00:00","dateModified":"2025-11-27T02:09:03+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/"},"wordCount":2325,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-1.png","keywords":["Animaci\u00f3n 3D","avatares","Blender 3D","Navidad","texturas 3D"],"articleSection":["Animaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/","url":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/","name":"Cortometraje Navide\u00f1o 3D: Creaci\u00f3n de Escenarios, Modelado y Edici\u00f3n Profesional","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-1.png","datePublished":"2025-11-26T19:51:53+00:00","dateModified":"2025-11-27T02:09:03+00:00","description":"Descubre c\u00f3mo se realiz\u00f3 un cortometraje navide\u00f1o 3D con escenarios, modelos .glb y .svg, animaci\u00f3n de avatares y edici\u00f3n profesional en Filmora.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/11\/ChatGPT-Image-26-nov-2025-13_11_44-1.png","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2025\/11\/26\/cortometraje-navideno-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"El regalo imposible &#8211; Animaci\u00f3n Blender 3D"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/d75c43ab9e74b638c62731e26a538938","name":"Joan Jimenez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7d23634a5834bf31c25fd0ee118d211cc398576389c15259f038bbc8ecf6d8c3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d23634a5834bf31c25fd0ee118d211cc398576389c15259f038bbc8ecf6d8c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d23634a5834bf31c25fd0ee118d211cc398576389c15259f038bbc8ecf6d8c3?s=96&d=mm&r=g","caption":"Joan Jimenez"},"url":"https:\/\/niixer.com\/index.php\/author\/joan-jimenez\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/73024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/1935"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=73024"}],"version-history":[{"count":16,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/73024\/revisions"}],"predecessor-version":[{"id":75023,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/73024\/revisions\/75023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/74801"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=73024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=73024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=73024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}