{"id":72682,"date":"2025-10-22T20:26:21","date_gmt":"2025-10-23T01:26:21","guid":{"rendered":"https:\/\/niixer.com\/?p=72682"},"modified":"2025-10-22T20:28:38","modified_gmt":"2025-10-23T01:28:38","slug":"modelos-texturas-y-animacion-con-blender","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/","title":{"rendered":"Modelos, Texturas y Animaci\u00f3n con Blender"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Parte 1: Modelado y Texturizado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Durante este ejercicio, vamos a explorar diferentes herramientas y formas de aplicar texturas dentro de Blender.  Para empezar, crearemos una habitaci\u00f3n donde se van a almacenar todas nuestras primitivas, y luego se explican t\u00e9cnicas para algunas primitivas<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">El Suelo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para comenzar, vamos a utilizar un plano como nuestra base.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"805\" height=\"424\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/plano.png\" alt=\"\" class=\"wp-image-72839\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/plano.png 805w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/plano-300x158.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/plano-768x405.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/plano-390x205.png 390w\" sizes=\"auto, (max-width: 805px) 100vw, 805px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s, entramos al menu de &#8220;Shading&#8221;, y modificamos el material del plano de tal forma que podamos a\u00f1adir un nodo &#8220;Checker Pattern&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"424\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/Imagen2.png\" alt=\"\" class=\"wp-image-72840\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/Imagen2.png 819w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/Imagen2-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/Imagen2-768x398.png 768w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, para a\u00f1adir &#8220;profundidad&#8221; al suelo, utilizamos un nodo llamado &#8220;Bump&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"822\" height=\"424\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/Imagen3-1.png\" alt=\"\" class=\"wp-image-72843\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/Imagen3-1.png 822w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/Imagen3-1-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/Imagen3-1-768x396.png 768w\" sizes=\"auto, (max-width: 822px) 100vw, 822px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Archimesh<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/otpmM-1024x538.jpg\" alt=\"\" class=\"wp-image-72844\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/otpmM-1024x538.jpg 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/otpmM-300x158.jpg 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/otpmM-768x404.jpg 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/otpmM-1536x807.jpg 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/otpmM-390x205.jpg 390w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/otpmM.jpg 1918w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/blender.stackexchange.com\/questions\/248795\/merging-rooms-in-archimesh\">Merging rooms in Archimesh &#8211; Blender Stack Exchange<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es un complemento de Blender que nos permite crear habitaciones con facilidad, en este caso, nos limitaremos a usarlo solo para colocar los muros y una ventana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1119-1024x529.png\" alt=\"\" class=\"wp-image-72845\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1119-1024x529.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1119-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1119-768x397.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1119.png 1281w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como se puede ver en la imagen, se cre\u00f3 un nuevo room que contiene la longitud del suelo, ademas de que podemos a\u00f1adir el n\u00famero de paredes que necesitemos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, como paso siguiente, podemos configurar en los primeros dos valores en el men\u00fa del complemento la altura y el ancho respectivamente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"529\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1120-1024x529.png\" alt=\"\" class=\"wp-image-72846\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1120-1024x529.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1120-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1120-768x397.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1120.png 1281w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se puede crear un material personalizado y colorear las paredes como queramos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"525\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1121-1024x525.png\" alt=\"\" class=\"wp-image-72847\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1121-1024x525.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1121-300x154.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1121-768x394.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1121.png 1290w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n podemos usar un &#8220;Panel Windows&#8221; y a\u00f1adir una ventana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"530\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1122-1024x530.png\" alt=\"\" class=\"wp-image-72848\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1122-1024x530.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1122-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1122-768x398.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1122.png 1279w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Primitivas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos comenzar creando una cortina a partir de un plano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"532\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1123-1024x532.png\" alt=\"\" class=\"wp-image-72849\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1123-1024x532.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1123-300x156.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1123-768x399.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1123.png 1275w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos subdividir este plano y seleccionar puntos aleatorios que determinar\u00e1n el pliegue de la cortina.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"532\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1124-1024x532.png\" alt=\"\" class=\"wp-image-72850\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1124-1024x532.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1124-300x156.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1124-768x399.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1124.png 1274w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos crear un Vertex Group con aquellos puntos, asociarlos con un Shape Key, y tambi\u00e9n distorsionar el plano con &#8220;Proportional Edit&#8221;, ya que ser\u00e1 necesario animarlo para obtener la cortina.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"527\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1125-1024x527.png\" alt=\"\" class=\"wp-image-72851\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1125-1024x527.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1125-300x154.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1125-768x395.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1125.png 1286w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para poder lograr ese fin, podemos utilizar un modificador llamado &#8220;Cloth&#8221;, que permitir\u00e1 obtener el efecto deseado de los pliegues al animar el plano que estar\u00e1 &#8220;agarrado&#8221; a los puntos que seleccionamos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"530\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1127-1024x530.png\" alt=\"\" class=\"wp-image-72853\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1127-1024x530.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1127-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1127-768x397.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1127.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez se a\u00f1ade el modificador, se puede animar la cortina, y, en un punto se pausa la animaci\u00f3n para obtener la forma que queremos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"530\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1128-1024x530.png\" alt=\"\" class=\"wp-image-72854\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1128-1024x530.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1128-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1128-768x397.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1128.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos a\u00f1adir un &#8220;Image Texture Node&#8221; que nos permitir\u00e1 colocar la textura de la cortina.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"533\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1129-1024x533.png\" alt=\"\" class=\"wp-image-72855\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1129-1024x533.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1129-300x156.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1129-768x399.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1129.png 1273w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora vamos a crear una estanter\u00eda a partir de un cubo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"527\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1130-1024x527.png\" alt=\"\" class=\"wp-image-72856\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1130-1024x527.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1130-300x154.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1130-768x395.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1130.png 1287w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, &#8220;estiramos&#8221; ese cubo y le quitamos una de sus caras.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"545\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1131-1024x545.png\" alt=\"\" class=\"wp-image-72857\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1131-1024x545.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1131-300x160.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1131-768x409.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1131.png 1243w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El modificador &#8220;Solidifier&#8221; permite a\u00f1adir grosor o &#8220;Thickness&#8221; para que se asemeje m\u00e1s a un estante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"528\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1132-1024x528.png\" alt=\"\" class=\"wp-image-72858\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1132-1024x528.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1132-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1132-768x396.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1132.png 1284w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El modificador array nos permite multiplicar este estante y convertirlo en una estanter\u00eda. En &#8220;Count&#8221; podemos seleccionar la cantidad y el factor determina en que eje y direcci\u00f3n se va a realizar la copia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"528\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1133-1024x528.png\" alt=\"\" class=\"wp-image-72859\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1133-1024x528.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1133-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1133-768x396.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1133.png 1285w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para terminar, se puede a\u00f1adir una textura de madera abriendo el editor UV, moviendo las &#8220;islas&#8221; y colocando el material como &#8220;Image Texture&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"528\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1134-1024x528.png\" alt=\"\" class=\"wp-image-72860\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1134-1024x528.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1134-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1134-768x396.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1134.png 1284w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, comencemos a crear una lata de bebida energizante a partir de un cilindro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"544\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1136-1024x544.png\" alt=\"\" class=\"wp-image-72863\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1136-1024x544.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1136-300x160.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1136-768x408.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1136.png 1245w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Extruimos, escalamos, generamos caras y todo lo dem\u00e1s hasta que tengamos la forma de la lata, luego seleccionamos unas aristas y las asignamos como costuras que servir\u00e1n para el proceso de texturizado a continuaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"528\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1137-1024x528.png\" alt=\"\" class=\"wp-image-72864\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1137-1024x528.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1137-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1137-768x396.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1137.png 1284w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el Editor UV, agregamos la textura, seleccionamos todo el modelo, y movemos cada una de las islas de tal forma que se puedan reorganizar las caras de la lata, y, el resultado se asigna como Image Texture dentro de Materiales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"526\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1138-1024x526.png\" alt=\"\" class=\"wp-image-72865\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1138-1024x526.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1138-300x154.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1138-768x394.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1138.png 1289w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">De manera similar se cre\u00f3 una dona con un toroide.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"527\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1140-1024x527.png\" alt=\"\" class=\"wp-image-72867\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1140-1024x527.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1140-300x154.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1140-768x395.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1140.png 1287w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Y un dado de 20 caras con un icosaedro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"530\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1141-1024x530.png\" alt=\"\" class=\"wp-image-72868\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1141-1024x530.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1141-300x155.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1141-768x397.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1141.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Parte 2: La animaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seleccionamos nuestro modelo de Sketchfab, en este caso al Agente Jonesy.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"516\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1142-1024x516.png\" alt=\"\" class=\"wp-image-72869\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1142-1024x516.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1142-300x151.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1142-768x387.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1142.png 1313w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/sketchfab.com\/3d-models\/agent-jonesy-4f58c52acca141e6950575c5f95bd193\">Agent Jonesy &#8211; Download Free 3D model by TheSitthikorn [4f58c52] &#8211; Sketchfab<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Modo Editar, seleccionamos los v\u00e9rtices de caras de la cabeza y los removemos por completo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"549\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1143-1024x549.png\" alt=\"\" class=\"wp-image-72870\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1143-1024x549.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1143-300x161.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1143-768x412.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1143.png 1235w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Implantamos la cabeza previamente hecha en Facebuilder. Se escala y translada para que ocupe el lugar perfectamente y luego unimos con Join (CTRL + J). Tambi\u00e9n eliminamos c\u00e1maras, armatures e iluminaci\u00f3n. Mixamo se encargar\u00e1 de asignarnos el armature.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"523\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1144-1024x523.png\" alt=\"\" class=\"wp-image-72871\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1144-1024x523.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1144-300x153.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1144-768x393.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1144.png 1295w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Realizamos el proceso de rigging en Mixamo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"443\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1145.png\" alt=\"\" class=\"wp-image-72872\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1145.png 921w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1145-300x144.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1145-768x369.png 768w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Luego descargamos animaciones como &#8220;Running&#8221;, &#8220;Idle&#8221;, &#8220;Climbing&#8221; o &#8220;Standing Up&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"440\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1146.png\" alt=\"\" class=\"wp-image-72873\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1146.png 921w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1146-300x143.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1146-768x367.png 768w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Primero, importamos la animaci\u00f3n &#8220;Idle&#8221; que ser\u00e1 nuestro armature inicial.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"593\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1147-1024x593.png\" alt=\"\" class=\"wp-image-72874\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1147-1024x593.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1147-300x174.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1147-768x445.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1147.png 1143w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adimos la animaci\u00f3n de &#8220;Running&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"593\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1148-1024x593.png\" alt=\"\" class=\"wp-image-72875\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1148-1024x593.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1148-300x174.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1148-768x445.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1148.png 1143w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Quitamos el modelo y solo dejamos el Armature de &#8220;Running&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"591\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1149-1024x591.png\" alt=\"\" class=\"wp-image-72876\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1149-1024x591.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1149-300x173.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1149-768x443.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1149.png 1147w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el &#8220;Action Editor&#8221; del &#8220;Dope Sheet&#8221;, podemos asignar la animaci\u00f3n de Running en el armature de Idle.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"593\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1152-1024x593.png\" alt=\"\" class=\"wp-image-72879\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1152-1024x593.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1152-300x174.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1152-768x445.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1152.png 1143w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un &#8220;Empty&#8221; que se emparenta al armature inicial, ayuda a realizar las transformaciones necesarias del modelo sin que este se distorsione al manipularlo directamente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"592\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1153-1024x592.png\" alt=\"\" class=\"wp-image-72880\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1153-1024x592.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1153-300x173.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1153-768x444.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1153.png 1145w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A traves del plugin de Sketchfab, importamos el modelo de un domo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"594\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1154-1024x594.png\" alt=\"\" class=\"wp-image-72881\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1154-1024x594.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1154-300x174.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1154-768x446.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1154.png 1141w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El personaje realizar\u00e1 lo siguiente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Saldr\u00e1 del domo.<\/li>\n\n\n\n<li>Llegara a una esquina del domo.<\/li>\n\n\n\n<li>Escalar\u00e1 el domo hasta llegar a la cima.<\/li>\n\n\n\n<li>Se quedar\u00e1 en position &#8220;Idle&#8221; mientras la c\u00e1mara se enfoca en el espacio de fondo.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Para marcar los key frame en cada instante, se mueve el Empty y el timeline, y luego con I se selecciona &#8220;Location + Rotation&#8221; para nuestro caso.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"594\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1155-1024x594.png\" alt=\"\" class=\"wp-image-72882\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1155-1024x594.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1155-300x174.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1155-768x446.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1155.png 1141w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El movimiento de la c\u00e1rmara se puede establecer de manera inicial por medio de una opci\u00f3n llamada &#8220;Lock to view&#8221; que nos permitir\u00e1 controlarla como si fuera otro objeto del escenario, y as\u00ed se a\u00f1adir\u00e1n de forma similar los key frames.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"608\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1156-1024x608.png\" alt=\"\" class=\"wp-image-72883\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1156-1024x608.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1156-300x178.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1156-768x456.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1156.png 1115w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para la iluminaci\u00f3n a\u00f1adiremos un &#8220;Sol&#8221; que m\u00e1s bien se comportar\u00e1 como la luna en este caso.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"600\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1157-1024x600.png\" alt=\"\" class=\"wp-image-72884\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1157-1024x600.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1157-300x176.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1157-768x450.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1157.png 1129w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos importar un HDRI del espacio y a\u00f1adirlo como nodo al mundo dentro del men\u00fa de Shading.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"595\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1158-1024x595.png\" alt=\"\" class=\"wp-image-72885\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1158-1024x595.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1158-300x174.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1158-768x446.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1158.png 1139w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para que se pueda notar la luz, se a\u00f1ade una especie de &#8220;neblina&#8221; que no es m\u00e1s que un cubo cubriendo toda la escena.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"594\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1159-1024x594.png\" alt=\"\" class=\"wp-image-72886\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1159-1024x594.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1159-300x174.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1159-768x446.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1159.png 1141w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos modificar el Shading y ya quedar\u00eda ajustado el cubo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"591\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1160-1024x591.png\" alt=\"\" class=\"wp-image-72887\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1160-1024x591.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1160-300x173.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1160-768x443.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1160.png 1147w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Y, finalmente a\u00f1adimos &#8220;As\u00ed Habl\u00f3 Zaratustra&#8221; como m\u00fasica de fondo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"589\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1161-1024x589.png\" alt=\"\" class=\"wp-image-72888\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1161-1024x589.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1161-300x173.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1161-768x442.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/image-1161.png 1151w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Resultado Final:<\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"espacio.mp4\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/0nEt7j2sejo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cr\u00e9ditos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Autor: Christian Camilo M\u00e9ndez Pulido<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Editor: Carlos Iv\u00e1n Pinz\u00f3n Romero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3digo: UCMV-10<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad: <a href=\"https:\/\/www.ucentral.edu.co\/\">Universidad Central<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Referencias<\/strong><\/h3>\n\n\n\n<pre class=\"wp-block-preformatted\">1.\tBlender Foundation. (s. f.). Screencast Keys [Complemento]. Blender Extensions. Recuperado de https:\/\/extensions.blender.org\/add-ons\/screencast-keys\/<br>2.\tBlender Foundation. (s. f.). Archimesh [Complemento]. Blender Extensions. Recuperado de https:\/\/extensions.blender.org\/add-ons\/archimesh\/<br>3.\tBlender Documentation. (s. f.). Subdivide edges. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/modeling\/meshes\/editing\/edge\/subdivide.html<br>4.\tBlender Documentation. (s. f.). Mirror. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/scene_layout\/object\/editing\/mirror.html<br>5.\tBlender Documentation. (s. f.). Solidify modifier. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/modeling\/modifiers\/generate\/solidify.html<br>6.\tBlender Documentation. (s. f.). Array modifier. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/modeling\/modifiers\/generate\/array.html<br>7.\tBlender Documentation. (s. f.). Join objects. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/scene_layout\/object\/editing\/join.html<br>8.\tBlender Documentation. (s. f.). Empties. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/modeling\/empties.html<br>9.\tBlender Documentation. (s. f.). Principled BSDF Shader. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/render\/shader_nodes\/shader\/principled.html<br>10.\tBlender Documentation. (s. f.). Checker Texture Node. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/compositing\/types\/texture\/checker.html<br>11.\tBlender Documentation. (s. f.). Bump Node. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/render\/shader_nodes\/vector\/bump.html<br>12.\tBlender Documentation. (s. f.). Material Preview. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/render\/materials\/preview.html<br>13.\tBlender Documentation. (s. f.). Shape Keys. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/animation\/shape_keys\/index.html<br>14.\tBlender Documentation. (s. f.). Proportional Editing. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/editors\/3dview\/controls\/proportional_editing.html<br>15.\tBlender Documentation. (s. f.). Nonlinear Animation (NLA) Editor. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/editors\/nla\/index.html<br>16.\tBlender Documentation. (s. f.). Dope Sheet Editor. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/editors\/dope_sheet\/index.html<br>17.\tBlender Documentation. (s. f.). Action Editor. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/editors\/dope_sheet\/modes\/action.html<br>18.\tBlender Documentation. (s. f.). Cloth Simulation. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/physics\/cloth\/index.html<br>19.\tBlender Documentation. (s. f.). Video Sequencer. Blender Manual. Recuperado de https:\/\/docs.blender.org\/manual\/en\/latest\/editors\/video_sequencer\/index.html<br>20.\tLignaushop. (s. f.). Solid oak hardwood shelf rustic grade (20 mm) [Imagen de textura]. Recuperado de https:\/\/www.lignaushop.de\/solid-oak-hardwood-shelf-rustic-grade-20-mm-unfinished-1659-2771.html<br>21.\tOpenGameArt. (s. f.). Energy drink texture (drink.png) [Textura digital]. Recuperado de https:\/\/opengameart.org\/content\/energy-drink-texture-drinkpng<br>22.\tWikimedia Commons. (s. f.). Donut texture, Doughnut.jpg [Archivo de imagen]. Recuperado de https:\/\/commons.wikimedia.org\/wiki\/File:Donut_texture,_Doughnut.jpg<br>23.\tFavPNG. (s. f.). UV mapping texture of icosahedron (D20) [Imagen]. Recuperado de https:\/\/favpng.com\/png_view\/uv-mapping-texture-mapping-icosahedron-edge-d20-system-png\/4z3Z6Ktt<br>24.\tSketchfab. (s. f.). Agent Jonesy (3D model) [Modelo 3D]. Recuperado de https:\/\/sketchfab.com\/3d-models\/agent-jonesy-4f58c52acca141e6950575c5f95bd193<br>25.\tSpaceSphereMaps. (s. f.). HDR Spheremaps collection [Mapas HDRI]. Recuperado de https:\/\/www.spacespheremaps.com\/hdr-spheremaps\/<br>26.\tYouTube. (2019). C\u00f3mo hacer baldosas en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=fXVPwlDEHrQ<br>27.\tYouTube. (2020). Patr\u00f3n de baldosas en Blender (versi\u00f3n 2) [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=pAxo1kWSjWI<br>28.\tYouTube. (2018). C\u00f3mo crear textura personalizada en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=F7Pt-SOnJ5U<br>29.\tYouTube. (2021). Transparencia en materiales de Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=o8k9TmMfRqc<br>30.\tYouTube. (2020). C\u00f3mo hacer una pared en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=Cunh57XjRv4<br>31.\tYouTube. (2020). C\u00f3mo modelar una ventana en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=M4yT4_JUVfg<br>32.\tYouTube. (2021). C\u00f3mo crear una cortina con simulaci\u00f3n de tela en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=DRbA0vgbcJ4<br>33.\tYouTube. (2020). Edici\u00f3n proporcional en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=DXSjuW0Yfoo<br>34.\tYouTube. (2021). C\u00f3mo modelar un estante en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=OOBKo-O6i_8<br>35.\tYouTube. (2022). C\u00f3mo modelar un donut en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=tBpnKTAc5Eo<br>36.\tYouTube. (2022). Combinar animaciones de Mixamo en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=fx7CCPl0m6U<br>37.\tYouTube. (2018). C\u00f3mo mover la c\u00e1mara en Blender [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=aY04h4ujrlY<br>38.\tYouTube. (2016). As\u00ed habl\u00f3 Zaratustra \u2014 Richard Strauss (Soundtrack) [Video]. Recuperado de https:\/\/www.youtube.com\/watch?v=SLuW-GBaJ8k<br>39.\tBlender Artists. (s. f.). UV mapping of a donut [Discusi\u00f3n en foro]. Recuperado de https:\/\/blenderartists.org\/t\/uv-mapping-of-a-donut\/551152<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parte 1: Modelado y Texturizado Durante este ejercicio, vamos a explorar diferentes herramientas y formas de aplicar texturas dentro de Blender. Para empezar, crearemos una habitaci\u00f3n donde se van a almacenar todas nuestras primitivas, y luego se explican t\u00e9cnicas para algunas primitivas El Suelo Para comenzar, vamos a utilizar unSeguir Leyendo<\/p>\n","protected":false},"author":1950,"featured_media":72838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1768],"tags":[1144,473,1324,1348,4214],"class_list":["post-72682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-animacion","tag-animacion-3d","tag-blender","tag-mixamo","tag-sketchfab","tag-texturizado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modelos, Texturas y Animaci\u00f3n con Blender &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos<\/title>\n<meta name=\"description\" content=\"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelos, Texturas y Animaci\u00f3n con Blender\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelos, Texturas y Animaci\u00f3n con Blender &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"og:description\" content=\"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelos, Texturas y Animaci\u00f3n con Blender\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-23T01:26:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T01:28:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/portada.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"589\" \/>\n\t<meta property=\"og:image:height\" content=\"302\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"cmendezp1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"cmendezp1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelos, Texturas y Animaci\u00f3n con Blender &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelos, Texturas y Animaci\u00f3n con Blender","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/","og_locale":"es_ES","og_type":"article","og_title":"Modelos, Texturas y Animaci\u00f3n con Blender &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","og_description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelos, Texturas y Animaci\u00f3n con Blender","og_url":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2025-10-23T01:26:21+00:00","article_modified_time":"2025-10-23T01:28:38+00:00","og_image":[{"width":589,"height":302,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/portada.webp","type":"image\/webp"}],"author":"cmendezp1","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"cmendezp1","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/"},"author":{"name":"cmendezp1","@id":"https:\/\/niixer.com\/#\/schema\/person\/5b6f7322279d0ff9c4956fd05fc160a8"},"headline":"Modelos, Texturas y Animaci\u00f3n con Blender","datePublished":"2025-10-23T01:26:21+00:00","dateModified":"2025-10-23T01:28:38+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/"},"wordCount":970,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/portada.webp","keywords":["Animaci\u00f3n 3D","Blender","Mixamo","sketchfab","Texturizado"],"articleSection":["Animaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/","url":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/","name":"Modelos, Texturas y Animaci\u00f3n con Blender &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/portada.webp","datePublished":"2025-10-23T01:26:21+00:00","dateModified":"2025-10-23T01:28:38+00:00","description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Modelos, Texturas y Animaci\u00f3n con Blender","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/portada.webp","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/10\/portada.webp","width":589,"height":302},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2025\/10\/22\/modelos-texturas-y-animacion-con-blender\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Modelos, Texturas y Animaci\u00f3n con Blender"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/5b6f7322279d0ff9c4956fd05fc160a8","name":"cmendezp1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a14b8d0cc50ca5c0af2262897b1a3621dc006406bbda42c9907091e83454b428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a14b8d0cc50ca5c0af2262897b1a3621dc006406bbda42c9907091e83454b428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a14b8d0cc50ca5c0af2262897b1a3621dc006406bbda42c9907091e83454b428?s=96&d=mm&r=g","caption":"cmendezp1"},"url":"https:\/\/niixer.com\/index.php\/author\/cmendezp1\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/72682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/1950"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=72682"}],"version-history":[{"count":6,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/72682\/revisions"}],"predecessor-version":[{"id":72894,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/72682\/revisions\/72894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/72838"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=72682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=72682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=72682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}