{"id":67109,"date":"2025-05-28T18:27:16","date_gmt":"2025-05-28T23:27:16","guid":{"rendered":"https:\/\/niixer.com\/?p=67109"},"modified":"2025-05-28T18:56:21","modified_gmt":"2025-05-28T23:56:21","slug":"blender-y-sus-diferentes-formas-de-modelar","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/","title":{"rendered":"Blender y sus diferentes formas de modelar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Blender y sus diferentes formas de modelar, en el siguiente articulo se presentara diferentes desarrollos que se pueden hacer gracias a blender y sus funcionalidades, como desglose se va a entregar como se realizo una taza, mu\u00f1eco de nieve, unas esferas, un dado, un l\u00e1piz, un planeta tierra con su luna, un port\u00e1til y una dona, adem\u00e1s cono se realizo el dise\u00f1o de un entorno para una animaci\u00f3n gracias con la herramienta sketchfab, para poder realizar una cinem\u00e1tica<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1\u00b0 Anillo : esferas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para iniciar con este proyecto debemos agregar a nuestro modelo un plano  con ctrl + A +malla,  y una esfera con ctrl + A + malla, el plano lo escal\u00e1ramos con la tecla s, en donde se busca que el plano se duplique su escala y la esfera la mantendremos en ese tama\u00f1o para luego ubicarla en la posici\u00f3n de x en 3,<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"583\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-150107-1024x583.png\" alt=\"\" class=\"wp-image-67115\" style=\"width:610px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-150107-1024x583.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-150107-300x171.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-150107-768x437.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-150107.png 1164w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Luego esta misma esfera la duplicaremos con shift + D, esta esfera la ubicaremos en -x=3, para luego duplicar estas dos esferas nuevamente con Shift +D y la ubicamos a 60 \u00b0, nuevamente las mismas esferas anteriores las duplicaremos con Shift + D y las ubicamos en la posici\u00f3n de -60\u00b0<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"817\" height=\"461\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-151054.png\" alt=\"\" class=\"wp-image-67116\" style=\"width:490px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-151054.png 817w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-151054-300x169.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-151054-768x433.png 768w\" sizes=\"auto, (max-width: 817px) 100vw, 817px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ya de tenerlas en esta ubicaci\u00f3n se aplicara el color, el la parte derecha de nuestra herramienta nos dirigimos a materiales y en ella seleccionamos el + de la ventana para poder crear un nuevo material, se crea un nuevo color en este caso se coloca el color azul con el c\u00f3digo 00BCFFFF,<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"566\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/image-415-1024x566.png\" alt=\"\" class=\"wp-image-67118\" style=\"width:431px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/image-415-1024x566.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/image-415-300x166.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/image-415-768x424.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/image-415.png 1061w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Luego Se coloca color a las dem\u00e1s esferas con los siguientes colores verde = 1DFF00FF, amarillo = FFFF00FF,  fucsia = FF00B5FF,  naranja = FF8500FF, morado = 9E00FFFF<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"564\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-152739-1024x564.png\" alt=\"\" class=\"wp-image-67125\" style=\"width:610px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-152739-1024x564.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-152739-300x165.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-152739-768x423.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-152739.png 1098w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ya de tener las esferas pintadas  se procede  agregar metalizado, abajo en la parte inferior de las herramientas se coloca 1 en metalizado, no se coloca ni 0.5 o 0.1, no, se debe colocar 1 o 0, esto se debe hacer con las dem\u00e1s esferas para que quede de la siguiente forma <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"572\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/image-422.png\" alt=\"\" class=\"wp-image-67128\" style=\"width:638px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/image-422.png 880w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/image-422-300x195.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/image-422-768x499.png 768w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo se coloca a Suzanne en en medio de los anillos con un color met\u00e1lico de color dorado <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"763\" height=\"408\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-162339.png\" alt=\"\" class=\"wp-image-67180\" style=\"width:512px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-162339.png 763w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-162339-300x160.png 300w\" sizes=\"auto, (max-width: 763px) 100vw, 763px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed nos quedar\u00edan los anillos con los colores aplicados<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"687\" height=\"546\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-162817.png\" alt=\"\" class=\"wp-image-67181\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-162817.png 687w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/Captura-de-pantalla-2025-05-21-162817-300x238.png 300w\" sizes=\"auto, (max-width: 687px) 100vw, 687px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Construcci\u00f3n del port\u00e1til<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para el siguiente objeto se agrego un cubo con Shift + A, luego con la tecla S y la rueda del rat\u00f3n, escalamos en sentido X y Y con la vista en Z, luego cambiamos la vista a Y y con la tecla S y la rueda del rat\u00f3n, escalamos en sentido de Z,<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"251\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/1-2.webp\" alt=\"\" class=\"wp-image-67806\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/1-2.webp 474w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/1-2-300x159.webp 300w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"447\" height=\"237\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/2-2.webp\" alt=\"\" class=\"wp-image-67807\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/2-2.webp 447w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/2-2-300x159.webp 300w\" sizes=\"auto, (max-width: 447px) 100vw, 447px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Luego seleccionamos el cubo y lo duplicamos, el que se acaba de duplicar con la herramienta rotar,&nbsp;<a href=\"https:\/\/personales.upv.es\/aperis\/docencia\/int_linea.pdf\">lo rotaremos en sentido del eje Z&nbsp;<\/a>haciendo que quede en una posici\u00f3n en diagonal, para luego moverlo con la tecla G, una de estas partes va hacer la pantalla del port\u00e1til y la otra la base de los componentes y el teclado , ocultaremos la pantalla.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"488\" height=\"275\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/3.webp\" alt=\"\" class=\"wp-image-67808\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/3.webp 488w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/3-300x169.webp 300w\" sizes=\"auto, (max-width: 488px) 100vw, 488px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Seleccionamos los v\u00e9rtices en modo editor, las dos v\u00e9rtices que se encuentran a los costados del eje X, y con el uso de la tecla G y la rueda del Mouse lo desplazaremos sobre el eje Z hacia abajo para que la base tenga un desnivel<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"201\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/4-1.webp\" alt=\"\" class=\"wp-image-67809\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/4-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/4-1-300x102.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Luego seleccionamos el objeto por completo y con el ctrl + R realizamos dos cortes en la parte mas ancha en sentido del eje Y y un corte mas en sentido del eje X en la parte superior, luego borramos los bordes que se encuentran en medio de los cortes y creamos nuevas caras con la tecla F, seleccionando las v\u00e9rtices donde queremos que se crean caras nuevas.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"288\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/5-1.webp\" alt=\"\" class=\"wp-image-67810\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/5-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/5-1-300x147.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"385\" height=\"272\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/6-1.webp\" alt=\"\" class=\"wp-image-67811\" style=\"width:275px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/6-1.webp 385w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/6-1-300x212.webp 300w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"270\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/7-1.webp\" alt=\"\" class=\"wp-image-67812\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/7-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/7-1-300x138.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Con la herramienta subdividir superficies, estando seleccionado el modo objeto&nbsp; y con ctrl +R realizando cortes para que nuestro objeto tenga una superficie mas curveada, luego de realizar varios cortes con la tecla S y con la rueda del rat\u00f3n escalaremos los cortes en sentido contrario del corte hasta el costado de los bordes de los objetos.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"265\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/8-1.webp\" alt=\"\" class=\"wp-image-67813\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/8-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/8-1-300x135.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"334\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/9-1.webp\" alt=\"\" class=\"wp-image-67814\" style=\"width:427px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/9-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/9-1-300x170.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Estos subdivisi\u00f3n de superficies las realizaremos en cada una de las caras que hemos cortado con anterioridad.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"373\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/10-1.webp\" alt=\"\" class=\"wp-image-67815\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/10-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/10-1-300x190.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez tengamos la primera parte del port\u00e1til habilitamos la pantalla la cual debemos estar en modo objeto, para luego buscar la herramienta modificadores y aplicar con el modificador subdividir superficies, luego con ctrl + R realizamos varios cortes para que cada corte se ubique a los costados del modelo.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"363\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/11-1.webp\" alt=\"\" class=\"wp-image-67816\" style=\"width:292px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/11-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/11-1-300x185.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"274\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/12-2.webp\" alt=\"\" class=\"wp-image-67817\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/12-2.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/12-2-300x140.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"440\" height=\"286\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/13-1.webp\" alt=\"\" class=\"wp-image-67818\" style=\"width:258px;height:auto\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/13-1.webp 440w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/13-1-300x195.webp 300w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora nos colocamos en modo editor, con selecci\u00f3n de caras seleccionamos las caras que se encuentran dentro de nuestro modelo dejando una cara en los bordes, con estas caras seleccionadas y con la tecla E extruimos en sentido del eje X hacia al fondo para darle profundidad a la pantalla.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"357\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/14-1.webp\" alt=\"\" class=\"wp-image-67819\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/14-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/14-1-300x182.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"310\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/15-1.webp\" alt=\"\" class=\"wp-image-67820\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/15-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/15-1-300x158.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/15-1-390x205.webp 390w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"371\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/16.webp\" alt=\"\" class=\"wp-image-67821\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/16.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/16-300x189.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"322\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/17.webp\" alt=\"\" class=\"wp-image-67822\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/17.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/17-300x164.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Elaboraci\u00f3n del teclado<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para la elaboraci\u00f3n del teclado se utiliz\u00f3 un cubo, Agregamos con Shift + A, luego con la tecla S lo escalamos a un menor tama\u00f1o, el suficiente para que quepa dentro de la base del teclado, luego de esto lo ubicamos en la parte superior derecha de nuestra base usando G para moverlo, luego en la base con la tecla S con rueda rat\u00f3n escalamos en sentido Z y Y para que su tama\u00f1o disminuya.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"287\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/18-2.webp\" alt=\"\" class=\"wp-image-67823\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/18-2.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/18-2-300x146.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"272\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/19-1.webp\" alt=\"\" class=\"wp-image-67824\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/19-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/19-1-300x139.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez lo tengamos en la posici\u00f3n lo duplicaremos la cantidad que sea necesaria para que se asimile a las teclas del teclado, una vez terminado de colocar las teclas tomaremos teclas aleatorias para hacerlas mas grande con el fin de que parezca al teclado normalmente utilizado.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"288\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/20-2.webp\" alt=\"\" class=\"wp-image-67825\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/20-2.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/20-2-300x147.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"300\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/21-1.webp\" alt=\"\" class=\"wp-image-67826\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/21-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/21-1-300x153.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"333\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/22-1.webp\" alt=\"\" class=\"wp-image-67827\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/22-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/22-1-300x170.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para la aplicaci\u00f3n del color se realizo lo siguiente, para la textura del teclado, abrimos directamente sombreado en donde seleccionamos el color #2B262FFF, la dem\u00e1s parte del port\u00e1til las ocultamos, Durante ese tiempo realizamos varias pruebas de como aplicar el color a las teclas, hasta que se dio con el resultado y es seleccionar la tecla que tiene el color y manteniendo seleccionado shift y con el rat\u00f3n seleccionamos las casillas que falta color, le damos clic derecho sobre la tecla del color y le damos Vincular materiales.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"300\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/24-1.webp\" alt=\"\" class=\"wp-image-67828\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/24-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/24-1-300x153.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"301\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/23-1.webp\" alt=\"\" class=\"wp-image-67831\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/23-1.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/23-1-300x153.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez realizado con la tecla G movemos el resto del port\u00e1til donde esta el teclado, y aplicamos un color gris,<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"589\" height=\"298\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/25-2.webp\" alt=\"\" class=\"wp-image-67830\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/25-2.webp 589w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/25-2-300x152.webp 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el resultado del modelado de un port\u00e1til a partir de un cubo <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"629\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/26-1024x629.webp\" alt=\"\" class=\"wp-image-67832\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/26-1024x629.webp 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/26-300x184.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/26-768x472.webp 768w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/26-1536x943.webp 1536w, https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/26.webp 1602w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Video de la cinem\u00e1tica <\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Video Final de cinem\u00e1tica de computaci\u00f3n grafica\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/YHvaaReYDRA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Cr\u00e9ditos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor<\/strong>:\u00a0<a href=\"https:\/\/niixer.com\/?s=David+Steven+Rojas+Santana\">David Steven Rojas Santana<\/a><br><strong>Editor<\/strong>:<a href=\"https:\/\/niixer.com\/?s=Carlos+Iv%C3%A1n+Pinz%C3%B3n+Romero\">\u00a0Magister ingeniero Carlos Iv\u00e1n Pinz\u00f3n Romero<\/a><br><strong>C\u00f3digo<\/strong>: UCCG-9<br><strong>Universidad<\/strong>:\u00a0<a href=\"https:\/\/www.google.com\/search?q=Universidad+Central&amp;oq=Universidad+Central&amp;gs_lcrp=EgZjaHJvbWUyBggAEEUYOTIGCAEQRRg7MgYIAhBFGDwyBggDEEUYPTIGCAQQLhhA0gEHMzY0ajBqOagCALACAQ&amp;sourceid=chrome&amp;ie=UTF-8\">Universidad Central<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Referencias<\/strong><\/h2>\n\n\n\n<pre class=\"wp-block-preformatted\">Adobe. (2025). Mixamo. https:\/\/www.mixamo.com\/#\/?page=1&amp;query=&amp;type=Motion%2CMotionPack<br>Nombres de personajes usados: Warzombie F, James, Avelange, Exo red, Maw J Laygo<br><br>Crowd Scream Imatination. (s.f.). Efecto de sonido Agon\u00eda, Grito, La risa. De uso gratuito [Efecto de sonido]. Pixabay. https:\/\/pixabay.com\/es\/sound-effects\/crowd-scream-imatination-232316\/<br><br>delosound. (2025). Suspense Tension Trailer [Audio]. Pixabay. https:\/\/pixabay.com\/es\/music\/suspenso-suspense-tension-trailer-345353\/<br><br>DRAGON-STUDIO. (2025). Female Zombie Screams: Efecto de sonido Grito de zombi, Chillido de zombi, Apocalipsis zombie [Efecto de sonido]. Pixabay. https:\/\/pixabay.com\/es\/sound-effects\/female-zombie-screams-324744\/<br><br>KRITZ STUDIO 3D. (2023, julio 26). \ud83d\udd34Combinar animaciones de MIXAMO en BLENDER \ud83d\udd34 Tutorial b\u00e1sico y simplificado [Video]. YouTube. https:\/\/www.youtube.com\/watch?v=SyCU7xqivBE&amp;t=12<br><br>Lumora_Studios. (s.f.). Pixel Jump: Efecto de sonido Pixel, Salto, Salto de p\u00edxeles [Efecto de sonido]. Pixabay. https:\/\/pixabay.com\/es\/sound-effects\/pixel-jump-319167\/<br><br>MyInstants. (s.f.). Corre perra, corre [Audio]. https:\/\/www.myinstants.com\/es\/instant\/corre-perra-corre-98740\/<br><br>Pablo Serrano. (2019, octubre 9). Ejemplo de animaci\u00f3n de c\u00e1mara en Blender 2.80 [Video]. YouTube. https:\/\/www.youtube.com\/watch?v=bscRt7z0sXQ&amp;t=723s<br><br>PW23CHECK. (s.f.). Winning: Efecto de sonido Ganador, Juego, Juegos de azar [Efecto de sonido]. Pixabay. https:\/\/pixabay.com\/es\/sound-effects\/winning-218995\/<br><br>Sketchfab. (2023, diciembre 15). Sketchfab for Blender (Versi\u00f3n 1.6.1) [Blender plugin]. GitHub. https:\/\/github.com\/sketchfab\/blender-plugin<br><br>Sketchfab. (2025). Personalize your experience. What are you interested in? Sketchfab. https:\/\/sketchfab.com\/feed<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Blender y sus diferentes formas de modelar, en el siguiente articulo se presentara diferentes desarrollos que se pueden hacer gracias a blender y sus funcionalidades, como desglose se va a entregar como se realizo una taza, mu\u00f1eco de nieve, unas esferas, un dado, un l\u00e1piz, un planeta tierra con suSeguir Leyendo<\/p>\n","protected":false},"author":1875,"featured_media":67997,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1938],"tags":[1153,473,1317,4275,1324],"class_list":["post-67109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blender","tag-animacion-2","tag-blender","tag-cultura","tag-desafio","tag-mixamo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blender y sus diferentes formas de modelar &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos<\/title>\n<meta name=\"description\" content=\"Descubre como se creo un port\u00e1til mediante el uso de blender, desde un cubo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blender y sus diferentes formas de modelar &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"og:description\" content=\"Descubre como se creo un port\u00e1til mediante el uso de blender, desde un cubo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-28T23:27:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-28T23:56:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/principal-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"drojass4\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"drojass4\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blender y sus diferentes formas de modelar &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","description":"Descubre como se creo un port\u00e1til mediante el uso de blender, desde un cubo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/","og_locale":"es_ES","og_type":"article","og_title":"Blender y sus diferentes formas de modelar &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","og_description":"Descubre como se creo un port\u00e1til mediante el uso de blender, desde un cubo","og_url":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2025-05-28T23:27:16+00:00","article_modified_time":"2025-05-28T23:56:21+00:00","og_image":[{"width":1280,"height":780,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/principal-1.jpg","type":"image\/jpeg"}],"author":"drojass4","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"drojass4","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/"},"author":{"name":"drojass4","@id":"https:\/\/niixer.com\/#\/schema\/person\/2e90f386bc1e2a751534deea4c51ecec"},"headline":"Blender y sus diferentes formas de modelar","datePublished":"2025-05-28T23:27:16+00:00","dateModified":"2025-05-28T23:56:21+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/"},"wordCount":1081,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/principal-1.jpg","keywords":["Animacion","Blender","Cultura","desafio","Mixamo"],"articleSection":["Blender"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/","url":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/","name":"Blender y sus diferentes formas de modelar &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/principal-1.jpg","datePublished":"2025-05-28T23:27:16+00:00","dateModified":"2025-05-28T23:56:21+00:00","description":"Descubre como se creo un port\u00e1til mediante el uso de blender, desde un cubo","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/principal-1.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2025\/05\/principal-1.jpg","width":1280,"height":780,"caption":"Renderizado de la cinem\u00e1tica"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2025\/05\/28\/blender-y-sus-diferentes-formas-de-modelar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Blender y sus diferentes formas de modelar"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/2e90f386bc1e2a751534deea4c51ecec","name":"drojass4","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/36124bc034087e5a467735abf51b9e69c14e2273a2dd7c2f82c69ddd60bd64c0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36124bc034087e5a467735abf51b9e69c14e2273a2dd7c2f82c69ddd60bd64c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36124bc034087e5a467735abf51b9e69c14e2273a2dd7c2f82c69ddd60bd64c0?s=96&d=mm&r=g","caption":"drojass4"},"url":"https:\/\/niixer.com\/index.php\/author\/drojass4\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/67109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/1875"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=67109"}],"version-history":[{"count":7,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/67109\/revisions"}],"predecessor-version":[{"id":68037,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/67109\/revisions\/68037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/67997"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=67109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=67109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=67109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}