{"id":577,"date":"2020-10-07T14:08:48","date_gmt":"2020-10-07T19:08:48","guid":{"rendered":"https:\/\/niixer.com\/?p=577"},"modified":"2020-10-23T11:59:26","modified_gmt":"2020-10-23T16:59:26","slug":"realidad-virtual-y-su-aplicacion-en-la-medicina","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/","title":{"rendered":"La Realidad Virtual y su aplicaci\u00f3n en la medicina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La medicina tiene varios campos de acci\u00f3n en el que la Realidad Virtual efect\u00faa una aplicaci\u00f3n, algunas de ellas son: la formaci\u00f3n de estudiantes de medicina, simulaci\u00f3n de operaciones, reducci\u00f3n de fobias. As\u00ed como la Realidad Virtual o VR consiste en la inmersi\u00f3n sensorial de una persona en un entorno o espacio de escenas de apariencia real generado por computadora y a trav\u00e9s de unas gafas, controles remotos y auriculares, de esta forma la persona tiene una sensaci\u00f3n m\u00e1s inmersiva en este mundo ficticio. As\u00ed mismo, la persona puede experimentar y tener reacciones f\u00edsicas y sensoriales cercanas a las que se podr\u00eda producir en la vida real.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Un poco de historia de la Realidad Virtual<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Realidad Virtual es una<a href=\"https:\/\/niixer.com\/?s=tecnologia\"> <\/a><a href=\"https:\/\/niixer.com\/?s=tecnologia\">tecnolog\u00eda<\/a> que se cre\u00f3 a mitad del siglo XX en el cual unos visionarios entendieron que este tipo de recreaciones podr\u00edan generar inter\u00e9s entre las personas.&nbsp; De hecho, una de las primeras m\u00e1quinas en poder generar este tipo de sensaciones fue \u201cSensorama\u201d creada a mediados del siglo XX, ya que estaba equipada con un asiento donde se pod\u00eda ver pel\u00edculas en 3D, era capaz de emitir olores, movimientos y vibraci\u00f3n con respecto a lo que se estaba proyectando en la pel\u00edcula.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aplicaci\u00f3n de la Realidad Virtual en la formaci\u00f3n de estudiantes de medicina<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente la<a href=\"https:\/\/niixer.com\/?s=medicina\"> <\/a><a href=\"https:\/\/niixer.com\/?s=medicina\">medicina<\/a> se destaca porque representa el trabajo multidisciplinario y la toma de decisiones riesgosas, por lo tanto, las nuevas tecnolog\u00edas han permitido unir la rob\u00f3tica y la realidad virtual, permitiendo un entorno muy parecido al real y a sus estudiantes practicar en escenarios m\u00e1s reales. Con todo esto, en las pr\u00e1cticas virtuales que puede hacer un estudiante es una simulaci\u00f3n de habilidades con maniqu\u00edes, los cuales tienen \u00f3rganos o partes completas del cuerpo humano. Este sistema permitir\u00e1 al estudiante adquirir habilidades manuales en la endoscopia, laparoscopia o navegaci\u00f3n endovascular, reconocer la estructura de los \u00f3rganos y aprender a utilizar los diferentes equipos m\u00e9dicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La medicina tiene varios campos de acci\u00f3n en el que la realidad virtual efect\u00faa una aplicaci\u00f3n, algunas de ellas son: la formaci\u00f3n de estudiantes de medicina, simulaci\u00f3n de operaciones, reducci\u00f3n de<a href=\"https:\/\/niixer.com\/?s=fobias\"> <\/a><a href=\"https:\/\/niixer.com\/?s=fobias\">fobias<\/a>. Finalmente consiste en la inmersi\u00f3n sensorial de una persona en un entorno o espacio de escenas de apariencia real generado por computadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de gafas, controles remotos y auriculares, de esta forma la persona tiene una sensaci\u00f3n m\u00e1s inmersiva en este mundo ficticio y las personas pueden experimentar y tener reacciones f\u00edsicas y sensoriales cercanas a las que se podr\u00eda producir en la vida real.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Simulaci\u00f3n de operaciones con la Realidad Virtual en la medicina<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con la integraci\u00f3n de programadores y modeladores 3D se puede replicar con mucha exactitud la anatom\u00eda de un paciente, con el objetivo de practicar la operaci\u00f3n antes de realizar el procedimiento en una persona. Con el uso de esta tecnolog\u00eda, se disminuye la pr\u00e1ctica en cad\u00e1veres, animales y con lo cual se evitar\u00e1 la pr\u00e1ctica con alg\u00fan paciente real, ya que usando la Realidad Virtual se podr\u00eda reiterar la operaci\u00f3n cuantas veces sea necesario para tener una mayor precisi\u00f3n al realizarla en una persona.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reducci\u00f3n de fobias usando la Realidad Virtual<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las fobias son un tipo de trastorno psicol\u00f3gico o miedos irracionales debido a que se presentan en algunas personas ante determinados objetos o situaciones.&nbsp; El miedo a algunos animales, a la oscuridad, a las alturas, a los espacios cerrados, a hablar en p\u00fablico o son un claro ejemplo de algunas fobias y con la realidad virtual lo que se hace es enfrentar al paciente y de forma gradual a sus fobias en un entorno artificial.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Autor:<a href=\"http:\/\/www.niixer.com\/?s=Andr%C3%A9s+Felipe+Tobos+Agudelo+\"> <\/a><a href=\"http:\/\/www.niixer.com\/?s=Andr%C3%A9s+Felipe+Tobos+Agudelo+\">Andr\u00e9s Felipe Tobos Agudelo<\/a><\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">Editor: Carlos Pinz\u00f3n<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">C\u00f3digo: UCRV-8<\/h5>\n\n\n\n<h5 class=\"wp-block-heading\">Universidad:<a href=\"https:\/\/www.ucentral.edu.co\/\"> <\/a><a href=\"https:\/\/www.ucentral.edu.co\/\">Universidad Central<\/a><\/h5>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes:<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Revista de Robots. (2020). <em>DEFINICI\u00d3N DE QU\u00c9 ES LA REALIDAD VIRTUAL<\/em>. Revista de Robots. <a href=\"https:\/\/revistaderobots.com\/rv\/definicion-de-que-es-la-realidad-virtual\/\">https:\/\/revistaderobots.com\/rv\/definicion-de-que-es-la-realidad-virtual\/<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EP Eduardo Pardos. (s.f). <em>Realidad virtual y medicina: usos y aplicaciones<\/em>. Baboonlab. <a href=\"https:\/\/baboonlab.odoo.com\/blog\/noticias-de-marketing-inmobiliario-y-tecnologia-1\/post\/realidad-virtual-y-medicina-usos-y-aplicaciones-27#blog_post_comment_quote\"><strong>https:\/\/baboonlab.odoo.com\/blog\/noticias-de-marketing-inmobiliario-y-tecnologia-1\/post\/realidad-virtual-y-medicina-usos-y-aplicaciones-27#blog_post_comment_quote<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noticias Pfizer. (s.f). <em>Qu\u00e9 es la realidad virtual y c\u00f3mo se aplica en Medicina. <\/em>Pfizer. <a href=\"https:\/\/www.pfizerpro.es\/news\/que-es-la-realidad-virtual-y-como-se-aplica-en-medicina\">https:\/\/www.pfizerpro.es\/news\/que-es-la-realidad-virtual-y-como-se-aplica-en-medicina<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EB Eugenia Bollmann. (2018).<em> 5 usos de la realidad virtual en el mundo de la medicina<\/em>. Blogthinkbig. <em>&nbsp;<\/em><a href=\"https:\/\/blogthinkbig.com\/realidad-virtual-medicina\">https:\/\/blogthinkbig.com\/realidad-virtual-medicina<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noticias Pfizer. (s.f). <em>Qu\u00e9 es la realidad virtual y c\u00f3mo se aplica en Medicina<\/em> [Imagen]. Pfizer. <a href=\"https:\/\/www.pfizerpro.es\/news\/que-es-la-realidad-virtual-y-como-se-aplica-en-medicina\">https:\/\/www.pfizerpro.es\/news\/que-es-la-realidad-virtual-y-como-se-aplica-en-medicina<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La medicina tiene varios campos de acci\u00f3n en el que la Realidad Virtual efect\u00faa una aplicaci\u00f3n, algunas de ellas son: la formaci\u00f3n de estudiantes de medicina, simulaci\u00f3n de operaciones, reducci\u00f3n de fobias. As\u00ed como la Realidad Virtual o VR consiste en la inmersi\u00f3n sensorial de una persona en un entornoSeguir Leyendo<\/p>\n","protected":false},"author":66,"featured_media":578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[47],"tags":[79,80,84,81,388],"class_list":["post-577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-realidad-virtual","tag-fobias","tag-medicina","tag-modelos-3d","tag-realidad-virtual","tag-trastorno-psicologico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Realidad Virtual y su aplicaci\u00f3n en la medicina &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos<\/title>\n<meta name=\"description\" content=\"La Realidad Virtual es una tecnolog\u00eda que se cre\u00f3 a mitad del siglo XX y su aplicaci\u00f3n en el campo medicina con el tratamieto de enfermedades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Realidad Virtual y su aplicaci\u00f3n en la medicina &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"og:description\" content=\"La Realidad Virtual es una tecnolog\u00eda que se cre\u00f3 a mitad del siglo XX y su aplicaci\u00f3n en el campo medicina con el tratamieto de enfermedades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-07T19:08:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-23T16:59:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/realidad_virtual.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"877\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andres Felipe Tobos Agudelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Felipe Tobos Agudelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Realidad Virtual y su aplicaci\u00f3n en la medicina &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","description":"La Realidad Virtual es una tecnolog\u00eda que se cre\u00f3 a mitad del siglo XX y su aplicaci\u00f3n en el campo medicina con el tratamieto de enfermedades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/","og_locale":"es_ES","og_type":"article","og_title":"La Realidad Virtual y su aplicaci\u00f3n en la medicina &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","og_description":"La Realidad Virtual es una tecnolog\u00eda que se cre\u00f3 a mitad del siglo XX y su aplicaci\u00f3n en el campo medicina con el tratamieto de enfermedades.","og_url":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2020-10-07T19:08:48+00:00","article_modified_time":"2020-10-23T16:59:26+00:00","og_image":[{"width":877,"height":493,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/realidad_virtual.jpg","type":"image\/jpeg"}],"author":"Andres Felipe Tobos Agudelo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Felipe Tobos Agudelo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/"},"author":{"name":"Andres Felipe Tobos Agudelo","@id":"https:\/\/niixer.com\/#\/schema\/person\/74a22399adf90e135a6c5cf1b5dceec2"},"headline":"La Realidad Virtual y su aplicaci\u00f3n en la medicina","datePublished":"2020-10-07T19:08:48+00:00","dateModified":"2020-10-23T16:59:26+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/"},"wordCount":790,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/realidad_virtual.jpg","keywords":["Fobias","Medicina","Modelos 3D","Realidad Virtual","Trastorno psicol\u00f3gico"],"articleSection":["Realidad Virtual"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/","url":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/","name":"La Realidad Virtual y su aplicaci\u00f3n en la medicina &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/realidad_virtual.jpg","datePublished":"2020-10-07T19:08:48+00:00","dateModified":"2020-10-23T16:59:26+00:00","description":"La Realidad Virtual es una tecnolog\u00eda que se cre\u00f3 a mitad del siglo XX y su aplicaci\u00f3n en el campo medicina con el tratamieto de enfermedades.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/realidad_virtual.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/realidad_virtual.jpg","width":877,"height":493,"caption":"Tratamiento de pacientes con realidad virtual"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/07\/realidad-virtual-y-su-aplicacion-en-la-medicina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"La Realidad Virtual y su aplicaci\u00f3n en la medicina"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/74a22399adf90e135a6c5cf1b5dceec2","name":"Andres Felipe Tobos Agudelo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fee00f0d0ceca767e819bd8f7500f27d323e35c2e032d5d1bd5a836bbb758966?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee00f0d0ceca767e819bd8f7500f27d323e35c2e032d5d1bd5a836bbb758966?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee00f0d0ceca767e819bd8f7500f27d323e35c2e032d5d1bd5a836bbb758966?s=96&d=mm&r=g","caption":"Andres Felipe Tobos Agudelo"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/atobosa\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=577"}],"version-history":[{"count":20,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/577\/revisions"}],"predecessor-version":[{"id":1554,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/577\/revisions\/1554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/578"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}