{"id":42616,"date":"2023-09-26T16:03:50","date_gmt":"2023-09-26T21:03:50","guid":{"rendered":"https:\/\/niixer.com\/?p=42616"},"modified":"2023-10-03T12:14:22","modified_gmt":"2023-10-03T17:14:22","slug":"revolucion-industrial","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/","title":{"rendered":"causas de la revoluci\u00f3n industrial"},"content":{"rendered":"\n<h3 class=\"wp-block-heading has-black-color has-white-background-color has-text-color has-background has-large-font-size\">En qu\u00e9 consisti\u00f3 la revoluci\u00f3n industrial?<\/h3>\n\n\n<h2 class=\"wp-block-post-title\">causas de la revoluci\u00f3n industrial<\/h2>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-cyan-bluish-gray-background-color has-background has-medium-font-size\"><a href=\"https:\/\/www.biografiasyvidas.com\/historia\/revolucion_industrial.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>primera Revoluci\u00f3n Industrial <\/strong><\/a><br><a href=\"https:\/\/www.biografiasyvidas.com\/historia\/revolucion_industrial.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>(1760-1840)&nbsp;<\/strong><\/a><\/h3>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><span style=\"text-decoration: underline;\">Causas<\/span>: La Primera Revoluci\u00f3n Industrial comenz\u00f3 en Gran Breta\u00f1a y se debi\u00f3 en parte a la acumulaci\u00f3n de capital, el acceso a recursos naturales como el carb\u00f3n y el hierro, y el aumento de la poblaci\u00f3n urbana.&nbsp;: La Primera Revoluci\u00f3n Industrial comenz\u00f3 en Gran Breta\u00f1a y se debi\u00f3 en parte a la acumulaci\u00f3n de capital, el acceso a recursos naturales como el carb\u00f3n y el hierro, y el aumento de la poblaci\u00f3n urbana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ventajas<\/strong>: Mayor eficiencia de producci\u00f3n, crecimiento econ\u00f3mico, urbanizaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Desventajas<\/strong>: Condiciones laborales precarias, desplazamiento de trabajadores agr\u00edcolas, contaminaci\u00f3n ambiental.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inventos Importantes:&nbsp;<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/es.wikipedia.org\/wiki\/M%C3%A1quina_de_vapor\">M\u00e1quina de vapo<\/a>r (James Watt)&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Telar mec\u00e1nico (Edmund Cartwright).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Spinning Jenny (James Hargreaves).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1quina de hilar mec\u00e1nica (Richard Arkwright).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Locomotora a vapor (George Stephenson).&nbsp; <\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Importancia <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera &nbsp;<strong>Revoluci\u00f3n Industrial&nbsp;<\/strong>produjo el cambio m\u00e1s importante desde la<strong>&nbsp;revoluci\u00f3n neol\u00edtica<\/strong>, en la que el hombre empez\u00f3 a cultivar la tierra, transformando la producci\u00f3n de bienes. Supuso el&nbsp;<strong>paso de una econom\u00eda agraria a una econom\u00eda liderada por la industria<\/strong>, en la que la&nbsp;<strong>producci\u00f3n de bienes se realizaba de manera mecanizada<\/strong>. Esto provoc\u00f3 a su vez un&nbsp;<strong>aumento de la actividad comercial<\/strong>, con una mayor&nbsp;<strong>expansi\u00f3n comercial<\/strong>&nbsp;tambi\u00e9n favorecida por los las mejoras en los transportes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva industria&nbsp;<strong>se basaba en la&nbsp; &nbsp;AUTOMATIZACI\u00d3N<\/strong>&nbsp;de la producci\u00f3n y&nbsp;<strong>la aplicaci\u00f3n de innovaciones t\u00e9cnicas<\/strong>; la m\u00e1s impactante fue la invenci\u00f3n de la m\u00e1quina de vapor pero otros muchos avances t\u00e9cnicos fueron fundamentales, junto con el&nbsp;<strong>uso de nuevas fuentes de energ\u00eda<\/strong>&nbsp;(primero carb\u00f3n posteriormente petr\u00f3leo frente a la fuerza humana, animal o hidr\u00e1ulica usada anteriormente). La&nbsp;<strong>AUTOMATIZACI\u00d3N tambi\u00e9n se <\/strong>aplic\u00f3<strong> <\/strong>a la<strong> <\/strong>agricultura, lo que produjo un cambio e impulso en las labores agr\u00edcolas, incrementando su producci\u00f3n. Otra gran novedad fue que&nbsp;<strong>el proceso de producci\u00f3n se desarroll\u00f3 en f\u00e1bricas<\/strong>, edificios concretos destinados a la fabricaci\u00f3n de bienes ee eqiupo, inexistentes hasta entonces, lo que se denomina sistema fabril.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"630\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/caracteristicas_de_la_primera_revolucion_industrial_1760_orig-1-1024x630.webp\" alt=\"revolucion-industrial  introdujo la fabricaci\u00f3n de bienes\" class=\"wp-image-42857\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/caracteristicas_de_la_primera_revolucion_industrial_1760_orig-1-1024x630.webp 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/caracteristicas_de_la_primera_revolucion_industrial_1760_orig-1-300x184.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/caracteristicas_de_la_primera_revolucion_industrial_1760_orig-1-768x472.webp 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/caracteristicas_de_la_primera_revolucion_industrial_1760_orig-1.webp 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/Taller_1-1-1024x576.webp\" alt=\"revolucion-industrial \n diferenc\u00edo la automatizaci\u00f3n \" class=\"wp-image-42859\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/Taller_1-1-1024x576.webp 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/Taller_1-1-300x169.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/Taller_1-1-768x432.webp 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/Taller_1-1.webp 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-e1567527525777-1024x576.webp\" alt=\"revolucion-industrial umento  la producci\u00f3n en el sector automovilistico\" class=\"wp-image-42861\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-e1567527525777-1024x576.webp 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-e1567527525777-300x169.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-e1567527525777-768x432.webp 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-e1567527525777.webp 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"521\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-3-e1567528054391-1024x521.webp\" alt=\"la revolucion-industrial  sent\u00f3 las bases para el panorama tecnol\u00f3gico \" class=\"wp-image-42862\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-3-e1567528054391-1024x521.webp 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-3-e1567528054391-300x153.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-3-e1567528054391-768x391.webp 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/segunda-revolucion-industrial-3-e1567528054391.webp 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-cyan-bluish-gray-background-color has-background has-medium-font-size\"><strong><a href=\"https:\/\/humanidades.com\/segunda-revolucion-industrial\/\" target=\"_blank\" rel=\"noreferrer noopener\">Segunda Revoluci\u00f3n Industrial (1870-1914)&nbsp;<\/a><\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><span style=\"text-decoration: underline;\">Causas<\/span>: Esta revoluci\u00f3n se debi\u00f3 a avances en la metalurgia, la qu\u00edmica y la electricidad, as\u00ed como a la expansi\u00f3n de los ferrocarriles y la globalizaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ventajas<\/strong>: Aumento de la producci\u00f3n, mejoras en el transporte, crecimiento de la clase media.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Desventajas<\/strong>: Desigualdad econ\u00f3mica, condiciones laborales pobres, agotamiento de recursos naturales.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inventos Importantes:&nbsp;<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00ednea de ensamblaje (Henry Ford).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bombilla el\u00e9ctrica (Thomas Edison).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.rtve.es\/television\/20230307\/telefono-historia-patente-bell-meucci-aniversario-invento\/2430287.shtml#:~:text=El%207%20de%20marzo%20de%201876%20Graham%20Bell%20patent%C3%B3%20el,venga%20aqu%C3%AD%2C%20quiero%20verle%E2%80%9D.\">Tel\u00e9fono<\/a> (Alexander Graham Bell).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Motor de combusti\u00f3n interna (Nikolaus Otto).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Radio (Guglielmo Marconi).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>imp\u00f3rtancia <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Segunda Revoluci\u00f3n Industrial sent\u00f3 las bases para el panorama tecnol\u00f3gico del siglo XX.&nbsp;<strong>Los cambios y avances cient\u00edficos y t\u00e9cnicos se aceleraron y se diversificaron<\/strong>&nbsp;no solo geogr\u00e1ficamente, sino hacia muchos otros sectores productivos y de la sociedad.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-left has-cyan-bluish-gray-background-color has-background has-medium-font-size\" style=\"text-transform:capitalize\"><strong><a href=\"https:\/\/www.epitech-it.es\/tercera-revolucion-industrial\/\" target=\"_blank\" rel=\"noreferrer noopener\">tercera Revoluci\u00f3n Industrial (1960-2010)&nbsp;<\/a><\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><span style=\"text-decoration: underline;\">Causas<\/span>: Esta revoluci\u00f3n se bas\u00f3 en la inform\u00e1tica, la electr\u00f3nica y la tecnolog\u00eda de la informaci\u00f3n. La Guerra Fr\u00eda y la rivalidad tecnol\u00f3gica entre Estados Unidos y la Uni\u00f3n Sovi\u00e9tica contribuyeron a la innovaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ventajas<\/strong>: Automatizaci\u00f3n de procesos, avances en la inform\u00e1tica, globalizaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Desventajas<\/strong>: Desempleo estructural, brecha digital, preocupaciones sobre la privacidad.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Inventos Importantes:&nbsp;<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Microprocesador (<a href=\"https:\/\/www.intel.la\/content\/www\/xl\/es\/homepage.html\">Intel<\/a>).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">World Wide Web (Tim Berners-Lee).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Computadora personal (IBM).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tel\u00e9fono celular (Martin Cooper).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GPS (Roger L. Easton.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Importancia <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Tercera Revoluci\u00f3n Industrial cre\u00f3 nuevas actividades econ\u00f3micas que fueron el origen de nuevos sectores econ\u00f3micos, tradicionalmente separados como: primario, secundario y terciario. Tambi\u00e9n, la Tercera Revoluci\u00f3n Industrial es la manera de llamar<strong>&nbsp;a la \u00faltima de las transformaciones econ\u00f3micas que la humanidad<\/strong>&nbsp;ha vivido a lo largo de su historia. Esta es la m\u00e1s reciente en el tiempo y hoy en d\u00eda, todav\u00eda seguimos sufriendo sus consecuencias.&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/que-es-tercera-revolucion-industrial.webp\" alt=\" el acreo vance de la maquinaria siendo el humano reemplazado\" class=\"wp-image-42864\" style=\"width:559px;height:559px\" width=\"559\" height=\"559\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/que-es-tercera-revolucion-industrial.webp 720w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/que-es-tercera-revolucion-industrial-300x300.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/que-es-tercera-revolucion-industrial-150x150.webp 150w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"572\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/foto_2_pag_14-1024x572.webp\" alt=\"revolucion-industrial  fomento la  nuevas actividades econ\u00f3micas\" class=\"wp-image-42866\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/foto_2_pag_14-1024x572.webp 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/foto_2_pag_14-300x168.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/foto_2_pag_14-768x429.webp 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/foto_2_pag_14.webp 1289w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-cyan-bluish-gray-background-color has-background has-medium-font-size\" style=\"text-transform:capitalize\"><strong><a href=\"https:\/\/niixer.com\/wp-admin\/post.php?post=42878&amp;action=edit\">Cuarta Revoluci\u00f3n Industrial (2010 en adelante)&nbsp;<\/a><\/strong><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-justify wp-block-paragraph\"><span style=\"text-decoration: underline;\">Causas<\/span>: La Cuarta Revoluci\u00f3n Industrial se caracteriza por la convergencia de tecnolog\u00edas digitales, f\u00edsicas y biol\u00f3gicas, y se debe en parte a la creciente capacidad de procesamiento de datos y la disponibilidad de tecnolog\u00edas como la inteligencia artificial y la rob\u00f3tica avanzada.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-2c90304e wp-block-group-is-layout-flex\">\n<ul class=\"wp-block-list\">\n<li><strong>Inventos importantes<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Inteligencia Artificial (IA).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Impresi\u00f3n 3D avanzada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Edici\u00f3n gen\u00e9tica CRISPR-Cas9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veh\u00edculos aut\u00f3nomos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Internet de las cosas (IoT).&nbsp;<\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Importancia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como hemos indicado anteriormente, la Cuarta Revoluci\u00f3n Industrial se basa en el factor humano como centro de todo. Es por ello que para su \u00e9xito se debe romper con el caracter\u00edstico miedo a lo desconocido, tan caracter\u00edstico de nuestra especie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Industria 4.0 no ha venido para sustituir a las personas en sus puestos de trabajo. Al contrario, va a facilitar las tareas y, adem\u00e1s, va a liberar a los trabajadores de tareas mon\u00f3tonas. As\u00ed, podr\u00e1n dedicarse a otras m\u00e1s enriquecedoras para la propia industria, como para ellos mismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es un claro ejemplo del hecho de que la Cuarta Revoluci\u00f3n Industrial tiene m\u00e1s que ver con la cadena de valor que con la cadena de suministro. Aunque, por supuesto, afecta considerable y positivamente a ambas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aparte de la automatizaci\u00f3n de tareas, la Cuarta Revoluci\u00f3n Industrial abre la puerta a nuevos modelos de negocio, ya que hace posible la incorporaci\u00f3n de nuevas funciones y servicios a trav\u00e9s de las tecnolog\u00edas emergentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/niixer.com\/wp-admin\/post.php?post=42889&amp;action=edit\">Origen <\/a><\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/niixer.com\/wp-admin\/post.php?post=42889&amp;action=edit\">Eventos importantes<\/a><\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/niixer.com\/wp-admin\/post.php?post=42889&amp;action=edit\">Causas<\/a><\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/niixer.com\/wp-admin\/post.php?post=42889&amp;action=edit\">Consecuencias <\/a><\/p>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/niixer.com\/wp-admin\/post.php?post=42889&amp;action=edit\">Sintesis <\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"493\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/KGBX7H2GNRCPRA2LABJOIE4NFY-1024x493.webp\" alt=\"nuevos modelos de negocio\" class=\"wp-image-42868\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/KGBX7H2GNRCPRA2LABJOIE4NFY-1024x493.webp 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/KGBX7H2GNRCPRA2LABJOIE4NFY-300x144.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/KGBX7H2GNRCPRA2LABJOIE4NFY-768x370.webp 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/KGBX7H2GNRCPRA2LABJOIE4NFY.webp 1279w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"628\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/11082022-PORTADA-Toyota-GR86-turbo-min-1024x628.webp\" alt=\"revolucion-industrial logro romper con el caracter\u00edstico miedo a lo desconocido\" class=\"wp-image-42871\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/11082022-PORTADA-Toyota-GR86-turbo-min-1024x628.webp 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/11082022-PORTADA-Toyota-GR86-turbo-min-300x184.webp 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/11082022-PORTADA-Toyota-GR86-turbo-min-768x471.webp 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/10\/11082022-PORTADA-Toyota-GR86-turbo-min.webp 1279w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La REVOLUCI\u00d3N INDUSTRIAL: sus causas, etapas, inventos y consecuencias\ud83d\ude82\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/gW54xz7Gs4E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"10 Consecuencias de la Revoluci\u00f3n Industrial\ud83d\ude82\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/BURj8_GeGuA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La Revoluci\u00f3n Industrial, causas y consecuencias\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/xs9fWqP8Bl0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor<\/strong>: Luis Alejandro Daza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor<\/strong>:  Carlos pinz\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo<\/strong>: UCPC-1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad :<\/strong> Universidad Central, Bogot\u00e1 Colombia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Datision. (2022). La Cuarta Revoluci\u00f3n industrial y su impacto en la producci\u00f3n. <em>Datision<\/em>. https:\/\/datision.com\/blog\/cuarta-revolucion-industrial-produccion\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><span style=\"font-family: &quot;Times New Roman&quot;; font-size: 12pt; text-indent: -36pt;\">Moreno, J. (2018, 12 septiembre). Caracter\u00edsticas de la Primera Revoluci\u00f3n industrial. <\/span><i style=\"font-family: &quot;Times New Roman&quot;; font-size: 12pt; text-indent: -36pt;\">unprofesor.com<\/i><span style=\"font-family: &quot;Times New Roman&quot;; font-size: 12pt; text-indent: -36pt;\">. https:\/\/www.unprofesor.com\/ciencias-sociales\/caracteristicas-de-la-primera-revolucion-industrial-1760.html<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De Todos Los Tiempos, E. M. G. (2015, 11 julio). <em>ETAPAS DE LA COMUNICACI\u00d3N \u2013 ERA INDUSTRIAL<\/em>. Comunicultura. https:\/\/comuniculturas.wordpress.com\/2015\/07\/11\/etapas-de-la-comunicacion-era-industrial\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Webmaster. (s.&nbsp;f.). <em>Segunda Revoluci\u00f3n industrial: la aparici\u00f3n de la producci\u00f3n en masa<\/em>. Sebastian Brau. http:\/\/sebastianbrau.com\/segunda-revolucion-industrial-la-aparicion-de-la-produccion-en-masa\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Internet cumple 50 a\u00f1os como protagonista de la Tercera Revoluci\u00f3n<\/em>. (2019, 28 octubre). Los Tiempos. https:\/\/www.lostiempos.com\/tendencias\/tecnologia\/20191028\/internet-cumple-50-anos-como-protagonista-tercera-revolucion<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">AndresO, &amp; AndresO. (2023). Despu\u00e9s de la Segunda Revoluci\u00f3n Industrial, viene la Tercera Revoluci\u00f3n Industrial\u2026 <em>Qu\u00e9 es<\/em>. https:\/\/quees.com\/tercera-revolucion-industrial\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n","protected":false},"excerpt":{"rendered":"<p>En qu\u00e9 consisti\u00f3 la revoluci\u00f3n industrial? primera Revoluci\u00f3n Industrial (1760-1840)&nbsp; Causas: La Primera Revoluci\u00f3n Industrial comenz\u00f3 en Gran Breta\u00f1a y se debi\u00f3 en parte a la acumulaci\u00f3n de capital, el acceso a recursos naturales como el carb\u00f3n y el hierro, y el aumento de la poblaci\u00f3n urbana.&nbsp;: La Primera Revoluci\u00f3nSeguir Leyendo<\/p>\n","protected":false},"author":1210,"featured_media":42681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"no_sidebar_full_width","colormag_page_sidebar_layout":"right_sidebar","footnotes":""},"categories":[30],"tags":[2048,3042,3051,3048,999,3049,613,228],"class_list":["post-42616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-niixer","tag-creatividad","tag-documental","tag-empresarios","tag-hechos-reales","tag-historia","tag-innovacon","tag-mercado","tag-tecnologia-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>causas de la revoluci\u00f3n industrial &#8211; revoluci\u00f3n industrial<\/title>\n<meta name=\"description\" content=\"Para poder comprender las fases del desarrollo en la industria y poder entender la actualidad, debemos conocer la historia y sus movimientos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"causas de la revoluci\u00f3n industrial &#8211; revoluci\u00f3n industrial\" \/>\n<meta property=\"og:description\" content=\"Para poder comprender las fases del desarrollo en la industria y poder entender la actualidad, debemos conocer la historia y sus movimientos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-26T21:03:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-03T17:14:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/09\/1920x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Alejandro Sebastian Daza Sanchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Alejandro Sebastian Daza Sanchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"causas de la revoluci\u00f3n industrial &#8211; revoluci\u00f3n industrial","description":"Para poder comprender las fases del desarrollo en la industria y poder entender la actualidad, debemos conocer la historia y sus movimientos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/","og_locale":"es_ES","og_type":"article","og_title":"causas de la revoluci\u00f3n industrial &#8211; revoluci\u00f3n industrial","og_description":"Para poder comprender las fases del desarrollo en la industria y poder entender la actualidad, debemos conocer la historia y sus movimientos.","og_url":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2023-09-26T21:03:50+00:00","article_modified_time":"2023-10-03T17:14:22+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/09\/1920x1080.jpg","type":"image\/jpeg"}],"author":"Luis Alejandro Sebastian Daza Sanchez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luis Alejandro Sebastian Daza Sanchez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/"},"author":{"name":"Luis Alejandro Sebastian Daza Sanchez","@id":"https:\/\/niixer.com\/#\/schema\/person\/33ee753b9f25fe2c8ad7e6528725da1d"},"headline":"causas de la revoluci\u00f3n industrial","datePublished":"2023-09-26T21:03:50+00:00","dateModified":"2023-10-03T17:14:22+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/"},"wordCount":1189,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/09\/1920x1080.jpg","keywords":["Creatividad","documental","empresarios","hechos reales","Historia","innovac\u00f3n","Mercado","Tecnologia"],"articleSection":["Niixer"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/","url":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/","name":"causas de la revoluci\u00f3n industrial &#8211; revoluci\u00f3n industrial","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/09\/1920x1080.jpg","datePublished":"2023-09-26T21:03:50+00:00","dateModified":"2023-10-03T17:14:22+00:00","description":"Para poder comprender las fases del desarrollo en la industria y poder entender la actualidad, debemos conocer la historia y sus movimientos.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/09\/1920x1080.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/09\/1920x1080.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2023\/09\/26\/revolucion-industrial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"causas de la revoluci\u00f3n industrial"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/33ee753b9f25fe2c8ad7e6528725da1d","name":"Luis Alejandro Sebastian Daza Sanchez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2a5a5ac49e1f667ed084df165b0777d90ce133efe8e0f27d1a69dc1fff477455?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a5a5ac49e1f667ed084df165b0777d90ce133efe8e0f27d1a69dc1fff477455?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a5a5ac49e1f667ed084df165b0777d90ce133efe8e0f27d1a69dc1fff477455?s=96&d=mm&r=g","caption":"Luis Alejandro Sebastian Daza Sanchez"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/ldazas\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/42616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/1210"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=42616"}],"version-history":[{"count":34,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/42616\/revisions"}],"predecessor-version":[{"id":43007,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/42616\/revisions\/43007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/42681"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=42616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=42616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=42616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}