{"id":4031,"date":"2020-11-28T16:36:30","date_gmt":"2020-11-28T21:36:30","guid":{"rendered":"https:\/\/niixer.com\/?p=4031"},"modified":"2020-12-07T08:24:29","modified_gmt":"2020-12-07T13:24:29","slug":"nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/","title":{"rendered":"Nokia anuncia lanzamiento de nuevo Smartphone de gama media"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La firma que alguna vez reino en el mercado de los celulares, quiere volver a imponer su presencia en una \u00e9poca totalmente diferente, es por esto que en la m\u00e1s reciente presentaci\u00f3n virtual por parte de HMD, due\u00f1a de sus derechos, se ha hecho el anuncio oficial del nuevo Nokia 3.4, un celular que tiene muchas novedades por ofrecer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dise\u00f1o del Nokia 3.4<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este terminal mide 160,97 X 75,99 mm, tiene un grosor de 8,7 mm y pesa 180 gr, caracter\u00edsticas propias de un m\u00f3vil dirigido a este mercado, seg\u00fan la empresa, tiene un estilo nordico, reflejando las ra\u00edces de donde es proveniente la marca, con colores vivos y atractivos, es comodo a la mano, adem\u00e1s de ser resistente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pantalla del nuevo Nokia<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva apuesta de la firma finlandesa adapta una pantalla LCD de 6,39 pulgadas con una resoluci\u00f3n HD+ (720 x 1560 pixeles), adem\u00e1s de &nbsp;un ratio 19.5:9, aspectos que lo ponen en un punto medio de calidad de pantalla frente a su competencia en el mercado, pero que innova bastante en comparaci\u00f3n a la generaci\u00f3n que preced\u00eda al 3.4; esta ten\u00eda un <em>notch<\/em> para la c\u00e1mara frontal, pero en esta ocasi\u00f3n, para un mayor aprovechamiento de pantalla, adaptaron una perforaci\u00f3n en la zona superior izquierda, dejando atr\u00e1s el ya obsoleto <em>notch<\/em>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Caracter\u00edsticas del Nokia 3.4<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El coraz\u00f3n de este Smartphone es su procesador Snapdragon 460 de Qualcomm, acompa\u00f1ado de una capacidad de memoria RAM de 3 GB o 4 GB, m\u00e1s una capacidad de almacenamiento de 32 GB o 64 GB, que se pueden ampliar hasta 512 GB con una microSD, apoyados por un sistema operativo Android 10.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A este Smartphone le adaptaron una bater\u00eda de 4000 mAh, que seg\u00fan la p\u00e1gina web, ofrece un uso de hasta 2 d\u00edas, m\u00e1s un lector de huellas trasero como sistema de seguridad; todas estas caracter\u00edsticas hacen este celular un m\u00f3vil decente para la gama media, pero desde HMD se informa, que este es el primer paso para el restablecimiento de Nokia en la industria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>C\u00e1maras<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">HMD quiso adaptar en esta ocasi\u00f3n, un panel de tres c\u00e1maras, en un formato aro, el sensor principal es de 13 megap\u00edxeles, el segundo es un ultra gran angular de 5 megap\u00edxeles, ambos complementados por un sensor de profundidad de 2 megap\u00edxeles, con respecto a la c\u00e1mara frontal incorpora un sensor de 8 megap\u00edxeles; complementado esta acptable resolucion en el apartado fotogr\u00e1fico, el 3.4 adapta una IA que ayuda al usuario a tomar las mejores capturas, tanto con la c\u00e1mara trasera como en la frontal. Adem\u00e1s de agregar reconocimiento facial, como otro sistema de seguridad a parte de la huella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autor:&nbsp;<a href=\"https:\/\/niixer.com\/?s=Andres+Felipe+Avenda%C3%B1o+Junca\">Andr\u00e9s Felipe Avenda\u00f1o Junca<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Editor: Carlos Pinz\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3digo: UUPS-5<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong><\/h3>\n\n\n\n<pre class=\"wp-block-preformatted\">Nokia. (s.f). <em>Nokia 3.4 el \u00fanico dispositivo que necesitar\u00e1s, m\u00e1s tel\u00e9fono, m\u00e1s potencia<\/em>. Nokia. <a href=\"https:\/\/www.nokia.com\/phones\/es_es\/nokia-3-4\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.nokia.com\/phones\/es_es\/nokia-3-4<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Carmona, J. A. (2020). <em>El Nokia 3.4 ya es compatible con ARCore y puede usar los servicios de Google Play para Realidad Aumentada<\/em>. Xataka M\u00f3vil. <a href=\"https:\/\/www.xatakamovil.com\/nokia\/nokia-3-4-compatible-arcore-puede-usar-servicios-google-play-para-ra\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.xatakamovil.com\/nokia\/nokia-3-4-compatible-arcore-puede-usar-servicios-google-play-para-ra<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Notim\u00e9rica. (2020). <em>Ya est\u00e1 disponible en Espa\u00f1a el Nokia 3.4 con triple c\u00e1mara y bater\u00eda con hasta dos d\u00edas de autonom\u00eda por 159 euros<\/em>. Notim\u00e9rica. <a href=\"https:\/\/www.notimerica.com\/ciencia-tecnologia\/noticia-portaltic-ya-disponible-espana-nokia-34-triple-camara-bateria-dos-dias-autonomia-159-euros-20201125161858.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.notimerica.com\/ciencia-tecnologia\/noticia-portaltic-ya-disponible-espana-nokia-34-triple-camara-bateria-dos-dias-autonomia-159-euros-20201125161858.html<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">SmartGSM. (s.f). <em>Nokia 3.4<\/em>. SmartGSM. <a href=\"https:\/\/www.smart-gsm.com\/moviles\/nokia-3-4\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.smart-gsm.com\/moviles\/nokia-3-4<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Sacrist\u00e1n, <em>Nokia 3.4: la gama econ\u00f3mica de Nokia apuesta por la triple c\u00e1mara y la pantalla perforada <\/em>[Imagen]. Xataka Android. <a href=\"https:\/\/www.xatakandroid.com\/moviles-android\/nokia-3-4-caracteristicas-precio-ficha-tecnica\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.xatakandroid.com\/moviles-android\/nokia-3-4-caracteristicas-precio-ficha-tecnica<\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>La firma que alguna vez reino en el mercado de los celulares, quiere volver a imponer su presencia en una \u00e9poca totalmente diferente, es por esto que en la m\u00e1s reciente presentaci\u00f3n virtual por parte de HMD, due\u00f1a de sus derechos, se ha hecho el anuncio oficial del nuevo NokiaSeguir Leyendo<\/p>\n","protected":false},"author":72,"featured_media":4034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[3,34],"tags":[155,99,554,580,432,31],"class_list":["post-4031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-android","category-smartphones","tag-celular","tag-celulares","tag-gama-media","tag-nokia","tag-smartphone","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nokia anuncia lanzamiento de nuevo Smartphone de gama media<\/title>\n<meta name=\"description\" content=\"HMD, due\u00f1a de los derechos de Nokia, ha hecho el anuncio oficial del nuevo Nokia 3.4, un celular que tiene muchas novedades por ofrecer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nokia anuncia lanzamiento de nuevo Smartphone de gama media\" \/>\n<meta property=\"og:description\" content=\"HMD, due\u00f1a de los derechos de Nokia, ha hecho el anuncio oficial del nuevo Nokia 3.4, un celular que tiene muchas novedades por ofrecer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-28T21:36:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-07T13:24:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/169nokia34_2_original.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andres Felipe Avenda\u00f1o Junca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Felipe Avenda\u00f1o Junca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nokia anuncia lanzamiento de nuevo Smartphone de gama media","description":"HMD, due\u00f1a de los derechos de Nokia, ha hecho el anuncio oficial del nuevo Nokia 3.4, un celular que tiene muchas novedades por ofrecer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/","og_locale":"es_ES","og_type":"article","og_title":"Nokia anuncia lanzamiento de nuevo Smartphone de gama media","og_description":"HMD, due\u00f1a de los derechos de Nokia, ha hecho el anuncio oficial del nuevo Nokia 3.4, un celular que tiene muchas novedades por ofrecer.","og_url":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2020-11-28T21:36:30+00:00","article_modified_time":"2020-12-07T13:24:29+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/169nokia34_2_original.jpg","type":"image\/jpeg"}],"author":"Andres Felipe Avenda\u00f1o Junca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Felipe Avenda\u00f1o Junca","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/"},"author":{"name":"Andres Felipe Avenda\u00f1o Junca","@id":"https:\/\/niixer.com\/#\/schema\/person\/2b0bafc50f372f80e7f3cd6d990128cf"},"headline":"Nokia anuncia lanzamiento de nuevo Smartphone de gama media","datePublished":"2020-11-28T21:36:30+00:00","dateModified":"2020-12-07T13:24:29+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/"},"wordCount":477,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/169nokia34_2_original.jpg","keywords":["Celular","Celulares","Gama media","Nokia","Smartphone","tecnolog\u00eda"],"articleSection":["Android","Smartphones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/","url":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/","name":"Nokia anuncia lanzamiento de nuevo Smartphone de gama media","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/169nokia34_2_original.jpg","datePublished":"2020-11-28T21:36:30+00:00","dateModified":"2020-12-07T13:24:29+00:00","description":"HMD, due\u00f1a de los derechos de Nokia, ha hecho el anuncio oficial del nuevo Nokia 3.4, un celular que tiene muchas novedades por ofrecer.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/169nokia34_2_original.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/169nokia34_2_original.jpg","width":800,"height":445,"caption":"Smartphone Nokia 3.4"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/28\/nokia-anuncia-lanzamiento-de-nuevo-smartphone-de-gama-media\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Nokia anuncia lanzamiento de nuevo Smartphone de gama media"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/2b0bafc50f372f80e7f3cd6d990128cf","name":"Andres Felipe Avenda\u00f1o Junca","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","caption":"Andres Felipe Avenda\u00f1o Junca"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/aavendanoju\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/4031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=4031"}],"version-history":[{"count":2,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/4031\/revisions"}],"predecessor-version":[{"id":4931,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/4031\/revisions\/4931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/4034"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=4031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=4031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=4031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}