{"id":39003,"date":"2023-08-08T17:15:20","date_gmt":"2023-08-08T22:15:20","guid":{"rendered":"https:\/\/niixer.com\/?p=39003"},"modified":"2023-08-08T17:15:22","modified_gmt":"2023-08-08T22:15:22","slug":"el-impacto-del-avion-en-la-2da-revolucion-industrial","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/","title":{"rendered":"El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion.png\" alt=\"\" class=\"wp-image-39679\" width=\"425\" height=\"425\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion-150x150.png 150w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion-768x768.png 768w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El invento de los aviones fue una creaci\u00f3n importante e hist\u00f3rica para la humanidad. Durante los tiempos, existieron varios inventores que dise\u00f1aron m\u00e1quinas capaces de volar, como las de Leonardo da Vinci, pero ninguna se construy\u00f3 con \u00e9xito. en 1783, los hermanos franceses Jean Jacques y Jacques \u00c9tienne Montgolfier construyeron un globo de papel lleno de aire caliente, que al ser m\u00e1s liviano que el aire fr\u00edo flotaba, abordo del cual fueron Francois de Rozier y el Marqu\u00e9s de Arlandes, quienes se convirtieron en los primeros seres humanos en volar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">sin embargo, un veh\u00edculo volador que pesaba m\u00e1s que el propio aire, se logr\u00f3 cuando&nbsp;en 1883 el f\u00edsico e inventor John Joseph Montgomery realiz\u00f3 un vuelo controlado con un planeador, creando as\u00ed nuevas posibilidades que no tardaron en explorar otros apasionados al vuelo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer avi\u00f3n propiamente dicho de la historia fue invenci\u00f3n del ingeniero franc\u00e9s Cl\u00e9ment Ader,&nbsp;con el cual logr\u00f3 volar 50 metros en 1890. Eso se repiti\u00f3 en 1892 y 1897, con nuevos dise\u00f1os, a bordo del \u00faltimo de los cuales logr\u00f3 un vuelo de 300 metros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo,&nbsp;reci\u00e9n en 1903 los hermanos Wilbur y Orville Wright lograron el primer vuelo sostenido de un avi\u00f3n impulsado por un motor, un inventor brasile\u00f1o Santos Dumont en 1906 se convirti\u00f3 en el primer ser humano en despegar a bordo de un avi\u00f3n impulsado por un motor aeron\u00e1utico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1les fueron los primeros aviones?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los primeros aviones aut\u00f3nomos comenzaron a existir a finales del siglo XIX, gracias a los adelantos en materia de aerodin\u00e1mica y a las exitosas pruebas de vuelo a bordo de globos aerost\u00e1ticos y planeadores. Los primeros modelos de avi\u00f3n fueron:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>El monoplano de <\/strong><strong>Aleksandr Moizhaisk<\/strong>: el primer avi\u00f3n de la historia creado por un ruso con un motor a vapor la cual le permiti\u00f3 un vuelo de 20 a 30 metros.<\/li>\n\n\n\n<li><strong>El&nbsp;<em>\u00c9ole&nbsp;<\/em><\/strong><strong>de Cl\u00e9ment Ader:<\/strong> fu el primer avi\u00f3n en lograr un vuelo de 50 metros con un motor a vapor, y fue la inspiraci\u00f3n de otros dos modelos de sus inventos, el avi\u00f3n tercero, jam\u00e1s fue capaz de despegar. El primer vuelo del&nbsp;<em>\u00c9ole<\/em>&nbsp;se considera el punto de partida de la aviaci\u00f3n moderna.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El Aer\u00f3dromo de Samuel Pierpont Langley<\/strong>: este avi\u00f3n prototipo&nbsp;<em>Aer\u00f3dromo 5 de un estadounidense <\/em>recorri\u00f3 casi mil metros a una velocidad de unos 40 km\/h, aunque sin tripulantes, e inspir\u00f3 nuevas y m\u00e1s exitosas versiones, como el&nbsp;<em>Aer\u00f3dromo A,<\/em>&nbsp;cuyas versiones mejoradas llevar\u00edan a Glenn Hammond Curtiss a alzar el vuelo en 1910.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><br>\u00b7 El<strong> Flyer creaci\u00f3n de hermanos: <\/strong>El c\u00e9lebre planeador de los hermanos Wright alz\u00f3 el vuelo a unos 48 km\/h, en varios intentos exitosos. Se trataba de un avi\u00f3n biplano, que inicialmente requiri\u00f3 de una catapulta para despegar, hasta que en 1905 logr\u00f3 hacerlo por sus propios medios. En 1910, los modelos m\u00e1s recientes del Flyer lograron el primer vuelo comercial de la historia, recorriendo 100 kil\u00f3metros en una hora, a una velocidad r\u00e9cord de 97 km\/h.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-20-1024x730.png\" alt=\"Los hermanos Wright, Orville y Wilburg experimentando el avi\u00f3n\n\" class=\"wp-image-39642\" width=\"424\" height=\"302\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-20-1024x730.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-20-300x214.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-20-768x548.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-20.png 1280w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00b7 El<strong>&nbsp;<em>14-bis<\/em> brasile\u00f1o: <\/strong>el brasile\u00f1o Alberto Santos Dumont al avi\u00f3n con que realiz\u00f3 un vuelo p\u00fablico en Par\u00eds, en 1906. Su modelo utilizaba un sistema de alabeo similar al de los hermanos Wright, y logr\u00f3 un vuelo de 221 metros sin necesidad de catapultas, ra\u00edles ni otros implementos para el despegue. Despu\u00e9s de estas experiencias, Santos Dumont invent\u00f3 tambi\u00e9n el primer ultraligero.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00b7 El<strong> hidroavi\u00f3n Benoist<\/strong>: Este fue el primer avi\u00f3n en tomar parte en una l\u00ednea a\u00e9rea comercial establecida entre St. Petersburg y Tampa, Florida. Se trataba de un avi\u00f3n biplano con capacidad para el piloto y un \u00fanico pasajero, que viajaba junto al conductor en una cabina abierta.  <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Los Primeros Aviones de la historia - El Primer Vuelo\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/OtWrlZ4zKak?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un sue\u00f1o convertido en realidad<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Durante los siglos XVIII y XIX, naci\u00f3 el primer equipo volador m\u00e1s ligero que el aire, mejor conocido como&nbsp;globo aerost\u00e1tico.<\/strong>&nbsp;Pese a que estos pod\u00edan volar durante m\u00e1s de 20 minutos, era imposible maniobrar con ellos. dio pas\u00f3 a los dirigibles, los cuales s\u00ed se pod\u00edan controlar a trav\u00e9s de mandos y motores. El primer dirigible fue construido por Henri Giffar en 1852.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-25-1024x713.png\" alt=\"Globo aerost\u00e1tico en la actualidad\" class=\"wp-image-39656\" width=\"363\" height=\"253\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-25-1024x713.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-25-300x209.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-25-768x535.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-25-392x272.png 392w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-25-130x90.png 130w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-25.png 1280w\" sizes=\"auto, (max-width: 363px) 100vw, 363px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Comercio de aviones en la guerra<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">los&nbsp;primeros aviones de comercio se realizaron en Estados Unidos, para llevar el correo, entre 1910 y 1911. En Europa, en cambio, fue en 1919 para transportar pasajeros. Durante ese mismo a\u00f1o,&nbsp;<strong>se efectu\u00f3 el primer vuelo <\/strong>trasatl\u00e1ntico con escalas entre Canad\u00e1 e Irlanda, el mismo dur\u00f3 aproximadamente 12 horas. Varios a\u00f1os m\u00e1s tardes, se consigui\u00f3 hacerlo sin escalas,&nbsp;por lo cual, el avi\u00f3n pronto se convertir\u00eda en el transporte estrella.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Primera Guerra Mundial, pese a la tragedia humana, trajo grandes avances en cuestiones a\u00e9reas, siendo uno de ellos, el descubrimiento de que la h\u00e9lice les limitaba en velocidad. Los alemanes, por ejemplo, crearon el caza Fokker Dr. I un triplano, mientras que los brit\u00e1nicos crearon un avi\u00f3n de combate, el Sopwith Camel, de un solo asiento. Este prototipo se convirti\u00f3 en uno de los aviones de cazas m\u00e1s populares, as\u00ed como uno de los m\u00e1s emblem\u00e1ticos de la \u00e9poca.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-27-1024x642.png\" alt=\"Comercio de aviones entre pa\u00edses  \" class=\"wp-image-39661\" width=\"494\" height=\"310\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-27-1024x642.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-27-300x188.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-27-768x481.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-27.png 1280w\" sizes=\"auto, (max-width: 494px) 100vw, 494px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Panel de control<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">son unos dispositivos mec\u00e1nicos o electr\u00f3nicos que le permiten al piloto saber a que altura esta, su rumbo, el ritmo del avi\u00f3n, el ascenso o descenso y el estado de los sistemas del avi\u00f3n durante el vuelo entre otras <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-26-1024x681.png\" alt=\"Uno de los primero paneles de control de un avi\u00f3n\" class=\"wp-image-39659\" width=\"533\" height=\"354\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-26-1024x681.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-26-300x199.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-26-768x511.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/image-26.png 1280w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor<\/strong>: Iv\u00e1n Esteban Suarez Moreno<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor<\/strong>: Carlos Iv\u00e1n Pinz\u00f3n Romero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo<\/strong>: 4RIARVR-10<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Colegio<\/strong>: T\u00e9cnico Distrital Paulo Freire<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad<\/strong>: Universidad Central<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong><\/h3>\n\n\n\n<pre class=\"wp-block-preformatted\">Documentales Completos en Espa\u00f1ol 2.0.(28 de enero 2015).<em>Los Primeros Aviones de la historia - El Primer Vuelo<\/em>[Video]. YouTube.<a href=\"https:\/\/www.youtube.com\/watch?v=OtWrlZ4zKak\">https:\/\/www.youtube.com\/watch?v=OtWrlZ4zKak<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">FRANCISCO MAR\u00cdA.(2022).<em>La evoluci\u00f3n del avi\u00f3n a lo largo de la historia<\/em>.OKdiario.<a href=\"https:\/\/okdiario.com\/historia\/evolucion-del-avion-lo-largo-historia-9557534\">https:\/\/okdiario.com\/historia\/evolucion-del-avion-lo-largo-historia-9557534<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">CurioSfera-Historia.com.(2018).<em>Origen del avi\u00f3n y de la aviaci\u00f3n<\/em>.CurioSfera-Historia.<a href=\"https:\/\/curiosfera-historia.com\/historia-de-la-aviacion\/\">https:\/\/curiosfera-historia.com\/historia-de-la-aviacion\/<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">WIKIlmages.(2012).<em>invention-60529_1280<\/em>.[Fotografia]. Pixabay.\n<a href=\"https:\/\/pixabay.com\/es\/photos\/invenci%C3%B3n-hermanos-wright-avi%C3%B3n-60529\/\">https:\/\/pixabay.com\/es\/photos\/invenci%C3%B3n-hermanos-wright-avi%C3%B3n-60529\/<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Nicolae_Balt.(2021).<em>hot-air-balloon-5979187_1280<\/em>.[Fotografia]. Pixabay.\n<a href=\"https:\/\/pixabay.com\/es\/photos\/globo-aerost%C3%A1tico-ballon-globo-5979187\/\">https:\/\/pixabay.com\/es\/photos\/globo-aerost%C3%A1tico-ballon-globo-5979187\/<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Tumisu.(2018).logistics-3382013_1280.[Fotografia]. Pixabay.\n<a href=\"https:\/\/pixabay.com\/es\/photos\/log%C3%ADstica-cami%C3%B3n-envase-avi%C3%B3n-3382013\/\">https:\/\/pixabay.com\/es\/photos\/log%C3%ADstica-cami%C3%B3n-envase-avi%C3%B3n-3382013\/<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Grayboy58.(2017).cockpit-2396223_1280.[fotografia]. Pixabay.\n<a href=\"https:\/\/pixabay.com\/es\/photos\/cabina-aviones-de-cabina-aeronave-2396223\/\">https:\/\/pixabay.com\/es\/photos\/cabina-aviones-de-cabina-aeronave-2396223\/<\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>El invento de los aviones fue una creaci\u00f3n importante e hist\u00f3rica para la humanidad. Durante los tiempos, existieron varios inventores que dise\u00f1aron m\u00e1quinas capaces de volar, como las de Leonardo da Vinci, pero ninguna se construy\u00f3 con \u00e9xito. en 1783, los hermanos franceses Jean Jacques y Jacques \u00c9tienne Montgolfier construyeronSeguir Leyendo<\/p>\n","protected":false},"author":1064,"featured_media":39681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[30],"tags":[],"class_list":["post-39003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-niixer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos<\/title>\n<meta name=\"description\" content=\"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"og:description\" content=\"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-08T22:15:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-08T22:15:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ivan Suarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ivan Suarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/","og_locale":"es_ES","og_type":"article","og_title":"El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","og_description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial","og_url":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2023-08-08T22:15:20+00:00","article_modified_time":"2023-08-08T22:15:22+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion-1.png","type":"image\/png"}],"author":"ivan Suarez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ivan Suarez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/"},"author":{"name":"ivan Suarez","@id":"https:\/\/niixer.com\/#\/schema\/person\/1961359452b31f21244ca9daf1957827"},"headline":"El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial","datePublished":"2023-08-08T22:15:20+00:00","dateModified":"2023-08-08T22:15:22+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/"},"wordCount":984,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion-1.png","articleSection":["Niixer"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/","url":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/","name":"El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion-1.png","datePublished":"2023-08-08T22:15:20+00:00","dateModified":"2023-08-08T22:15:22+00:00","description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/08\/primer-avion-1.png","width":1024,"height":1024,"caption":"primer avi\u00f3n de los hermanos Wright, Orville y Wilburg"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2023\/08\/08\/el-impacto-del-avion-en-la-2da-revolucion-industrial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"El impacto del avi\u00f3n en la 2da revoluci\u00f3n industrial"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/1961359452b31f21244ca9daf1957827","name":"ivan Suarez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/cf6cd3685bcf48f3d20249c45ac780f472bdb4654af07fe64f47a7bba76a4035?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf6cd3685bcf48f3d20249c45ac780f472bdb4654af07fe64f47a7bba76a4035?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf6cd3685bcf48f3d20249c45ac780f472bdb4654af07fe64f47a7bba76a4035?s=96&d=mm&r=g","caption":"ivan Suarez"},"url":"https:\/\/niixer.com\/index.php\/author\/ivan-suarez\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/39003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/1064"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=39003"}],"version-history":[{"count":3,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/39003\/revisions"}],"predecessor-version":[{"id":39682,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/39003\/revisions\/39682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/39681"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=39003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=39003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=39003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}