{"id":38016,"date":"2023-05-23T17:04:29","date_gmt":"2023-05-23T22:04:29","guid":{"rendered":"https:\/\/niixer.com\/?p=38016"},"modified":"2023-05-24T16:08:45","modified_gmt":"2023-05-24T21:08:45","slug":"blender-creacion-3d-y-sus-peliculas-en-el-cine","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/","title":{"rendered":"Blender: creaci\u00f3n 3D y sus pel\u00edculas en el cine."},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1-1024x576.jpg\" alt=\"\" class=\"wp-image-38027\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1-1024x576.jpg 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1-300x169.jpg 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1-768x432.jpg 768w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Imagen 1. <a href=\"https:\/\/niixer.com\/index.php\/2022\/04\/29\/secuencia-de-animaciones-con-mixamo-y-blender\/\">Blender<\/a> creaci\u00f3n 3D. Tomado de:&nbsp;<a href=\"https:\/\/i.ytimg.com\/vi\/cazrI0QU3yw\/maxresdefault.jpg\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/i.ytimg.com\/vi\/cazrI0QU3yw\/maxresdefault.jpg<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es blender?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Blender se considera como una suite de creaci\u00f3n <a href=\"https:\/\/niixer.com\/index.php\/2022\/05\/21\/3d-y-realidad-virtual-wordpress\/\">3D<\/a> gratuita y de c\u00f3digo abierto. Que permite animar objetos en 3D y crear pel\u00edculas. Este programa puede ser ejecutado en sistemas como Linux, macOS y\/o Windows. Este software se adapta muy bien a las personas y estudios peque\u00f1os que se benefician al ser f\u00e1cilmente entendible y con un proceso altamente receptivo. Blender (2021)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Blender tiene una alta variedad de herramientas que se adaptan casi a cualquier tipo de persona. Tanto los especializados como aquellos que a penas van empezando en el mundo 3D.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Funciones y caracter\u00edsticas de <a href=\"https:\/\/niixer.com\/index.php\/2022\/04\/29\/creacion-de-cinematicas-en-blender\/\">Blender<\/a><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro del paquete de creaci\u00f3n de blender se puede tener herramientas para Modelado, Manipulaci\u00f3n, animaci\u00f3n, simulaci\u00f3n, renderizado, composici\u00f3n y seguimiento de movimiento, edici\u00f3n de video y tuber\u00eda de animaci\u00f3n 2D.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Modelado y escultura 3D.<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para la creaci\u00f3n de distintas figuras que pueden conformar la pel\u00edcula. Se encuentra el modelado que funciona a trav\u00e9s de distinto pol\u00edgonos donde se construyen objetos a partir de superficies individuales. Esto se conoce como modelado en mallas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra opci\u00f3n de modelado es basada en curvas que se base en dibujar l\u00edneas estructurales en gu\u00eda que luego ser\u00e1n usadas para generar mallas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de esculpir se usa para empujar o tirar las mallas de distintas maneras. Funciona muy bien para pol\u00edgonos con el fin de crear objetos m\u00e1s detallados y texturizados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Texturizado y desenvolvimiento UV<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de este m\u00f3dulo se permite dar al modelado texturas y materiales creando una variedad de apariencias en los objetos. Lo que busca el desenvolvimiento es aplanar la superficie del modelo para pintar con una propia textura y de esta manera, ajustar la opacidad, reflejo de la luz entre otras.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Montaje y animaci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Blender permite animar los modelos realizados a trav\u00e9s de l\u00edneas de tiempo y se denomina m\u00e9todo stop-motion. El cual crea puntos en la l\u00ednea de tiempo de la animaci\u00f3n y de esta manera algo se mover\u00e1 del punto A al B.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para animar elementos m\u00e1s complejos se usar\u00e1 la herramienta manipulaci\u00f3n, que permitir\u00e1 que el modelo se mueva exactamente como se desea. Ya luego Blender podr\u00e1 completar el movimiento entre fotograf\u00edas claves creando la pose inicial y la final.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/blender-2.png\" alt=\"\" class=\"wp-image-38028\" width=\"1134\" height=\"756\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/blender-2.png 840w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/blender-2-300x200.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/blender-2-768x512.png 768w\" sizes=\"auto, (max-width: 1134px) 100vw, 1134px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Imagen 2. Corto Blender. Tomado de:&nbsp;<a href=\"https:\/\/i.blogs.es\/12d22e\/nuevo-blender\/840_560.png\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/i.blog<\/a><a href=\"https:\/\/i.blogs.es\/12d22e\/nuevo-blender\/840_560.png\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\">s.es\/12d22e\/nuevo-blender\/840_560.png<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pel\u00edculas creadas con Blender<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los casos de \u00e9xitos ha sido la pel\u00edcula Cosmos Laundromat dirigida por Mathieu Auvray y patrocinada por el proyecto Blender, y la cual fue premiada en el SIGGRAPH 2016 con el Premio del Jurado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llega a la plataforma de Netflix Next Gen pel\u00edcula creada completamente en blender, esta pel\u00edcula es una adaptaci\u00f3n del comic 7723 de Wang Nima y cuenta la historia entre una chica rebelde y un robot secreto quienes crean una grandiosa amistad y permitir\u00e1 cautivar al p\u00fablico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Blender and Next Gen: a Netflix Original\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/iZn3kCsw5D8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">https:\/\/www.youtube.com\/watch?v=iZn3kCsw5D8<\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Blender (2023). Introducci\u00f3n.https:\/\/docs.blender.org\/manual\/es\/dev\/getting_started\/about\/introduction.html<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Offidocs (s.f).Funciones y caracter\u00edsticas de Blender 3D. https:\/\/www.offidocs.com\/es\/index.php\/main-quick-links\/121049-blender-online-3d-movies-creation-suite<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cortes J.(2022). Next Gen | La Nueva Generaci\u00f3n \u2013 La nueva Pelicula de Animaci\u00f3n de Netflix hecha en BLENDER. Notodoanimacion.es. https:\/\/www.notodoanimacion.es\/next-gen-la-nueva-generacion-la-nueva-pelicula-de-animacion-de-netflix\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/lamiradadelreplicante.com\/author\/tannhausser\/\">Tannhausser<\/a>. (2016). Pel\u00edcula hecha con Blender premiada en el SIGGRAPH 2016.&nbsp;https:\/\/lamiradadelreplicante.com\/2016\/07\/09\/pelicula-hecha-con-blender-premiada-en-el-siggraph-2016\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Blender.(2018). Blender and Next Gen: a Netflix Original [Video]. YouTube. https:\/\/www.youtube.com\/watch?v=iZn3kCsw5D8<a href=\"https:\/\/www.notodoanimacion.es\/\"><\/a><\/p>\n<cite>3<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Autor:&nbsp;Angie Milena Archila Martinez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Editor: Carlos Iv\u00e1n Pinz\u00f3n Romero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3digo: UCRV-8<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad:&nbsp;<a href=\"https:\/\/www.ucentral.edu.co\/\">Universidad Central<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagen 1. Blender creaci\u00f3n 3D. Tomado de:&nbsp;https:\/\/i.ytimg.com\/vi\/cazrI0QU3yw\/maxresdefault.jpg \u00bfQu\u00e9 es blender? Blender se considera como una suite de creaci\u00f3n 3D gratuita y de c\u00f3digo abierto. Que permite animar objetos en 3D y crear pel\u00edculas. Este programa puede ser ejecutado en sistemas como Linux, macOS y\/o Windows. Este software se adapta muySeguir Leyendo<\/p>\n","protected":false},"author":580,"featured_media":38027,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1938],"tags":[1310,228],"class_list":["post-38016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blender","tag-blender-3d","tag-tecnologia-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blender: creaci\u00f3n 3D y sus pel\u00edculas en el cine. &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos<\/title>\n<meta name=\"description\" content=\"Blender se considera como una suite de creaci\u00f3n 3D gratuita y de c\u00f3digo abierto. Que permite animar objetos en 3D y crear pel\u00edculas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blender: creaci\u00f3n 3D y sus pel\u00edculas en el cine. &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"og:description\" content=\"Blender se considera como una suite de creaci\u00f3n 3D gratuita y de c\u00f3digo abierto. Que permite animar objetos en 3D y crear pel\u00edculas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-23T22:04:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-24T21:08:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aarchila\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aarchila\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blender: creaci\u00f3n 3D y sus pel\u00edculas en el cine. &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","description":"Blender se considera como una suite de creaci\u00f3n 3D gratuita y de c\u00f3digo abierto. Que permite animar objetos en 3D y crear pel\u00edculas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/","og_locale":"es_ES","og_type":"article","og_title":"Blender: creaci\u00f3n 3D y sus pel\u00edculas en el cine. &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","og_description":"Blender se considera como una suite de creaci\u00f3n 3D gratuita y de c\u00f3digo abierto. Que permite animar objetos en 3D y crear pel\u00edculas.","og_url":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2023-05-23T22:04:29+00:00","article_modified_time":"2023-05-24T21:08:45+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1.jpg","type":"image\/jpeg"}],"author":"aarchila","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aarchila","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/"},"author":{"name":"aarchila","@id":"https:\/\/niixer.com\/#\/schema\/person\/eabddcc7e24d462fbc8ae5ac65df8363"},"headline":"Blender: creaci\u00f3n 3D y sus pel\u00edculas en el cine.","datePublished":"2023-05-23T22:04:29+00:00","dateModified":"2023-05-24T21:08:45+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/"},"wordCount":666,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1.jpg","keywords":["Blender 3D","Tecnologia"],"articleSection":["Blender"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/","url":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/","name":"Blender: creaci\u00f3n 3D y sus pel\u00edculas en el cine. &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1.jpg","datePublished":"2023-05-23T22:04:29+00:00","dateModified":"2023-05-24T21:08:45+00:00","description":"Blender se considera como una suite de creaci\u00f3n 3D gratuita y de c\u00f3digo abierto. Que permite animar objetos en 3D y crear pel\u00edculas.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/05\/BLENDER-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2023\/05\/23\/blender-creacion-3d-y-sus-peliculas-en-el-cine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Blender: creaci\u00f3n 3D y sus pel\u00edculas en el cine."}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/eabddcc7e24d462fbc8ae5ac65df8363","name":"aarchila","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0fc97653bb3d919763a86704ca03c7b792ee574bd7595f78c8ce7403ec8df2e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0fc97653bb3d919763a86704ca03c7b792ee574bd7595f78c8ce7403ec8df2e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0fc97653bb3d919763a86704ca03c7b792ee574bd7595f78c8ce7403ec8df2e9?s=96&d=mm&r=g","caption":"aarchila"},"url":"https:\/\/niixer.com\/index.php\/author\/aarchila\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/38016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/580"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=38016"}],"version-history":[{"count":3,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/38016\/revisions"}],"predecessor-version":[{"id":38089,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/38016\/revisions\/38089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/38027"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=38016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=38016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=38016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}