{"id":36150,"date":"2023-03-21T16:11:57","date_gmt":"2023-03-21T21:11:57","guid":{"rendered":"https:\/\/niixer.com\/?p=36150"},"modified":"2023-03-21T17:24:36","modified_gmt":"2023-03-21T22:24:36","slug":"tipos-de-drones-y-su-clasificacion","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/","title":{"rendered":"Tipos de drones y su Clasificaci\u00f3n"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Que son los drones <\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los drones son como un <a href=\"https:\/\/niixer.com\/?s=vehiculo\">veh\u00edculo <\/a>que se maneja por un control remoto, que para ascender se usa la fuerza de giro de sus motores unidos a las<a href=\"https:\/\/niixer.com\/?s=helices\"> h\u00e9lices<\/a>, varios reciben el nombre de Cuadricopteros, sexacopteros u octracopteros, dependiendo de los drones si tienen 4,6 o 8 h\u00e9lices. \u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Origen de los drones<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El origen de los drones se da a inicios del siglo XIX, el primer acontecimiento el precursor del dron se us\u00f3 como blanco de pr\u00e1ctica para las<a href=\"https:\/\/niixer.com\/?s=fuerzas+militares\"> fuerzas militares<\/a> a principios del siglo XX.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En segundo lugar, fue en el periodo de entreguerra y en la segunda guerra mundial, que el avi\u00f3n no tripulado o sea el dron era utilizado para ser una especie de bomba volante que era enviado a trav\u00e9s de las l\u00edneas enemigas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>C\u00f3mo funciona un dron<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEl funcionamiento de los drones es b\u00e1sicamente el mismo que el de un avi\u00f3n o un helic\u00f3ptero. Se ponen en marcha los motores y las aletas se mueven para posibilitar el vuelo. Despu\u00e9s, con los mandos de control se va dirigiendo el vuelo, que depender\u00e1 en gran medida de los conocimientos y la pericia del piloto.\u201d <\/em><strong><em>(Tecnolog\u00eda, 2023)<\/em><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1les son los usos de los drones ?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cTambi\u00e9n se puede hacer una clasificaci\u00f3n de los tipos de drones seg\u00fan el uso que se les d\u00e9. Estos veh\u00edculos no tripulados pueden ser usados con fines recreaciones les , comerciales, de servicio o de seguridad.&nbsp; Por tanto, seg\u00fan sean los tipos de drones y sus caracter\u00edsticas, los usos m\u00e1s comunes pueden ser los siguientes:\u201d<strong> (Umiles, 2023)<\/strong><\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Drones de uso particular, son aquellos utilizados como elementos de entretenimiento para j\u00f3venes y adultos, estos tambi\u00e9n son utilizados con fines comerciales, para realizar tomas en altitud de paisajes, grabaciones de eventos, comerciales, ETC..<\/li>\n\n\n\n<li>&nbsp;Tambi\u00e9n son usados en el tema del periodismo para hacer grabaciones de sucesos en el lugar del acontecimiento.<\/li>\n\n\n\n<li>Se utiliza tambi\u00e9n para el \u00e1mbito geogr\u00e1fico para realizar tomas a <a href=\"https:\/\/niixer.com\/?s=terrenos\">terrenos<\/a> y espacios con caracter\u00edsticas diversas, en el \u00e1rea de la topograf\u00eda se ha implementado para hacer mediciones desde las alturas de la planimetr\u00eda y altimetr\u00eda de los lugares.<\/li>\n\n\n\n<li>Otros de los usos cotidianos que se utiliza en un dron es para tareas de seguridad, como el dron de vigilancia Saturno.<\/li>\n\n\n\n<li>En varios sitios los drones son utilizados para realizar env\u00edos de mercanc\u00eda.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/funcionamiento-tipos-y-usos-de-drones-1.jpg\" alt=\"Drones y su clasificaci\u00f3n\" class=\"wp-image-36341\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/funcionamiento-tipos-y-usos-de-drones-1.jpg 800w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/funcionamiento-tipos-y-usos-de-drones-1-300x150.jpg 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/funcionamiento-tipos-y-usos-de-drones-1-768x384.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Clasificaci\u00f3n seg\u00fan la normatividad de los drones<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La clasificaci\u00f3n de los drones se basa de acuerdo a la normativa vigente, que es dictaminado por<a href=\"https:\/\/es.wikipedia.org\/wiki\/Agencia_Europea_de_Seguridad_A%C3%A9rea\"> EASA<\/a> que significa (Agencia de la uni\u00f3n europea para la seguridad a\u00e9rea), existen 6 clases de drones. que se clasifican en relaci\u00f3n a su masa m\u00e1xima al despegue o MTOW (Peso m\u00e1ximo al despegue), pero tambi\u00e9n deben cumplir ciertas caracter\u00edsticas que deben cumplir los drones para ser considerado dentro de cada categor\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro de las categor\u00edas de drones establecidas que encontramos en los reglamentos, se enumeran las clases que inician desde C0 hasta C6.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/image-286.png\" alt=\"enumeracion \" class=\"wp-image-36153\" width=\"524\" height=\"215\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/image-286.png 451w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/image-286-300x123.png 300w\" sizes=\"auto, (max-width: 524px) 100vw, 524px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las categor\u00edas para los tipos de drones se enumeran a continuaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de drones C0<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los drones que se encuentran dentro de la categor\u00eda clase C0 deben cumplir con los siguientes requisitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>\u201cSu peso o <a href=\"https:\/\/dle.rae.es\/masa\">masa<\/a> m\u00e1xima al despegue (<a href=\"https:\/\/niixer.com\/?s=mtow\">MTOW<\/a>) no puede ser superior a 250g<\/em><\/li>\n\n\n\n<li><em>La velocidad de vuelo no puede ser superior a 19 m\/s.<\/em><\/li>\n\n\n\n<li><em>Deben estar dise\u00f1ados para evitar causar da\u00f1os en las personas y deben poder controlarse de manera segura<\/em><\/li>\n\n\n\n<li><em>Deben ser comercializados con las instrucciones de uso del fabricante.\u201d <strong>(Umiles, 2023)<\/strong><\/em><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de drones C1<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los drones que se encuentran dentro de la categor\u00eda clase C1 deben cumplir con los siguientes requisitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>\u201cSu peso o MTOW debe ser menor a 900 g, pero superior a 250 gr.<\/em><\/li>\n\n\n\n<li><em>Su energ\u00eda de impacto no puede superar los 80 julios.<\/em><\/li>\n\n\n\n<li><em>La velocidad de vuelo que alcance no puede superar los 19 metros por segundo.<\/em><\/li>\n\n\n\n<li><em>Deben contar con sistema de geo consciencia.<\/em><\/li>\n\n\n\n<li><em>Deben estar equipados con sistema de recuperaci\u00f3n de forma segura en caso de desconexi\u00f3n de la <a href=\"https:\/\/dle.rae.es\/se%C3%B1al\">se\u00f1al <\/a>o p\u00e9rdida.<\/em><\/li>\n\n\n\n<li><em>Es necesario que cuenten con identificaci\u00f3n a distancia.<\/em><\/li>\n\n\n\n<li><em>Deben estar marcados con un n\u00famero de serie \u00fanico en f\u00edsico.<\/em><\/li>\n\n\n\n<li><em>Deben estar equipados con luces para poder ser visualizados de noche.<\/em><\/li>\n\n\n\n<li><em>Su dise\u00f1o debe ser desarrollado de tal manera que se pueda evitar causar da\u00f1os en las personas.<\/em><\/li>\n\n\n\n<li><em>Deben ser controlados de manera segura.<\/em><\/li>\n\n\n\n<li><em>Su comercializaci\u00f3n debe realizarse con las instrucciones de uso del fabricante.\u201d <strong>(Umiles, 2023)<\/strong><\/em><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de drones C2<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los drones que se encuentran dentro de la categor\u00eda clase C2 deben cumplir con los siguientes requisitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>\u201cSu peso o <a href=\"https:\/\/niixer.com\/?s=mtow\">MTOW<\/a> no debe superar los 4 kg.<\/em><\/li>\n\n\n\n<li><em>Deben estar equipados con una funci\u00f3n de baja velocidad, con un l\u00edmite menor a 3 m\/s.<\/em><\/li>\n\n\n\n<li><em>Deben estar equipados con sistema de geo consciencia.<\/em><\/li>\n\n\n\n<li><em>En su estructura deben estar marcados con un n\u00famero de serie f\u00edsico y \u00fanico.<\/em><\/li>\n\n\n\n<li><em>Deben contar con sistema de identificaci\u00f3n a distancia.<\/em><\/li>\n\n\n\n<li><em>Es necesario que cuenten con un enlace de datos protegido ante interferencias.<\/em><\/li>\n\n\n\n<li><em>Deben contar con un sistema de seguridad para finalizar el vuelo y recuperar el dron en caso de p\u00e9rdida o desconexi\u00f3n.<\/em><\/li>\n\n\n\n<li><em>Es indispensable que est\u00e9n equipados con sistema de iluminaci\u00f3n para la visibilidad nocturna.<\/em><\/li>\n\n\n\n<li><em>Su dise\u00f1o debe ser desarrollado para evitar causar da\u00f1os a las personas.<\/em><\/li>\n\n\n\n<li><em>Deben poder manejarse de manera segura.<\/em><\/li>\n\n\n\n<li><em>Para su comercializaci\u00f3n se debe incluir el manual de instrucciones del fabricante.\u201d <strong>(Umiles, 2023)<\/strong><\/em><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de drones C3<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los drones que se encuentran dentro de la categor\u00eda clase C3 deben cumplir con los siguientes requisitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Su peso o MTOW no debe sobrepasar los 25 kg.<\/li>\n\n\n\n<li>Su magnitud m\u00e1s larga no debe exceder los 3 metros de longitud.<\/li>\n\n\n\n<li>Debe ser regulado con sistema de <a href=\"https:\/\/www.hispadrones.com\/normativa\/reglas-pilotar\/union-europea\/reglas-pilotar-drones-ue\/\">geo consciencia<\/a>.<\/li>\n\n\n\n<li>Debe contar con enlace de datos protegido ante interferencias.<\/li>\n\n\n\n<li>Es necesario que cuente con un sistema de finalizaci\u00f3n de vuelo o de recuperaci\u00f3n de la conexi\u00f3n en caso de p\u00e9rdida.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de drones C4<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de la categor\u00eda C4 se incluyen los drones que cumplan con las siguientes caracter\u00edsticas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Que su peso sea inferior a 25 kg.<\/li>\n\n\n\n<li>Su dominio no es de manera segura.<\/li>\n\n\n\n<li>Este no dispone de modo de vuelo autom\u00e1tico,<\/li>\n\n\n\n<li>Su venta debe incluir el manual de instrucciones.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de drones C5<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los drones que se encuentran en esta categor\u00eda llamada C5 se deben contemplar los siguientes aspectos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Su peso o MTOW debe ser por debajo de los 25 kg.<\/li>\n\n\n\n<li>Debe dar informaci\u00f3n clara sobre la altitud del vuelo.<\/li>\n\n\n\n<li>Cuenta con sistema de <a href=\"https:\/\/www3.gobiernodecanarias.org\/medusa\/edublog\/ieslasveredillas\/wp-content\/uploads\/sites\/82\/2014\/11\/la-velocidad.pdf\">velocidad<\/a> baja que no sobrepase los 5 m\/s.<\/li>\n\n\n\n<li>Tiene sistema de geo consciencia.<\/li>\n\n\n\n<li>Cuenta con sistema de aviso de bater\u00eda baja.<\/li>\n\n\n\n<li>Tiene un sistema de luces nocturnas.<\/li>\n\n\n\n<li>Cuenta con un sistema de aterrizaje seguro en caso de desconexi\u00f3n del enlace.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de drones C6<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En la \u00faltima clase denominada clase C6 se deben tener en cuenta los siguientes par\u00e1metros:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>\u201cSu peso o MTOW no debe superar los 25 kg.<\/em><\/li>\n\n\n\n<li><em>Debe contar con un sistema de informaci\u00f3n clara sobre los datos de altitud del vuelo, que evite que el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Veh%C3%ADculo_a%C3%A9reo_no_tripulado\">dron<\/a> supere los l\u00edmites.<\/em><\/li>\n\n\n\n<li><em>La velocidad m\u00e1xima horizontal permitida ser\u00e1 de 50 m\/s en relaci\u00f3n al suelo.<\/em><\/li>\n\n\n\n<li><em>Debe contar con un sistema de recuperaci\u00f3n y aterrizaje seguro en caso de que se pierda el enlace con el mando.<\/em><\/li>\n\n\n\n<li><em>Es necesario que cuente con enlace de datos protegidos para evitar accesos no autorizados.<\/em><\/li>\n\n\n\n<li><em>Debe contar con un n\u00famero de identificaci\u00f3n \u00fanico marcado en su superficie.<\/em><\/li>\n\n\n\n<li><em>Debe contar con sistema de identificaci\u00f3n a distancia.<\/em><\/li>\n\n\n\n<li><em>Tambi\u00e9n debe contar con sistema de geo consciencia.<\/em><\/li>\n\n\n\n<li><em>Es necesario que cuente con sistema de notificaci\u00f3n de bater\u00eda baja.<\/em><\/li>\n\n\n\n<li><em>En caso de que incorpore sistema de limitaci\u00f3n de vuelo, es necesario que posea un sistema de notificaci\u00f3n al piloto de tal limitante.<\/em><\/li>\n\n\n\n<li><em>Debe contar con <a href=\"https:\/\/niixer.com\/?s=sistema\">sistema<\/a> de luces de control para vuelos nocturnos.\u201d<strong>(Umiles, 2023)<\/strong><\/em><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/image-287.png\" alt=\"tipos de dron\" class=\"wp-image-36163\" width=\"528\" height=\"291\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/image-287.png 452w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/image-287-300x165.png 300w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Video de apoyo<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"DRONES: Funcionamiento, tipos y usos (en Espa\u00f1ol)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/i82wD4wIgho?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor:<\/strong> <a href=\"https:\/\/niixer.com\/?s=Bryan+Camilo+Garavito+Cifuentes\">Bryan Camilo Garavito Cifuentes<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor:<\/strong> <a href=\"https:\/\/niixer.com\/?s=Carlos+Iv%C3%A1n+Pinz%C3%B3n\">Carlos Iv\u00e1n Pinz\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo:<\/strong> <a href=\"https:\/\/niixer.com\/?s=UCPSG6-1\">UCPSG6-1<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad:<\/strong> <a href=\"https:\/\/niixer.com\/?s=Universidad+Central+\">Universidad Central <\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Fuentes:<\/strong><\/h4>\n\n\n\n<pre class=\"wp-block-preformatted\">UMILES. (2022). <em>Tipos de Drones. Clasificaci\u00f3n por uso y caracter\u00edsticas<\/em>. UMILES Group. <a href=\"https:\/\/umilesgroup.com\/tipos-de-drones\/\">https:\/\/umilesgroup.com\/tipos-de-drones\/\n<\/a>\nEquipo de Expertos en Ciencia y Tecnolog\u00eda. (2018). <em>\u00bfQu\u00e9 es un dron y c\u00f3mo funciona?<\/em>. VIU. <a href=\"https:\/\/www.universidadviu.com\/int\/actualidad\/nuestros-expertos\/que-es-un-dron-y-como-funciona\">https:\/\/www.universidadviu.com\/int\/actualidad\/nuestros-expertos\/que-es-un-dron-y-como-funciona<\/a>\n\nFast Track Aviation.(2022). Todo sobre Drones: su funcionamiento, tipos y usos. Fast Track Aviation. <a href=\"https:\/\/www.ftaviation.com.co\/funcionamiento-tipos-y-usos-de-drones\/\">https:\/\/www.ftaviation.com.co\/funcionamiento-tipos-y-usos-de-drones\/<\/a>\n\nDrone con c\u00e1mara 4k. (2022, 3 febrero). Shopee. Recuperado 21 de marzo de 2023, de <a href=\"https:\/\/shopee.com.co\/mini-drone-Con-C%C3%A1mara-4K-E99-pro-K3-Evitaci%C3%B3n-De-Obst%C3%A1culos-2.4G-control-Remoto-Plegable-360-Flip-Sin-Cabeza-Modo-Ni%C3%B1os-drones-i.804891235.18748835268\">https:\/\/shopee.com.co\/mini-drone-Con-C%C3%A1mara-4K-E99-pro-K3-Evitaci%C3%B3n-De-Obst%C3%A1culos-2.4G-control-Remoto-Plegable-360-Flip-Sin-Cabeza-Modo-Ni%C3%B1os-drones-i.804891235.18748835268<\/a>\n\nE. (2019, 7 julio). Historia de los drones. El Drone. <a href=\"http:\/\/eldrone.es\/historia-de-los-drones\/\">http:\/\/eldrone.es\/historia-de-los-drones\/<\/a>\n\nTecnonauta. (30 de julio de 2014). <em>DRONES: Funcionamiento, tipos y usos (en Espa\u00f1ol)<\/em> [Video]. YouTube. <a href=\"https:\/\/youtu.be\/i82wD4wIgho\">https:\/\/youtu.be\/i82wD4wIgho<\/a> \n\nFast Track Aviation. (2022). <em>Todo sobre Drones: su funcionamiento, tipos y usos<\/em> [Imagen]. Fast Track Aviation. <a href=\"https:\/\/www.ftaviation.com.co\/funcionamiento-tipos-y-usos-de-drones\/\">https:\/\/www.ftaviation.com.co\/funcionamiento-tipos-y-usos-de-drones\/<\/a> <\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que son los drones Los drones son como un veh\u00edculo que se maneja por un control remoto, que para ascender se usa la fuerza de giro de sus motores unidos a las h\u00e9lices, varios reciben el nombre de Cuadricopteros, sexacopteros u octracopteros, dependiendo de los drones si tienen 4,6 oSeguir Leyendo<\/p>\n","protected":false},"author":945,"featured_media":36204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2640],"tags":[157,2399,581,582,31],"class_list":["post-36150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-drones","tag-camara-2","tag-camara4k","tag-drone","tag-drones","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Drones y su clasificaci\u00f3n &#8211; Tipos de drones<\/title>\n<meta name=\"description\" content=\"Un dron es un veh\u00edculo que se maneja por un control remoto, que para ascender se usa la fuerza de giro de sus motores unidos a las h\u00e9lices.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drones y su clasificaci\u00f3n &#8211; Tipos de drones\" \/>\n<meta property=\"og:description\" content=\"Un dron es un veh\u00edculo que se maneja por un control remoto, que para ascender se usa la fuerza de giro de sus motores unidos a las h\u00e9lices.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-21T21:11:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T22:24:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Drone-con-camara-HD-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bgaravitoc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"bgaravitoc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Drones y su clasificaci\u00f3n &#8211; Tipos de drones","description":"Un dron es un veh\u00edculo que se maneja por un control remoto, que para ascender se usa la fuerza de giro de sus motores unidos a las h\u00e9lices.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/","og_locale":"es_ES","og_type":"article","og_title":"Drones y su clasificaci\u00f3n &#8211; Tipos de drones","og_description":"Un dron es un veh\u00edculo que se maneja por un control remoto, que para ascender se usa la fuerza de giro de sus motores unidos a las h\u00e9lices.","og_url":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2023-03-21T21:11:57+00:00","article_modified_time":"2023-03-21T22:24:36+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Drone-con-camara-HD-1.jpg","type":"image\/jpeg"}],"author":"bgaravitoc","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"bgaravitoc","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/"},"author":{"name":"bgaravitoc","@id":"https:\/\/niixer.com\/#\/schema\/person\/193b588c9259f3557f87eba9562f84fb"},"headline":"Tipos de drones y su Clasificaci\u00f3n","datePublished":"2023-03-21T21:11:57+00:00","dateModified":"2023-03-21T22:24:36+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/"},"wordCount":1390,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Drone-con-camara-HD-1.jpg","keywords":["Camara","Camara4K","Drone","Drones","tecnolog\u00eda"],"articleSection":["Drones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/","url":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/","name":"Drones y su clasificaci\u00f3n &#8211; Tipos de drones","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Drone-con-camara-HD-1.jpg","datePublished":"2023-03-21T21:11:57+00:00","dateModified":"2023-03-21T22:24:36+00:00","description":"Un dron es un veh\u00edculo que se maneja por un control remoto, que para ascender se usa la fuerza de giro de sus motores unidos a las h\u00e9lices.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Drone-con-camara-HD-1.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Drone-con-camara-HD-1.jpg","width":1280,"height":720,"caption":"Drones y su clasificaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2023\/03\/21\/tipos-de-drones-y-su-clasificacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Tipos de drones y su Clasificaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/193b588c9259f3557f87eba9562f84fb","name":"bgaravitoc","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/916ef1acc35160f482faf13360be1f3faa52d6f2af43e0333dfe1054ff4c9222?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/916ef1acc35160f482faf13360be1f3faa52d6f2af43e0333dfe1054ff4c9222?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/916ef1acc35160f482faf13360be1f3faa52d6f2af43e0333dfe1054ff4c9222?s=96&d=mm&r=g","caption":"bgaravitoc"},"url":"https:\/\/niixer.com\/index.php\/author\/bgaravitoc\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/36150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/945"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=36150"}],"version-history":[{"count":19,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/36150\/revisions"}],"predecessor-version":[{"id":36662,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/36150\/revisions\/36662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/36204"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=36150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=36150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=36150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}