{"id":33237,"date":"2023-03-09T16:15:13","date_gmt":"2023-03-09T21:15:13","guid":{"rendered":"https:\/\/niixer.com\/?p=33237"},"modified":"2023-03-09T16:15:14","modified_gmt":"2023-03-09T21:15:14","slug":"hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/","title":{"rendered":"Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Origen y aportes a la ciencia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue un f\u00edsico, fil\u00f3sofo y l\u00f3gico alem\u00e1n, que fundo y fue uno de los principales miembros del famoso circulo de Berl\u00edn quien fue fundamental en la filosof\u00eda cient\u00edfica y estuvo mayormente activo entre 1926 y 1933.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hizo varias contribuciones a las teor\u00edas de la ciencia como la probabilidad, filosof\u00eda. Relatividad, mec\u00e1nica cu\u00e1ntica y partes de la termodin\u00e1mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue uno de los fundadores del movimiento del positivismo l\u00f3gico en la filosof\u00eda de la ciencia y defendi\u00f3 la idea de que el conocimiento cient\u00edfico debe basarse \u00fanicamente en un an\u00e1lisis l\u00f3gico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco de la primera guerra mundial trabajo siendo consejero t\u00e9cnico y escribi\u00f3 el impacto de la guerra en la filosof\u00eda de la ciencia, tambi\u00e9n fue relevante durante el debate sobre el positivismo l\u00f3gico en la sociolog\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-96.png\" alt=\"\" class=\"wp-image-33293\" width=\"198\" height=\"293\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-96.png 414w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-96-203x300.png 203w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">La esencia del conocimiento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Hans Reichenbach la esencia del conocimiento es la generalizaci\u00f3n, ya que el conocimiento se puede derivar de una generalizaci\u00f3n entre experiencias particulares, el menciono que el esp\u00edritu humano busca generalidades cada vez mayores por lo que entre m\u00e1s grande sea una generalidad m\u00e1s grande debe ser la cantidad de observaciones y pensamiento cr\u00edtico, de igual manera el propone que empirismo puede ser una base del conocimiento y la inducci\u00f3n como un buen m\u00e9todo para conocer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El asegura que hay dos clases de falsas generalizaciones, la primera puede ser una forma inofensiva de un error que se puede corregir de manera simple con mas experiencia, mientras que la segunda clase de falsa generalizaci\u00f3n es una forma mas nociva de cometer un error ya que consisten en similitudes que pueden conducir a peligros intolerables.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-105.png\" alt=\"\" class=\"wp-image-33303\" width=\"200\" height=\"193\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-105.png 326w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-105-300x290.png 300w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Probabilidad y causalidad <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><img loading=\"lazy\" decoding=\"async\" width=\"204\" height=\"204\" src=\"\" alt=\"C\u00f3mo calcular la probabilidad de que algo pase - 5 pasos\">Reichenbach trabajo en el \u00e1rea de la probabilidad y propuso la teor\u00eda de la causalidad probabil\u00edstica, por lo que llego a determinar que seg\u00fan esta teor\u00eda los eventos pueden tener variedad de causas y puede haber una relaci\u00f3n causal entre ellas que puede ser mas o menos probable seg\u00fan la cantidad de eventos y causas que determinen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otra teor\u00eda que propuso fue un principio de causalidad com\u00fan, tiene un grado de relevancia grande ya que postula una conexi\u00f3n entre una estructura causal y las conecta con relaciones probabil\u00edsticas que determina las interferencias sobre una relaci\u00f3n causal a partir de relaciones posiblemente observables.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-110.png\" alt=\"\" class=\"wp-image-33310\" width=\"196\" height=\"197\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-110.png 331w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-110-300x300.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-110-150x150.png 150w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Epistemologia<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Hans contribuyo en gran cantidad a la epistemolog\u00eda, que en si es la teor\u00eda del conocimiento y argumento que el conocimiento cient\u00edfico se puede basar en su mayor\u00eda de la experiencia y que la predicci\u00f3n es un elemento esencial en la investigaci\u00f3n cient\u00edfica y filos\u00f3fica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo considero que la epistemolog\u00eda no era una materia descriptiva sino como una actividad critica y prescriptiva para lograr buenos resultados, tambi\u00e9n consideraba que una de sus funciones mas importantes era causar una reconstrucci\u00f3n racional de la misma manera de la que puede pensar un cient\u00edfico, ya que se debe considerar que siempre se debe comparar con alg\u00fan cient\u00edfico real, al momento de hacer alguna comparaci\u00f3n con un cient\u00edfico se debe tomar como una oportunidad de eliminar alguna forma de pensar que no cumpla con el criterio m\u00ednimo que se necesita para una aceptabilidad racional y que se le de un cierto valor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El inter\u00e9s epistemol\u00f3gico de Reichenbach era una reconstrucci\u00f3n racional de la filosof\u00eda en la ciencia.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-116.png\" alt=\"\" class=\"wp-image-33317\" width=\"211\" height=\"172\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-116.png 337w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-116-300x245.png 300w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Filosof\u00eda de la fisica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Reichenbach hizo considerables aportes a la filosof\u00eda de la f\u00edsica, especialmente enfocada y relacionada con la mec\u00e1nica cu\u00e1ntica ya que en su lenguaje l\u00f3gico incluyo m\u00e1s all\u00e1 de un verdadero y un falso a\u00f1adi\u00f3 el valor indeterminado que se pod\u00eda usar en cantidades no sustituibles, pero recibi\u00f3 varias cr\u00edticas desde el \u00e1rea de la f\u00edsica como de la l\u00f3gica ya que el propuso una interpretaci\u00f3n de probabilidad de su teor\u00eda cu\u00e1ntica y argumento que las leyes cu\u00e1nticas no son ni pueden ser deterministas, sino que simplemente proporcionan una probabilidad de un resultado.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-119.png\" alt=\"\" class=\"wp-image-33322\" width=\"217\" height=\"180\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-119.png 416w, https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-119-300x248.png 300w\" sizes=\"auto, (max-width: 217px) 100vw, 217px\" \/><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Obras literarias <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este representa la integraci\u00f3n de las contribuciones filos\u00f3ficas de toda la vida y sus investigaciones sobre el an\u00e1lisis del tiempo <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-120.png\" alt=\"\" class=\"wp-image-33328\" width=\"106\" height=\"163\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En esta obra Hans trata de demostrar que la filosof\u00eda de la ciencia puede ser de f\u00e1cil acceso y entendimiento<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/02\/image-122.png\" alt=\"\" class=\"wp-image-33331\" width=\"110\" height=\"166\" \/><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">V\u00eddeo explicaci\u00f3n y profundizaci\u00f3n <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> <a href=\"https:\/\/youtu.be\/jP_je615SmU\">https:\/\/youtu.be\/jP_je615SmU <\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor:<\/strong> Sara Valentina Henao Vanegas <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor:<\/strong> Carlos Ivan Pinzon Romero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo:<\/strong> UCPSG7-1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad:<\/strong> Universidad central <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Fuentes: <\/h4>\n\n\n\n<pre class=\"wp-block-preformatted\">Biblioteca digital, El positivismo l\u00f3gico: Wittgenstein, Carnap y el circulo de Viena. Reichenbach y la escuela de Berl\u00edn.<a href=\"http:\/\/bibliotecadigital.ilce.edu.mx\/sites\/ciencia\/volumen3\/ciencia3\/161\/html\/sec_41.html#:~:text=Reichenbach%20consideraba%20a%20la%20epistemolog%C3%ADa,la%20de%20los%20cient%C3%ADficos%20reales\">http:\/\/bibliotecadigital.ilce.edu.mx\/sites\/ciencia\/volumen3\/ciencia3\/161\/html\/sec_41.html#:~:text=Reichenbach%20consideraba%20a%20la%20epistemolog%C3%ADa,la%20de%20los%20cient%C3%ADficos%20reales<\/a>.<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Marx, T. (2010) GRIN, La filosof\u00eda cient\u00edfica de Hans Reichenbach - un resumen cr\u00edtico. <a href=\"https:\/\/www.grin.com\/document\/180429\">https:\/\/www.grin.com\/document\/180429<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Enciclopedia Herder, Hans Reichenbach. <a href=\"https:\/\/encyclopaedia.herdereditorial.com\/wiki\/Autor:Reichenbach,_Hans#:~:text=Sus%20principales%20aportaciones%20se%20centran,medida%20en%20que%20es%20probable\">https:\/\/encyclopaedia.herdereditorial.com\/wiki\/Autor:Reichenbach,_Hans#:~:text=Sus%20principales%20aportaciones%20se%20centran,medida%20en%20que%20es%20probable<\/a>.<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Wikiwand, Filosof\u00eda y ciencia. <a href=\"https:\/\/www.wikiwand.com\/es\/Filosof%C3%ADa_y_ciencia\">https:\/\/www.wikiwand.com\/es\/Filosof%C3%ADa_y_ciencia<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Hans Reichenbach.(febrero 2007) En Wikipedia. <a href=\"https:\/\/es.wikipedia.org\/wiki\/Hans_Reichenbach#:~:text=Hizo%20importantes%20contribuciones%20a%20la,cu%C3%A1ntica%20y%20de%20la%20termodin%C3%A1mica\">https:\/\/es.wikipedia.org\/wiki\/Hans_Reichenbach#:~:text=Hizo%20importantes%20contribuciones%20a%20la,cu%C3%A1ntica%20y%20de%20la%20termodin%C3%A1mica<\/a>.<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">IM\u00c1GENES<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Barbera, G. (enero 2016) Reflexiones filos\u00f3ficas [Imagen]. Blogspot <a href=\"http:\/\/2.bp.blogspot.com\/-EqEOJruQNQQ\/VpfeAfU_VBI\/AAAAAAAAAbo\/wyowDG-hTZo\/s320\/1.jpg\">http:\/\/2.bp.blogspot.com\/-EqEOJruQNQQ\/VpfeAfU_VBI\/AAAAAAAAAbo\/wyowDG-hTZo\/s320\/1.jpg<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Proyectos Wikimedia, (noviembre 2022) Hans Reichenbach [Fotografia]. Wikipedia ]Wikipedia<a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/6\/66\/H_Reichenbach.jpg\/220px-H_Reichenbach.jpg\">https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/6\/66\/H_Reichenbach.jpg\/220px-H_Reichenbach.jpg<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Mart\u00ednez, M (enero 2017) Como calcular la probabilidad de que algo pase. [Imagen]. Uncomo <a href=\"https:\/\/t1.uc.ltmcdn.com\/es\/posts\/3\/7\/3\/como_calcular_la_probabilidad_de_que_algo_pase_1373_600.webp\">https:\/\/t1.uc.ltmcdn.com\/es\/posts\/3\/7\/3\/como_calcular_la_probabilidad_de_que_algo_pase_1373_600.webp<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Wikipedia (abril 2007) El conocimiento como intersecci\u00f3n de creencias y verdades. [Imagen]. <a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/f\/fc\/Definicion_clasica_de_conocimiento.png\/220px-Definicion_clasica_de_conocimiento.png\">https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/f\/fc\/Definicion_clasica_de_conocimiento.png\/220px-Definicion_clasica_de_conocimiento.png<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">L\u00f3pez, N (junio 2015) La ciencia que estudia las propiedades. [Imagen].Prezi <a href=\"https:\/\/tomi-digital-resources.storage.googleapis.com\/images\/classes\/lessons\/lsn-48101-5f304750111b2.jpeg\">https:\/\/tomi-digital-resources.storage.googleapis.com\/images\/classes\/lessons\/lsn-48101-5f304750111b2.jpeg<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Amazon, The direction of the time. [Fotografia].Tomado de: <a href=\"https:\/\/m.media-amazon.com\/images\/I\/710pQtwCd7L.jpg\">https:\/\/m.media-amazon.com\/images\/I\/710pQtwCd7L.jpg<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Lecturlandia, La filosof\u00eda cient\u00edfica. [Fotografia]. <a href=\"https:\/\/assets.lectulandia.com\/b\/ab\/Hans%20Reichenbach\/La%20filosofia%20cientifica%20(1)\/big.jpg\">https:\/\/assets.lectulandia.com\/b\/ab\/Hans%20Reichenbach\/La%20filosofia%20cientifica%20(1)\/big.jpg<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">L\u00f3pez Garcia, J. (6 enero 2018). Tutorial sobre Reichenbach [Video]. YouTube. <a href=\"https:\/\/youtu.be\/jP_je615SmU\">https:\/\/youtu.be\/jP_je615SmU<\/a><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Origen y aportes a la ciencia Fue un f\u00edsico, fil\u00f3sofo y l\u00f3gico alem\u00e1n, que fundo y fue uno de los principales miembros del famoso circulo de Berl\u00edn quien fue fundamental en la filosof\u00eda cient\u00edfica y estuvo mayormente activo entre 1926 y 1933. Hizo varias contribuciones a las teor\u00edas de laSeguir Leyendo<\/p>\n","protected":false},"author":548,"featured_media":34832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[30],"tags":[2470,2494,602,2403,2096],"class_list":["post-33237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-niixer","tag-filosofia","tag-hans-reichenbach","tag-sistemas","tag-teoria-general-de-sistemas-2","tag-tgs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0 &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos<\/title>\n<meta name=\"description\" content=\"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0 &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"og:description\" content=\"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-09T21:15:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-09T21:15:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Teoria-de-sistemas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"shenaov\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"shenaov\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0 &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/","og_locale":"es_ES","og_type":"article","og_title":"Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0 &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","og_description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0","og_url":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2023-03-09T21:15:13+00:00","article_modified_time":"2023-03-09T21:15:14+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Teoria-de-sistemas.jpg","type":"image\/jpeg"}],"author":"shenaov","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"shenaov","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/"},"author":{"name":"shenaov","@id":"https:\/\/niixer.com\/#\/schema\/person\/0901bcb13041f9233d3397696f6cfca6"},"headline":"Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0","datePublished":"2023-03-09T21:15:13+00:00","dateModified":"2023-03-09T21:15:14+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/"},"wordCount":804,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Teoria-de-sistemas.jpg","keywords":["filosofia","Hans Reichenbach","Sistemas","teoria general de sistemas","TGS"],"articleSection":["Niixer"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/","url":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/","name":"Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0 &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Teoria-de-sistemas.jpg","datePublished":"2023-03-09T21:15:13+00:00","dateModified":"2023-03-09T21:15:14+00:00","description":"En Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos encuentra los mejores contenidos del mundo de la tecnolog\u00eda | Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Teoria-de-sistemas.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2023\/03\/Teoria-de-sistemas.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2023\/03\/09\/hans-reichenbach-la-experiencia-y-el-conocimiento-de-un-sistema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Hans Reichenbach: La experiencia y el conocimiento de un sistema\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/0901bcb13041f9233d3397696f6cfca6","name":"shenaov","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eb57b4f888d04eccd91f7c98334c68b757c1939e504e8b0abdea882f54e2599b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb57b4f888d04eccd91f7c98334c68b757c1939e504e8b0abdea882f54e2599b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb57b4f888d04eccd91f7c98334c68b757c1939e504e8b0abdea882f54e2599b?s=96&d=mm&r=g","caption":"shenaov"},"description":"Estudiante ingenieria industrial","url":"https:\/\/niixer.com\/index.php\/author\/shenaov\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/33237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/548"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=33237"}],"version-history":[{"count":3,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/33237\/revisions"}],"predecessor-version":[{"id":34833,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/33237\/revisions\/34833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/34832"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=33237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=33237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=33237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}