{"id":3225,"date":"2020-11-16T16:01:15","date_gmt":"2020-11-16T21:01:15","guid":{"rendered":"https:\/\/niixer.com\/?p=3225"},"modified":"2020-11-16T16:01:17","modified_gmt":"2020-11-16T21:01:17","slug":"biostar-presenta-nueva-ssd-de-estado-solido-portable","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/","title":{"rendered":"BIOSTAR presenta nueva SSD de estado s\u00f3lido portable"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La empresa taiwanesa de tecnolog\u00eda presenta la nueva BIOSTAR P500, una SSD externa dirigida a los usuarios que quieren aprovechar las ventajas de las unidades de estado s\u00f3lido, para mover datos y archivos a una gran velocidad, conect\u00e1ndose pr\u00e1cticamente a casi cualquier equipo y lugar que se imagine.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dise\u00f1o de la BIOSTAR P500<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Esta unidad viene en una carcasa de aluminio, dise\u00f1ada para disipar el calor, proteger de descargas electrost\u00e1ticas por alg\u00fan apag\u00f3n, proporcionar rigidez estructural y brindar est\u00e9ticamente un aspecto atractivo y personalizado por el sistema de iluminaci\u00f3n RGB que incluye, el cual puede activar o desactivar simplemente moviendo la unidad 45 grados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, mide poco m\u00e1s de 11 cm por lo que puede transportarse con comodidad a cualquier parte y en cualquier lugar, viene von un puerto USB Tipo C, aunque la compa\u00f1\u00eda incluye un segundo puerto, pero USB Tipo A, para aumentar la compatibilidad con dispositivos que no adapten tecnolog\u00eda actualizada como la del USB Tipo C.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Caracter\u00edsticas del nuevo BIOSTAR<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Al Interior la P500 se conecta a una interfaz PCIe y soporta el protocolo NVMe, externamente la interfaz es la est\u00e1ndar, USB 3.2 Gen2, por lo que su tasa de transferencia de datos es elevada, hasta 1.000 \/ 900 Mbytes por segundo en lectura \/ escritura secuencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan rumores esta SSD de almacenamiento se comercializar\u00e1 en capacidades de almacenamiento de 512 GB, 1 TB y 2 TB; la unidad est\u00e1 dirigida a creadores de contenido o jugadores que busquen tiempos de carga m\u00e1s r\u00e1pidos, aunque obviamente es \u00fatil para cualquier usuario que busque una soluci\u00f3n de almacenamiento externo y portable de alto rendimiento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Lanzamiento<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00fan no se sabe el precio y fecha de lanzamiento que tendr\u00e1 esta nueva SSD, pero est\u00e1 claro que las ventajas de las unidades de estado s\u00f3lido, se est\u00e1n extendiendo de a poco y r\u00e1pidamente a las SSD externas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autor:&nbsp;<a href=\"https:\/\/niixer.com\/?s=Andres+Felipe+Avenda%C3%B1o+Junca\">Andr\u00e9s Felipe Avenda\u00f1o Junca<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Editor: Carlos Pinz\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3digo: UUPS-5<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong><\/h3>\n\n\n\n<pre class=\"wp-block-preformatted\">Dau, A. (2020). <em>BIOSTAR anuncia su nuevo SSD de la serie port\u00e1til P500<\/em>. Tecnogaming. <a href=\"https:\/\/tecnogaming.com\/biostar-anuncia-su-nuevo-ssd-de-la-serie-portatil-p500\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tecnogaming.com\/biostar-anuncia-su-nuevo-ssd-de-la-serie-portatil-p500\/<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Montes, J. (2020). <em>BIOSTAR presenta la SSD externa y portable, serie P500<\/em>. MuyComputer. <a href=\"https:\/\/www.muycomputer.com\/2020\/11\/16\/biostar-p500-ssd-portable\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.muycomputer.com\/2020\/11\/16\/biostar-p500-ssd-portable\/<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">David. (2020). <em>BIOSTAR anuncia las SSD externas P500 de hasta 2 TB<\/em>. Geektopia. <a href=\"https:\/\/www.geektopia.es\/es\/technology\/2020\/11\/16\/noticias\/biostar-anuncia-las-ssd-externas-p500-de-hasta-2-tb.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.geektopia.es\/es\/technology\/2020\/11\/16\/noticias\/biostar-anuncia-las-ssd-externas-p500-de-hasta-2-tb.html<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">David. (2020). <em>BIOSTAR anuncia las SSD externas P500 de hasta 2 TB <\/em>[Imagen]. Geektopia. <a href=\"https:\/\/www.geektopia.es\/es\/technology\/2020\/11\/16\/noticias\/biostar-anuncia-las-ssd-externas-p500-de-hasta-2-tb.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.geektopia.es\/es\/technology\/2020\/11\/16\/noticias\/biostar-anuncia-las-ssd-externas-p500-de-hasta-2-tb.html<\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>La empresa taiwanesa de tecnolog\u00eda presenta la nueva BIOSTAR P500, una SSD externa dirigida a los usuarios que quieren aprovechar las ventajas de las unidades de estado s\u00f3lido, para mover datos y archivos a una gran velocidad, conect\u00e1ndose pr\u00e1cticamente a casi cualquier equipo y lugar que se imagine. Dise\u00f1o deSeguir Leyendo<\/p>\n","protected":false},"author":72,"featured_media":3226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[30],"tags":[246,668,663,31,669],"class_list":["post-3225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-niixer","tag-almacenamiento","tag-biostar","tag-ssd","tag-tecnologia","tag-unidades-ssd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BIOSTAR presenta nueva SSD de estado s\u00f3lido portable<\/title>\n<meta name=\"description\" content=\"La empresa taiwanesa presenta la nueva BIOSTAR P500, una SSD externa dirigida a los usuarios que busquen tiempos de carga m\u00e1s r\u00e1pidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BIOSTAR presenta nueva SSD de estado s\u00f3lido portable\" \/>\n<meta property=\"og:description\" content=\"La empresa taiwanesa presenta la nueva BIOSTAR P500, una SSD externa dirigida a los usuarios que busquen tiempos de carga m\u00e1s r\u00e1pidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-16T21:01:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-16T21:01:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/126biostarp500_2_original.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andres Felipe Avenda\u00f1o Junca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Felipe Avenda\u00f1o Junca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BIOSTAR presenta nueva SSD de estado s\u00f3lido portable","description":"La empresa taiwanesa presenta la nueva BIOSTAR P500, una SSD externa dirigida a los usuarios que busquen tiempos de carga m\u00e1s r\u00e1pidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/","og_locale":"es_ES","og_type":"article","og_title":"BIOSTAR presenta nueva SSD de estado s\u00f3lido portable","og_description":"La empresa taiwanesa presenta la nueva BIOSTAR P500, una SSD externa dirigida a los usuarios que busquen tiempos de carga m\u00e1s r\u00e1pidos.","og_url":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2020-11-16T21:01:15+00:00","article_modified_time":"2020-11-16T21:01:17+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/126biostarp500_2_original.jpg","type":"image\/jpeg"}],"author":"Andres Felipe Avenda\u00f1o Junca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Felipe Avenda\u00f1o Junca","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/"},"author":{"name":"Andres Felipe Avenda\u00f1o Junca","@id":"https:\/\/niixer.com\/#\/schema\/person\/2b0bafc50f372f80e7f3cd6d990128cf"},"headline":"BIOSTAR presenta nueva SSD de estado s\u00f3lido portable","datePublished":"2020-11-16T21:01:15+00:00","dateModified":"2020-11-16T21:01:17+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/"},"wordCount":348,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/126biostarp500_2_original.jpg","keywords":["Almacenamiento","BIOSTAR","SSD","tecnolog\u00eda","Unidades SSD"],"articleSection":["Niixer"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/","url":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/","name":"BIOSTAR presenta nueva SSD de estado s\u00f3lido portable","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/126biostarp500_2_original.jpg","datePublished":"2020-11-16T21:01:15+00:00","dateModified":"2020-11-16T21:01:17+00:00","description":"La empresa taiwanesa presenta la nueva BIOSTAR P500, una SSD externa dirigida a los usuarios que busquen tiempos de carga m\u00e1s r\u00e1pidos.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/126biostarp500_2_original.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/126biostarp500_2_original.jpg","width":800,"height":445,"caption":"Unidad de almacenamiento SSD BIOSTAR P500"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/16\/biostar-presenta-nueva-ssd-de-estado-solido-portable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"BIOSTAR presenta nueva SSD de estado s\u00f3lido portable"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/2b0bafc50f372f80e7f3cd6d990128cf","name":"Andres Felipe Avenda\u00f1o Junca","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","caption":"Andres Felipe Avenda\u00f1o Junca"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/aavendanoju\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/3225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=3225"}],"version-history":[{"count":1,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/3225\/revisions"}],"predecessor-version":[{"id":3227,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/3225\/revisions\/3227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/3226"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=3225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=3225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=3225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}