{"id":2930,"date":"2020-11-10T23:38:58","date_gmt":"2020-11-11T04:38:58","guid":{"rendered":"https:\/\/niixer.com\/?p=2930"},"modified":"2020-11-17T18:36:17","modified_gmt":"2020-11-17T23:36:17","slug":"easyar-motor-realidad-aumentada","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/","title":{"rendered":"EasyAR motor de realidad aumentada"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">EasyAR Sense es un motor de <a href=\"https:\/\/niixer.com\/?s=Realidad+Aumentada\">realidad aumentada<\/a> que nos proporciona una detecci\u00f3n del mundo real. EasyAR Sense <a href=\"https:\/\/niixer.com\/?s=Unity\">Unity<\/a> Pluguin es un complemento de Unity para EasyAR Sense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EasyAR Sense tiene una gran familia de versiones a partir de la versi\u00f3n 4, el conocido anteriormente EasyAR SDK se llamar\u00e1 EasyAR Sense. De hecho, proporciona capacidades de detecci\u00f3n del mundo real, las funcionalidades de la familia 3.0 tambi\u00e9n est\u00e1n incluidas en EasyAR en su cuarta familia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Versiones de la Familia EasyAR<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">EasyAR Sense 4.0<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">En esta versi\u00f3n de EasyAR Sense 4.0 le ofrece cuatro modos de suscripci\u00f3n: Edici\u00f3n personal (gratuita), edici\u00f3n profesional (pago mensual), edici\u00f3n cl\u00e1sica (pago \u00fanico) y edici\u00f3n empresarial (personalizada).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4.0, EasyAR Sense no solo proporciona todas las funciones de la versi\u00f3n 3.x. Igualmente tambi\u00e9n agrega nuevos componentes de algoritmo y soporte de plataforma.&nbsp;Por consiguiente, Sparse Spatial Map ofrece la capacidad de escanear el entorno para generar mapas de nubes de puntos Sparse 3D en tiempo real.&nbsp;De igual forma, Dense Spatial Map admite la generaci\u00f3n en tiempo real de mapas de cuadr\u00edcula 3D mediante el escaneo del entorno y habilita los efectos de colisi\u00f3n y oclusi\u00f3n. Tambi\u00e9n,&nbsp;Motion Tracking hace que los objetos virtuales sean m\u00e1s estables en el espacio y reduce la deriva causada por el movimiento de la c\u00e1mara.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">EasyAR Sense 3.0<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">EasyAR Sense 3.0 le ofrece dos variantes de licencia: Basic y Pro.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">EasyAR SDK 2.0<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">EasyAR SDK es un motor de realidad aumentada. Asimismo, hay dos versiones las cuales son: EasyAR SDK Basic y EasyAR SDK Pro.&nbsp;Aun as\u00ed, EasyAR SDK 1.x solo tiene la edici\u00f3n b\u00e1sica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por parte de <strong>EasyAR SDK Basic<\/strong>&nbsp;es gratuito para uso comercial. Aun as\u00ed,&nbsp;no hay limitaciones ni marcas de agua.&nbsp;Adem\u00e1s, es compatible con AR basado en un objetivo plano, admite una carga suave y reconocimiento para m\u00e1s de 1000 objetivos locales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cambio, <strong>EasyAR SDK Pro<\/strong>&nbsp;es una nueva edici\u00f3n introducida en EasyAR SDK 2.0. Pero&nbsp;todas las funciones que est\u00e1n en EasyAR SDK Basic est\u00e1n disponibles en EasyAR SDK Pro.&nbsp;Y en esta versi\u00f3n Pro incluye m\u00e1s funciones en comparaci\u00f3n con EasyAR SDK Basic, por lo tanto, est\u00e1 incluido el seguimiento de objetos 3D, SLAM y la grabaci\u00f3n de pantalla.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">La nueva experiencia de AR<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sparse SpatialMap: Se utiliza para la construcci\u00f3n de mapas espaciales dispersos. En segundo lugar. As\u00ed como, para la localizaci\u00f3n utilizando mapas existentes.&nbsp;Tambi\u00e9n proporciona utilidades para el acceso a la nube de puntos y al plano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DenseSpatialMap: Se utiliza para reconstruir un entorno con extrema precisi\u00f3n y densidad. De esta forma, el modelo reconstruido est\u00e1 representado por una&nbsp;malla triangular. Y DenseSpatialMap necesita 1 b\u00fafer de c\u00e1mara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autor: <a href=\"https:\/\/www.niixer.com\/?s=Andr%C3%A9s+Felipe+Tobos+Agudelo+\">Andr\u00e9s Felipe Tobos Agudelo<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Editor: Carlos Pinz\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3digo: UCRV-8<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad: <a href=\"https:\/\/www.ucentral.edu.co\/\">Universidad Central<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong><\/h3>\n\n\n\n<pre class=\"wp-block-preformatted\">EasyAR. (2020). <em>Augmented Reality &amp; AR SDK<\/em>. https:\/\/www.easyar.com\/<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Imagen<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Vectary. (2018).<em> 4 easy AR tools you can use as a marketer and designer <\/em>[Imagen]. VECTARY. <a href=\"https:\/\/as.com\/esports\/2016\/09\/16\/portada\/1473981525_248613.html\">https:\/\/www.vectary.com\/3d-modeling-inspiration\/4-easy-ar-tools-you-can-use-as-a-marketer-and-designer\/<\/a><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EasyAR Sense es un motor de realidad aumentada que nos proporciona una detecci\u00f3n del mundo real. EasyAR Sense Unity Pluguin es un complemento de Unity para EasyAR Sense. EasyAR Sense tiene una gran familia de versiones a partir de la versi\u00f3n 4, el conocido anteriormente EasyAR SDK se llamar\u00e1 EasyARSeguir Leyendo<\/p>\n","protected":false},"author":66,"featured_media":3019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[55],"tags":[501,634,65,214],"class_list":["post-2930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-realidad-aumentada","tag-ar","tag-easyar","tag-realidad-aumentada","tag-unity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EasyAR motor de realidad aumentada &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos<\/title>\n<meta name=\"description\" content=\"EasyAR Sense es un motor de realidad aumentada que nos proporciona: EasyAR Sense Unity Pluguin es un complemento de Unity para EasyAR Sense.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EasyAR motor de realidad aumentada &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"og:description\" content=\"EasyAR Sense es un motor de realidad aumentada que nos proporciona: EasyAR Sense Unity Pluguin es un complemento de Unity para EasyAR Sense.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-11T04:38:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-17T23:36:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/EasyAR-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andres Felipe Tobos Agudelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Felipe Tobos Agudelo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EasyAR motor de realidad aumentada &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","description":"EasyAR Sense es un motor de realidad aumentada que nos proporciona: EasyAR Sense Unity Pluguin es un complemento de Unity para EasyAR Sense.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/","og_locale":"es_ES","og_type":"article","og_title":"EasyAR motor de realidad aumentada &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","og_description":"EasyAR Sense es un motor de realidad aumentada que nos proporciona: EasyAR Sense Unity Pluguin es un complemento de Unity para EasyAR Sense.","og_url":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2020-11-11T04:38:58+00:00","article_modified_time":"2020-11-17T23:36:17+00:00","og_image":[{"width":2560,"height":1441,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/EasyAR-scaled.jpg","type":"image\/jpeg"}],"author":"Andres Felipe Tobos Agudelo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Felipe Tobos Agudelo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/"},"author":{"name":"Andres Felipe Tobos Agudelo","@id":"https:\/\/niixer.com\/#\/schema\/person\/74a22399adf90e135a6c5cf1b5dceec2"},"headline":"EasyAR motor de realidad aumentada","datePublished":"2020-11-11T04:38:58+00:00","dateModified":"2020-11-17T23:36:17+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/"},"wordCount":499,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/EasyAR-scaled.jpg","keywords":["AR","EasyAR","Realidad Aumentada","Unity"],"articleSection":["Realidad Aumentada"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/","url":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/","name":"EasyAR motor de realidad aumentada &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/EasyAR-scaled.jpg","datePublished":"2020-11-11T04:38:58+00:00","dateModified":"2020-11-17T23:36:17+00:00","description":"EasyAR Sense es un motor de realidad aumentada que nos proporciona: EasyAR Sense Unity Pluguin es un complemento de Unity para EasyAR Sense.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/EasyAR-scaled.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/EasyAR-scaled.jpg","width":2560,"height":1441,"caption":"EasyAR"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/10\/easyar-motor-realidad-aumentada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"EasyAR motor de realidad aumentada"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/74a22399adf90e135a6c5cf1b5dceec2","name":"Andres Felipe Tobos Agudelo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fee00f0d0ceca767e819bd8f7500f27d323e35c2e032d5d1bd5a836bbb758966?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fee00f0d0ceca767e819bd8f7500f27d323e35c2e032d5d1bd5a836bbb758966?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fee00f0d0ceca767e819bd8f7500f27d323e35c2e032d5d1bd5a836bbb758966?s=96&d=mm&r=g","caption":"Andres Felipe Tobos Agudelo"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/atobosa\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/2930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=2930"}],"version-history":[{"count":8,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/2930\/revisions"}],"predecessor-version":[{"id":3329,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/2930\/revisions\/3329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/3019"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=2930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=2930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=2930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}