{"id":2741,"date":"2020-11-09T18:16:06","date_gmt":"2020-11-09T23:16:06","guid":{"rendered":"https:\/\/niixer.com\/?p=2741"},"modified":"2020-11-17T18:18:54","modified_gmt":"2020-11-17T23:18:54","slug":"assets","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/","title":{"rendered":"Assets"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 son los Assets?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un asset, tambi\u00e9n conocido como game assets, los assets son los recursos que se usan en un videojuego y que se incorporan en el mismo. Como por ejemplo la incorporaci\u00f3n de los sonidos, las animaciones, etc. [<a href=\"https:\/\/www.geekno.com\/glosario\/asset\">1<\/a>]<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Assets en Unity<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los assets que podemos usar:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1.<strong>Animator Controller <\/strong>en unity&nbsp;permite organizar conjuntos de animaciones para lograr transiciones de animaci\u00f3n para los  personajes o objetos.&nbsp;[<a href=\"https:\/\/docs.unity3d.com\/Manual\/class-AnimatorController.html\">2<\/a>]<br>2.<strong>El mezclador de audio<\/strong> de Unity le permite mezclar varias fuentes de audio, aplicarles efectos y realizar la masterizaci\u00f3n. Contiene un mezclador de audio que en una cadena de se\u00f1al le permite aplicar atenuaci\u00f3n de volumen y correcci\u00f3n de tono, adem\u00e1s de  insertar efectos que procesan la se\u00f1al de audio para modificar los par\u00e1metros de los efectos.&nbsp;[<a href=\"https:\/\/docs.unity3d.com\/Manual\/AudioMixer.html\">3<\/a>]<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como implementar el paquete gratuito de standard assets:<\/h3>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">En este peque\u00f1o instructivo, se explicara como realizar la descarga del paquete de assets en la versi\u00f3n 2018.4.29f1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1.primero se crea o abre un proyecto en Unity<br>2.para acceder a la tienda de Unity, se selecciona Window&gt;Asset Store.  <br>3.una vez damos click en Asset Store, cargara la siguiente ventana:<br>en el buscador de la tienda de Unity, se escribe standard assets.<\/p>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"743\" height=\"716\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen1-3.png\" alt=\"\" class=\"wp-image-3269\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen1-3.png 743w, https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen1-3-300x289.png 300w\" sizes=\"auto, (max-width: 743px) 100vw, 743px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">5.Buscamos la versi\u00f3n gratuita de standard asset creada por Unity Technologies .Una vez encontrado, se dar\u00e1 clic en el bot\u00f3n importar o abrir en Unity e iniciara el proceso de descarga.<br>Nota: se recomienda tener una carpeta exclusiva para la descarga de archivos Unity<br>6. Luego aparecer\u00e1 una ventana&#8221; Import Unity Package &#8220;, se dar\u00e1 clic en Import.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"608\" height=\"678\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen2.png\" alt=\"\" class=\"wp-image-3272\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen2.png 608w, https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen2-269x300.png 269w\" sizes=\"auto, (max-width: 608px) 100vw, 608px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">7.Una vez descargado el paquete de standard assets, se verifica que en la opci\u00f3n Project que se encuentre implementado el paquete.<br>8.Disfrutamos los assets que son los recursos que se usan en el videojuego.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"244\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen3-1024x244.png\" alt=\"\" class=\"wp-image-3275\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen3-1024x244.png 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen3-300x72.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen3-768x183.png 768w, https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen3.png 1526w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Autor:<a href=\"https:\/\/theworldinoneclick.000webhostapp.com\/\">Diana Milena Bri\u00f1ez Rodriguez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Editor:&nbsp;<a href=\"https:\/\/niixer.com\/\">Carlos Pinz\u00f3n<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Codigo:UCRV-6<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad:<a href=\"https:\/\/www.ucentral.edu.co\/\">Universidad Central<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Referencias<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">[1] Cervera, I., &amp; Cervera, I. (2019, 23 abril).&nbsp;<em>Asset | \u00bfQu\u00e9 significa Asset? | \u00bfQu\u00e9 son los assets de un juego?<\/em>&nbsp;Geekno. https:\/\/www.geekno.com\/glosario\/asset<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[2] Technologies, U. (s. f.).&nbsp;<em>Unity &#8211; Manual: Animator Controller<\/em>. Unity. https:\/\/docs.unity3d.com\/Manual\/class-AnimatorController.html<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[3] Technologies, U. (s. f.-b).&nbsp;<em>Unity &#8211; Manual: Audio Mixer<\/em>. Unity. https:\/\/docs.unity3d.com\/Manual\/AudioMixer.html<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[4] Brinez, D. (2020, 9 noviembre). Manual_1 [Ilustraci\u00f3n]. En&nbsp;<em>Manual_1<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[5] Brinez, D. (2020, 9 noviembre). Manual_2 [Ilustraci\u00f3n]. En&nbsp;<em>Manual_<\/em>2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">[6] <em>ASSETS<\/em>. (s. f.). [Ilustraci\u00f3n]. Unity. https:\/\/unity3d.com\/es\/quick-guide-to-unity-asset-store.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 son los Assets? Un asset, tambi\u00e9n conocido como game assets, los assets son los recursos que se usan en un videojuego y que se incorporan en el mismo. Como por ejemplo la incorporaci\u00f3n de los sonidos, las animaciones, etc. [1] Assets en Unity Los assets que podemos usar: 1.AnimatorSeguir Leyendo<\/p>\n","protected":false},"author":45,"featured_media":3298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[77],"tags":[337,214,66],"class_list":["post-2741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videojuegos","tag-assets","tag-unity","tag-videojuegos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los assets son los recursos que se usan en un videojuego<\/title>\n<meta name=\"description\" content=\"Los assets son los recursos que se usan en un videojuego y que se incorporan en el mismo. Como por ejemplo la incorporaci\u00f3n de los sonidos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los assets son los recursos que se usan en un videojuego\" \/>\n<meta property=\"og:description\" content=\"Los assets son los recursos que se usan en un videojuego y que se incorporan en el mismo. Como por ejemplo la incorporaci\u00f3n de los sonidos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-09T23:16:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-17T23:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"734\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diana Milena Bri\u00f1ez Rodriguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diana Milena Bri\u00f1ez Rodriguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los assets son los recursos que se usan en un videojuego","description":"Los assets son los recursos que se usan en un videojuego y que se incorporan en el mismo. Como por ejemplo la incorporaci\u00f3n de los sonidos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/","og_locale":"es_ES","og_type":"article","og_title":"Los assets son los recursos que se usan en un videojuego","og_description":"Los assets son los recursos que se usan en un videojuego y que se incorporan en el mismo. Como por ejemplo la incorporaci\u00f3n de los sonidos","og_url":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2020-11-09T23:16:06+00:00","article_modified_time":"2020-11-17T23:18:54+00:00","og_image":[{"width":700,"height":734,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen-3.jpg","type":"image\/jpeg"}],"author":"Diana Milena Bri\u00f1ez Rodriguez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Diana Milena Bri\u00f1ez Rodriguez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/"},"author":{"name":"Diana Milena Bri\u00f1ez Rodriguez","@id":"https:\/\/niixer.com\/#\/schema\/person\/823f0a6bb1ef8abecba077f3bf41de0a"},"headline":"Assets","datePublished":"2020-11-09T23:16:06+00:00","dateModified":"2020-11-17T23:18:54+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/"},"wordCount":416,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen-3.jpg","keywords":["Assets","Unity","Videojuegos"],"articleSection":["Videojuegos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/","url":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/","name":"Los assets son los recursos que se usan en un videojuego","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen-3.jpg","datePublished":"2020-11-09T23:16:06+00:00","dateModified":"2020-11-17T23:18:54+00:00","description":"Los assets son los recursos que se usan en un videojuego y que se incorporan en el mismo. Como por ejemplo la incorporaci\u00f3n de los sonidos","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen-3.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/Imagen-3.jpg","width":700,"height":734},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/09\/assets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Assets"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/823f0a6bb1ef8abecba077f3bf41de0a","name":"Diana Milena Bri\u00f1ez Rodriguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/967f537029d57e139158615124112dd622ec969485f39d347c56c2b4f71638e2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/967f537029d57e139158615124112dd622ec969485f39d347c56c2b4f71638e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/967f537029d57e139158615124112dd622ec969485f39d347c56c2b4f71638e2?s=96&d=mm&r=g","caption":"Diana Milena Bri\u00f1ez Rodriguez"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/dbrinezr\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/2741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=2741"}],"version-history":[{"count":24,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/2741\/revisions"}],"predecessor-version":[{"id":3314,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/2741\/revisions\/3314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/3298"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=2741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=2741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=2741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}