{"id":2521,"date":"2020-11-02T19:39:47","date_gmt":"2020-11-03T00:39:47","guid":{"rendered":"https:\/\/niixer.com\/?p=2521"},"modified":"2020-11-02T19:39:49","modified_gmt":"2020-11-03T00:39:49","slug":"samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/","title":{"rendered":"Samsung impacta en el mercado de la gama media con nuevo celular"},"content":{"rendered":"\n<p>La famosa y reconocida marca coreana de productos tecnol\u00f3gicos SAMSUNG, hace unos meses hizo el lanzamiento de su Galaxy M51, un celular con el cual busca tener una relevancia importante dentro del mercado de m\u00f3viles de gama media; imperando sobre todas las novedades tecnol\u00f3gicas, la gran capacidad de bater\u00eda que tiene para ser un Smartphone que no va competir en lo m\u00e1s alto del mercado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dise\u00f1o del Samsung M51<\/strong><\/h3>\n\n\n\n<p>El nuevo Galaxy mide 163 x 78 mm, tiene un grosor de 8,5 mm y pesa 213 gr, factores que lo hacen un m\u00f3vil muy similar a lo que hemos visto en las \u00faltimas entregas en el sector de la gama media, no es muy grande, ni pesado, pero tampoco es peque\u00f1o, y su peso liviano lo hace un celular c\u00f3modo de utilizar, y f\u00e1cil de guardar, cuando tenga ropa muy ajustada.<\/p>\n\n\n\n<p>Su pantalla es muy bien aprovechada, casi no tiene bordes y se puede apreciar mucho color sin estorbo, no tiene un <em>notch<\/em> engorroso como en anteriores generaciones, en cambio tiene una perforaci\u00f3n donde se ubica la c\u00e1mara frontal, que con el tiempo se vuelve imperceptible, en total es de 6,7 pulgadas y tiene una resoluci\u00f3n FullHD+.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Caracter\u00edsticas del nuevo Galaxy<\/strong><\/h3>\n\n\n\n<p>El M51 tiene un procesador Snapdragon 730G, un chipset de gama media premium de ocho n\u00facleos a 2,2 GHz, junto a este lo acompa\u00f1a 6 GB de memoria RAM y 128 GB de almacenamiento interno, que se pueden ampliar con una tarjeta microSD, permitiendo una capacidad m\u00e1xima de almacenamiento de hasta 512 GB; convirti\u00e9ndolo sin duda alguna, es una de las mejores opciones del mercado de la gama media.<\/p>\n\n\n\n<p>La firma coreana quiso apostar por la capacidad de bater\u00eda en su nueva entrega, es por esto que adapto una bater\u00eda de 7.000 mAh, que convierte al nuevo M51 en el celular con mayor capacidad de energ\u00eda en la gama media, hasta el momento. Samsung no ha dado estimaciones sobre su autonom\u00eda, lo que se sabe es que tiene carga r\u00e1pida de 25W, que seg\u00fan la marca, carga el celular por completo en un lapso de dos horas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>C\u00e1maras aceptables<\/strong> <strong>en este Samsung<\/strong><\/h3>\n\n\n\n<p>El Galaxy M51 tiene un panel trasero de cuatro c\u00e1maras traseras, la principal tiene una capacidad de 64 megap\u00edxeles, con un focal 1.8, junto a esta, como apoyo, la acompa\u00f1a un sensor gran angular de 12 megap\u00edxeles, con 123\u00b0 de campo de visi\u00f3n y un focal de 2.2; las otras dos c\u00e1maras son un apoyo de las dos principales, ambos sensores son de 5 megap\u00edxeles, m\u00e1s un focal 2.4. Por su parte, la peque\u00f1a c\u00e1mara frontal tiene una resoluci\u00f3n de 32 megap\u00edxeles.<\/p>\n\n\n\n<p>Autor:&nbsp;<a href=\"https:\/\/niixer.com\/?s=Andres+Felipe+Avenda%C3%B1o+Junca\">Andr\u00e9s Felipe Avenda\u00f1o Junca<\/a><\/p>\n\n\n\n<p>Editor: Carlos Pinz\u00f3n<\/p>\n\n\n\n<p>Codigo: UUPS-5<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong><\/h3>\n\n\n\n<pre class=\"wp-block-preformatted\">Redacci\u00f3n. (2020).<em> Samsung lanza el m\u00f3vil de gama media con la mayor bater\u00eda del mercado<\/em>. La Vanguardia. <a href=\"https:\/\/www.lavanguardia.com\/tecnologia\/20201006\/483890529131\/samsung-m51-el-movil-con-la-bateria-mas-grande.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.lavanguardia.com\/tecnologia\/20201006\/483890529131\/samsung-m51-el-movil-con-la-bateria-mas-grande.html<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Samsung. (s.f). <em>Samsung anuncia Galaxy M51, el smartphone con la mayor bater\u00eda del mercado<\/em>. Samsung. <a href=\"https:\/\/news.samsung.com\/es\/samsung-anuncia-galaxy-m51-el-smartphone-con-la-mayor-bateria-del-mercado\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/news.samsung.com\/es\/samsung-anuncia-galaxy-m51-el-smartphone-con-la-mayor-bateria-del-mercado<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Garc\u00eda, J. (2020). <em>El Samsung Galaxy M51 llega a Espa\u00f1a: precio y disponibilidad oficiales del gama media con 7.000 mAh de bater\u00eda<\/em>. Xataka. <a href=\"https:\/\/www.xataka.com\/moviles\/samsung-galaxy-m51-llega-a-espana-precio-disponibilidad-oficiales-gama-media-7-000-mah-bateria\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.xataka.com\/moviles\/samsung-galaxy-m51-llega-a-espana-precio-disponibilidad-oficiales-gama-media-7-000-mah-bateria<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Noticias de m\u00f3viles. (2020). <em>El Samsung Galaxy M51 tendr\u00eda 7.000mAh de bater\u00eda y m\u00e1s<\/em> [Imagen]. El Rinc\u00f3n de China. <a href=\"https:\/\/elrincondechina.com\/noticias\/noticias-de-moviles-smartphones\/el-samsung-galaxy-m51-tendria-7-000mah-de-bateria-y-mas\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/elrincondechina.com\/noticias\/noticias-de-moviles-smartphones\/el-samsung-galaxy-m51-tendria-7-000mah-de-bateria-y-mas\/<\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>La famosa y reconocida marca coreana de productos tecnol\u00f3gicos SAMSUNG, hace unos meses hizo el lanzamiento de su Galaxy M51, un celular con el cual busca tener una relevancia importante dentro del mercado de m\u00f3viles de gama media; imperando sobre todas las novedades tecnol\u00f3gicas, la gran capacidad de bater\u00eda queSeguir Leyendo<\/p>\n","protected":false},"author":72,"featured_media":2522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[3,34],"tags":[116,99,89,421,422,432],"class_list":["post-2521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-android","category-smartphones","tag-android","tag-celulares","tag-nuevo","tag-samsung","tag-samsung-galaxy","tag-smartphone"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Samsung impacta en el mercado de la gama media con nuevo celular<\/title>\n<meta name=\"description\" content=\"Samsung hizo el lanzamiento de su Galaxy M51, con el que busca tener una relevancia importante dentro del mercado de m\u00f3viles de gama media.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Samsung impacta en el mercado de la gama media con nuevo celular\" \/>\n<meta property=\"og:description\" content=\"Samsung hizo el lanzamiento de su Galaxy M51, con el que busca tener una relevancia importante dentro del mercado de m\u00f3viles de gama media.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-03T00:39:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-03T00:39:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/80samsunggalaxym51_2_original.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andres Felipe Avenda\u00f1o Junca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Felipe Avenda\u00f1o Junca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Samsung impacta en el mercado de la gama media con nuevo celular","description":"Samsung hizo el lanzamiento de su Galaxy M51, con el que busca tener una relevancia importante dentro del mercado de m\u00f3viles de gama media.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/","og_locale":"es_ES","og_type":"article","og_title":"Samsung impacta en el mercado de la gama media con nuevo celular","og_description":"Samsung hizo el lanzamiento de su Galaxy M51, con el que busca tener una relevancia importante dentro del mercado de m\u00f3viles de gama media.","og_url":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2020-11-03T00:39:47+00:00","article_modified_time":"2020-11-03T00:39:49+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/80samsunggalaxym51_2_original.jpg","type":"image\/jpeg"}],"author":"Andres Felipe Avenda\u00f1o Junca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Felipe Avenda\u00f1o Junca","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/"},"author":{"name":"Andres Felipe Avenda\u00f1o Junca","@id":"https:\/\/niixer.com\/#\/schema\/person\/2b0bafc50f372f80e7f3cd6d990128cf"},"headline":"Samsung impacta en el mercado de la gama media con nuevo celular","datePublished":"2020-11-03T00:39:47+00:00","dateModified":"2020-11-03T00:39:49+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/"},"wordCount":481,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/80samsunggalaxym51_2_original.jpg","keywords":["Android","Celulares","Nuevo","Samsung","Samsung Galaxy","Smartphone"],"articleSection":["Android","Smartphones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/","url":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/","name":"Samsung impacta en el mercado de la gama media con nuevo celular","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/80samsunggalaxym51_2_original.jpg","datePublished":"2020-11-03T00:39:47+00:00","dateModified":"2020-11-03T00:39:49+00:00","description":"Samsung hizo el lanzamiento de su Galaxy M51, con el que busca tener una relevancia importante dentro del mercado de m\u00f3viles de gama media.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/80samsunggalaxym51_2_original.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/80samsunggalaxym51_2_original.jpg","width":800,"height":445,"caption":"celular Samsung Galaxy M51"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2020\/11\/02\/samsung-impacta-en-el-mercado-de-la-gama-media-con-nuevo-celular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Samsung impacta en el mercado de la gama media con nuevo celular"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/2b0bafc50f372f80e7f3cd6d990128cf","name":"Andres Felipe Avenda\u00f1o Junca","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","caption":"Andres Felipe Avenda\u00f1o Junca"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/aavendanoju\/"}]}},"jetpack_featured_media_url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/11\/80samsunggalaxym51_2_original.jpg","_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/2521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=2521"}],"version-history":[{"count":1,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/2521\/revisions"}],"predecessor-version":[{"id":2523,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/2521\/revisions\/2523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/2522"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=2521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=2521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=2521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}