{"id":23514,"date":"2022-04-08T19:56:45","date_gmt":"2022-04-09T00:56:45","guid":{"rendered":"https:\/\/niixer.com\/?p=23514"},"modified":"2022-04-08T20:13:44","modified_gmt":"2022-04-09T01:13:44","slug":"tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/","title":{"rendered":"Tutorial de texturas sobre modelos 2D y 3D en blender"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.blender.org\/\">Blender <\/a>es una suite que nos permite visualizar objetos 3D, asi c\u00f3mo realizar animaciones, ediciones de video, entre otras funcionalidades. En esta ocasi\u00f3n, se mostrar\u00e1 un tutorial para aplicar texturas sobre modelos 2D y 3D.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tutorial: C\u00f3mo hacer un cono de tr\u00e1nsito en blender<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para comenzar con el tutorial, se realizar\u00e1 un cono de tr\u00e1nsito en <a href=\"https:\/\/www.blender.org\/\">blender<\/a>; por lo tanto iniciaremos creando un plano utilizando la combinaci\u00f3n de teclas Shift + A<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/BabIzZeMJ4l37zM5G9tCOMGM6glTlVUDUe02pScemeWTe0txVjoaZ15rOxKrcSZdrEB5RAyvZSAc4FjDKN7f6tL1SEHYQqhu00EVx4IItpQ82tgxMOknos1pUxUxDB0mGNk7H2A7\" alt=\"\" width=\"613\" height=\"439\"\/><figcaption><em>Creaci\u00f3n de plano<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Luego pasamos al modo de edici\u00f3n, damos clic derecho sobre el plano y seleccionamos la opci\u00f3n de subdivisi\u00f3n. Esto se realizar\u00e1 dos veces para obtener un resultado m\u00e1s \u00f3ptimo al momento de suavizar bordes<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/kVUpihz8KMnvQURsnEPnF6j2mDwpq0QlUS0lxGoYjLTIaZ7e7ukOqscJCPoRN5xLrL_IQDTn9h-tSmsMcd6mJlx7CSt9fSo9rX5lKmqxbbO-GUgU3JfSm1deRYqKLyx4FPkWmkso\" alt=\"\" width=\"611\" height=\"390\"\/><figcaption><em>Subdivisi\u00f3n del plano<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Como siguiente paso, se seleccionan todos los v\u00e9rtices de las esquinas, se da clic\u00a0derecho y se selecciona la opci\u00f3n de biselar v\u00e9rtices. Para a\u00f1adir o quitar segmentos, se\u00a0debe utilizar la rueda del mouse. Esto genera un efecto de redondeado sobre el plano:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/sEITxIo1nArxu_6bO0j2E6EMhFxIcxlse6AOG03B7Mk2zRQIXfkKq9ihIB4fWm4ZAH2D1PEdL3NwAjbS3oWhfBta3bbsNpjwsl5rla37kq1Svgy1VWDPQjIPD_JHWCAkXstwUfUJ\" alt=\"\" width=\"591\" height=\"393\"\/><figcaption><em>Biselado de v\u00e9rtices del plano<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Seguidamente, se realiza una selecci\u00f3n total (A) y se realiza una <a href=\"https:\/\/docs.blender.org\/manual\/en\/2.80\/modeling\/meshes\/editing\/duplicating\/extrude.html\">extrusi\u00f3n <\/a>sobre el eje z positivamente.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/daW2Bd22rEsJ1atw9BJg1gtIY0x0ypgVNHXJwqMIJd3QpUuxSkG6tfrqpOfWWcS5Bp5YCb4U9AWAJmIIAnisH6LTAhUSRrHrO54iHSg60LapEBMuKVVQdgAmSYinLj8zdFamQDsq\" alt=\"\" width=\"474\" height=\"321\"\/><figcaption><em>Extrusi\u00f3n de plano<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00fan con todos los v\u00e9rtices seleccionados, se crea una nueva cara interna (tecla I) y luego se redondean las caras haciendo uso de la combinaci\u00f3n de teclas Alt + Shift + S<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/gLi3t06ITGtEBcENXnUD8_HEp5T7FAvDn1gkpNYrzXUQ5dwC7npbKqXh_qk7HnGEKFEieNZYFWGYOxuBmfX1w_afQB3bo93sSmctiBj3B9FzOee8p14XzeXDUzrOodfY4BVv03S_\" alt=\"\" width=\"345\" height=\"283\"\/><figcaption><em>Caras internas redondeadas<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizando la<a href=\"https:\/\/docs.blender.org\/manual\/es\/dev\/editors\/3dview\/navigate\/projections.html\"> vista ortogonal<\/a>, se observa que hay un v\u00e9rtice que est\u00e1 negativamente sobre el eje Z. Por lo tanto, para corregir esto, se selecciona dicho v\u00e9rtice y se realiza un movimiento sobre el eje Z utilizando la tecla G, logrando as\u00ed que todas las caras superiores queden alineadas.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">   <img loading=\"lazy\" decoding=\"async\" width=\"343\" height=\"220\" src=\"https:\/\/lh5.googleusercontent.com\/YmGinTGjhef2FEWDHC7HzXup71lqQyJJppDbN7RtNV5vHBYTBtZbRIKZSyPxSmCHxDtlok50sHD3ZD3c9RBWfEkmtNXO0lVRkpkHAgUG34IAZUAwfAQxYJpG4jN8BXlm5Cm8RTEd\"><\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/1O_7rQgFCW9W6AWxLpio5nM9KEonnCVW3LArHAHr-cnl1vBhZGXkepmtdMZUHal57BcVXZa9UES4Jy84McEoJpP9CvgO0uwrhiootIlEJXukrPOGDvjK_eIPsm6l4Wd9HkS-46Y1\" alt=\"\"\/><figcaption><em>V\u00e9rtice desalineado<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/YmGinTGjhef2FEWDHC7HzXup71lqQyJJppDbN7RtNV5vHBYTBtZbRIKZSyPxSmCHxDtlok50sHD3ZD3c9RBWfEkmtNXO0lVRkpkHAgUG34IAZUAwfAQxYJpG4jN8BXlm5Cm8RTEd\" alt=\"\"\/><figcaption><em>Caras alineadas<\/em><\/figcaption><\/figure><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Modelando la parte superior del cono de tr\u00e1nsito<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como siguiente paso, se seleccionan todas las caras superiores inferiores, luego se realiza una extrusi\u00f3n (tecla E) positivamente sobre el eje Z y por \u00faltimo se realiza un <a href=\"https:\/\/appgametutoriales.com\/atajos-para-mover-escalar-y-rotar-en-blender\/\">escalamiento<\/a> (tecla S) hacia adentro para que el objeto tome la figura de un cono.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/7C4h__BREaPauZZL-uAOvktg6ED29pqzspUg_GAbd9RQy0m5hea0HjA5luR1mVQSbL0JfE5mzJPJ8P47D6QjLn36WGpqfCyrv7-OKo3y88EsLN7QPxkF5iJDJZGZUMKjHfPITErh\" alt=\"\" width=\"375\" height=\"297\"\/><figcaption><em>Cono formado<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, se agrega una cara interna y se realiza una extrusi\u00f3n hacia abajo, para lograr el efecto del vaci\u00f3 dentro del cono. Despu\u00e9s de esto, se realiza un corte en bucle utilizando las teclas Ctrl + R y se a\u00f1aden o se quitan cortes utilizando la rueda del mouse<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/5VxIhWCfOKJpoTjak26r9xL7R6YF6JSOqgckwCWXk_z8ijoERuHWQA6icNu2Rlpiu47WkDgUJSoKZ1hLxDIljxtUoTUqfBKJftbyR-fgAzDyBCfQqTranoy9G9t6RCGxaARZ0hJU\" alt=\"\" width=\"284\" height=\"305\"\/><figcaption><em>Cono con hueco<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/ZTe51dn4Ux_BJml3VsASybYSdsIJHVnVRNfoCRv2GpGHOJjCklltTtApZceUiKwysnjzLvujKXNreHVzCIF0EPT3sQtV356hDqMH-ZLLShWREpmQiadU4o4kXt_WlHSc8xWyQrr8\" alt=\"\" width=\"295\" height=\"320\"\/><figcaption><em>Cono con cortes<\/em><\/figcaption><\/figure><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Tutorial de texturas: Cono de tr\u00e1nsito<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ya con el objeto creado, se procede a agregar el material de texturas para el cono dando clic en el icono de materiales que se encuentra en el men\u00fa de la derecha. En esta opci\u00f3n se selecciona superficie y BSDF Difuso, luego, se da clic al c\u00edrculo dentro de la opci\u00f3n de <em>\u201cColor\u201d <\/em> y se selecciona la opci\u00f3n de imagen.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/tyo_ZY1XLNet1b27RldzpT74y7Jz2aUodOga2cUNiF7NK4eWAVAJZPDp4EytOhFOZNzGttLpBLG8ob8yE59ieL56tq5g4kAtWD_QAEyNPNJAHR07J78SKNO0z1Hp86cIPCA3uQcv\" alt=\"\" width=\"333\" height=\"511\"\/><figcaption><em>&nbsp;Opci\u00f3n materiales<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/cnmXokAwsy_20ls7ylXugolTQiJvVmk0cIhMsqDNP-WvOnKp2-P9I1rFPahnxm8_hpwXC1EJRk6U-BrDRugJhbC27iB9Nz48hj8fjf2tHSAcTk_cyM_Hw27dqpcoABJAvNCgrmD2\" alt=\"\" width=\"349\" height=\"383\"\/><figcaption><em>Superficie<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/9KDPs9YhVkgXLoA0HOk6Hhl3YL92gh9SvfxN1QcW8oAp9ociBYBVFENa1eyh9zEDvDbHn4cdHRFJuLqInqb5HT7z2-M70FC1mq12T5a__SQzu3rlEqq2NFPeyD0nXtaW7Oa0tZTD\" alt=\"\" width=\"399\" height=\"318\"\/><figcaption><em>Imagen de textura<\/em><\/figcaption><\/figure><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Se selecciona la imagen de la textura, y se da clic en la opci\u00f3n de Edicion UV dentro del men\u00fa superior.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/s4gh-40La78yTyKUki01NTZd9lehDFMMOxWMcGNyy8DO4lNH2ocTlyfyTqVP-NDNVwbpe4RHNIIhdtf-0fpfqnSifa2cW6Idjz_vwadIQIoBHfzDntFo3JZB90VKawFg3YoIDoWf\" alt=\"\" width=\"801\" height=\"233\"\/><figcaption><em>Edici\u00f3n UV<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Luego dentro de la edici\u00f3n UV, se selecciona la imagen de la textura dando clic en la siguiente opci\u00f3n.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/A2bB8sTsU2CfvWvo2lHe7dBKKEHf4hfmyDrftwWI5JlSDJRo9iStVApTgv23sHvYmwmtRO4mCgfwEywUi0FRKSW5Fo1CsBNqM9EndHJMsgILePtBQj35YgI6kAjUUv7A1N1GuwBw\" alt=\"\" width=\"428\" height=\"468\"\/><figcaption><em>Selecci\u00f3n de textura en edici\u00f3n UV<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Como paso siguiente, se seleccionar\u00e1n todas las caras que est\u00e9n por encima de la base del cono. Para esto se da clic en la opci\u00f3n <em>\u201cWireframe\u201d <\/em>para poder seleccionar m\u00e1s f\u00e1cil las caras del cono y se realiza una selecci\u00f3n arrastrando el mouse.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/AeI7ypITEdKGuxFuO2mt0vJqFA6XlayJlPLM8MxsYUxPEML8sXDKrGKjmPSkxU6vwA_sQQ0TwmjEB6NSVfl1VU9ME-X1tCv7LDuBeP9Yzz4dMhZjFR8LgX7mqbgnaLzXIGnWN0wG\" alt=\"\" width=\"379\" height=\"468\"\/><figcaption><em>Selecci\u00f3n caras del con<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Hecho esto, se da clic derecho sobre las caras seleccionadas y se da clic en la opci\u00f3n de <em>\u201cCube Projection\u201d <\/em>dentro de la opci\u00f3n de <em>\u201cUV Unwrap faces\u201d<\/em>, luego, dentro de la edici\u00f3n UV se observar\u00e1 el cono de la siguiente manera.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/dpH_qXF9kfTttim4urpQV0MHeiHY026mRGg2P4vLodYmku-wxSnNIHajRbfElWDg-pKIRHTXgmz257udvbUyta6peV1DARVXzWQdFW5lAaim5O88NpXg7wb5-KelKH0879rwbKzX\" alt=\"\" width=\"353\" height=\"313\"\/><figcaption><em>&nbsp;Proyecci\u00f3n de cubo<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/cebldKISnasHkjb2Gh98C7FXMhYJVA1tqDZUKuUb4Te2E_GmUSA8A535ATw6FeVhGK0e1_1kE285hJCnBo5SzRYIMbSajDYynKd0EUB89ortNz5Uc9o6INM3k5uKa0CXJ1K4qvWV\" alt=\"\" width=\"213\" height=\"258\"\/><figcaption><strong><em>Cono en edici\u00f3n UV<\/em><\/strong><\/figcaption><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Damos clic en la tecla A para seleccionar todo dentro de la edici\u00f3n UV, luego se realiza un movimiento hacia arriba (Tecla G) para que la silueta del cono quede alineada con la imagen de la textura. Con lo anterior, ya para finalizar, nos dirigimos al modo objeto y seleccionamos la opci\u00f3n para mostrar las texturas, por lo tanto, el resultado es el siguiente:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/xioFUvjOT315kqgpGW16QnJ9OkhZktQmQxHd_MBxI7-CHMYPwrQM8QHXxzH6hZ3O0l3wF_-d688DJHsK-f2NdgqW2jbgp4l5kCleOyPRl2P3hmkGAaqlfBuA3fhmawGlOPa2o16L\" alt=\"\" width=\"238\" height=\"248\"\/><figcaption><em>Silueta alineada con textura<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/ZPORPIktsRXdRP70370SeS6mxvGPlZoX8uWqMd5aTPUZFm6Xd2xdER9Bw5iAuLhpbUUD-tnIEgKEgplJQyyxcYAldU9Yu5fx3FF-uMDyF6tD6JgKcLysv8FGqWsb6BYZPo50k_HG\" alt=\"\" width=\"832\" height=\"528\"\/><figcaption><em>Textura aplicada al cono<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Tutorial: C\u00f3mo hacer una llanta de autom\u00f3vil en blender<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para la creaci\u00f3n de la llanta del autom\u00f3vil, primero creamos un c\u00edrculo y lo rotamos 90 grados sobre el eje Y<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/gwshdnFU5rpK2Fta7-ZXF1eK7I2oE_nRDwrq5Gf6ysFdHIQbOTdmp5TcYfAmhkzEAaV0LdiefmMmG9ikVt0PIE40avaKKONov6WnXb3E1GEG5b_qlO32pmQt0VnkAEUrIerMR5sw\" alt=\"\" width=\"317\" height=\"271\"\/><figcaption><em>C\u00edrculo rotado 90 grados<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Pasamos al modo edici\u00f3n y damos clic en la opci\u00f3n para seleccionar los v\u00e9rtices, luego desplazamos sobre el eje x positivamente, de tal manera que quede un espacio de un cuadro entre el punto de origen y el c\u00edrculo, para esto se utiliza la vista ortogonal frontal<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/3l8AQAhN1RlmA1aHfxc9Gsja2fR_WbpfMYuiV77Dwn5ilsnT4YASFfkjYzHFDC8kGdEX4sdk2U47GTTn4rHwSgcvxG-EEj7wNGSthlWOdyRFoMRQfHBu4eovPhPAzlvKBt7HIbA-\" alt=\"\" width=\"468\" height=\"414\"\/><figcaption><em>C\u00edrculo desplazado<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Como siguiente paso, nos dirigiremos a la opci\u00f3n de modificadores (icono de llave inglesa en men\u00fa derecho) y luego agregamos el modificador de Espejo<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/Zb9YnuWx53QA-BonUK4hhQsOEhZlcEndMCttgbOXWRIPlKRa_rDoHreQUYmpyzu7SLAH4Z7MMPOm8ciYCGgYAzq6cr1o0lI4fTlBNJWzd5UiLkbI6BzoEFlGt1iIcoo39sffLE0L\" alt=\"\" width=\"472\" height=\"332\"\/><figcaption><em>Modificador espejo<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro del modificador seleccionamos la opci\u00f3n de clipping para trabajar \u00fanicamente con una parte del espejo y como siguiente paso, en la edici\u00f3n de objetos, seleccionamos la opci\u00f3n de objeto \u2013 aplicar \u2013 rotaci\u00f3n y escala.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/vPIKCOXTU1LIXwmj9jkfBcE2E4Vm3NLn6k-0s4vVdpG1DGfGd5-rhI2vuqEq-D48cF85oeFBnu89S9Y7gaOLMX3FTso1foVJyCXa1bi2TZoSoJsZAFpI87KBaJxcUelYeeM2ajXJ\" alt=\"\" width=\"595\" height=\"310\"\/><figcaption><em>Rotaci\u00f3n y escala reflejados<\/em><\/figcaption><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/n1dSKP_sQgFkbBCMqdRUIduOSQSgZ-gOw8ccg_BwwbIVdNcV9XWyDj4YxwCHNmWz6euJyZGxSDOLbSUhA_P43w1_vxiP5NpWvVRZiaDqPxlnDZoGto3HkESX79yIWTFswktsciwz\" alt=\"\" width=\"508\" height=\"406\"\/><figcaption><em>C\u00edrculos duplicados<\/em><\/figcaption><\/figure><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Cambiamos al modo edici\u00f3n y extruimos hacia adentro para formar la llanta, luego seleccionamos los v\u00e9rtices exteriores con la combinaci\u00f3n de teclas Shift + Alt + Clic derecho, cambiamos el modo de extrusi\u00f3n dejando presionado el clic sobre la opci\u00f3n de extruir y seleccionamos extrusi\u00f3n a lo largo de las normales. A partir de esto, se realiza una extrusi\u00f3n hacia adentro.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/hb3rg_ASlzE4eI3o-H4S7hkadbhmV_BOW7EUWJGC8dQCHam_gKAR2cxvu0ao6Lup1kCv00bv0c1R4X4D9ScfWPvwVwJ3MEYyyCoV9CNwvEJYn_TmPsEjp1Dua3TTYaGdAmIR-AEI\" alt=\"\" width=\"713\" height=\"419\"\/><figcaption><em>&nbsp;Extrusi\u00f3n hacia adentro<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Realizamos dos cortes en la mitad de la rueda con la combinaci\u00f3n de teclas Ctrl + R para luego realizar otros dos cortes mas dejando un peque\u00f1o espacio entre los dos cortes resultantes, por \u00faltimo se realiza la misma extrusi\u00f3n que se realiz\u00f3 en el paso anterior.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/tgSS1HvM4zGdMu1PBEp15P9eiRXVGvYUHyOJrY9sL5HPwmUltlRd4pJKs5i4n0tdodj39anmeEDXDp6APNFihIxHy5uwW-IS7TFnx8BsfeIIH9HdwqwXBSeQ-KcFyVgA7hmFTdd5\" alt=\"\" width=\"500\" height=\"415\"\/><figcaption><em>Extrusi\u00f3n sobre la normal<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Seleccionamos la l\u00ednea de la mitad con el modo de selecci\u00f3n de aristas, y se realiza una rotaci\u00f3n sobre el eje x, dando como resultado lo siguiente:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/v1-ePAIcsqXP1lMfPHNSJWIsRzthHQKbSqhxTEN39XLZJmkAks5ybd1JIHQEWQ7zuQw3WdveDe_Do4K6EahNoM2aW_w2JKaCmGh-qW8Nhqjm_MnqttZKXeYX0itOVqxyTMSAj9_m\" alt=\"\" width=\"336\" height=\"320\"\/><figcaption><em>Rotaci\u00f3n sobre la l\u00ednea central de la llanta<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Aplicando texturas a llanta de autom\u00f3vil<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de este tutorial, se observar\u00e1 como aplicar <a href=\"https:\/\/niixer.com\/index.php\/2022\/04\/08\/texturas-iluminacion-2d-y-3d\/\">texturas <\/a>a este tipo de modelos 3D, tal y como lo es la llanta de un autom\u00f3vil. Primero, agregamos un nuevo modificador de subdivisi\u00f3n de caras y luego agregamos el material de la textura que queremos. Para este caso se <a href=\"https:\/\/niixer.com\/index.php\/2022\/04\/08\/texturas-iluminacion-2d-y-3d\/\">utilizar\u00e1n dos texturas<\/a>, una para la parte lateral de la rueda y as\u00ed mismo, otra textura para la parte superior. Para el lateral de la rueda, se agregar\u00e1 el siguiente material<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/jbZf342mAgaAxwgytyn5l7eGpOr1YIp8V4uUbr4yrV5roKY4Ib7DicvcoKp4tBT-NKy1cpc5P_8kspsFrfut9w1b4tUWmWHNzZUmF9-8uIVKPt0auoMISf9wDOjBDfjxX3XEvfM-\" alt=\"\" width=\"540\" height=\"276\"\/><figcaption><em>Tutorial textura lateral de llanta<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para la parte superior de la llanta, se utilizar\u00e1 otra textura, por lo cual es necesario que al dar clic en la opci\u00f3n de UV se seleccione la opci\u00f3n de proyecci\u00f3n de cubo para que se logren acoplar las caras a la textura.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/9M46l89GVuOhX0qsRKsV8FaD2AykxG6wrF1ciF_h6gkpgDl2idvaUeFYOnQ0A15vzJqwvqYBCbAu7CwG8ktXaTaFyWdoq0Fmbck8aKUHzXe5_I1t_eLnCK0BiFPLir88RZ_c0gKj\" alt=\"\" width=\"736\" height=\"522\"\/><figcaption><em>Textura superior de la llanta<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para concluir este tutorial, se crea una pared y un suelo para simular un peque\u00f1o escenario, dentro del cual se a\u00f1adiran los <a href=\"https:\/\/niixer.com\/index.php\/2022\/04\/08\/guia-para-la-creacion-de-modelos-3d-y-2d-con-texturizado-e-iluminacion\/\">modelos <\/a>creados anteriormente adem\u00e1s de todos los <a href=\"https:\/\/niixer.com\/index.php\/2022\/04\/08\/guia-para-la-creacion-de-modelos-3d-y-2d-con-texturizado-e-iluminacion\/\">modelos <\/a>que pueden ser creados dentro de blender<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/xd67n-xFnBBejTu_-xstsYQHaNnLl2EBGWRGBQwJad8jUqGXsz89rcvS3d77DjHw-M95FaDbtbr4KrP9j-pzOoZlikinc2iHIMb-7PQbpIrzHjH4FxOTndaUqS4cKMlAUSYh_nCQ\" alt=\"\" width=\"739\" height=\"372\"\/><figcaption><em>Modelo de suelo con textura aplicada<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/CaGcHD6SZ5JoEm6pz4XRO02vZWUpIhjlrwLP_3ox6qO8N4c0g3Px6D6eJBmaYGuY4qbdbp261WTl8aXJvhczboWVzT8mrdtYckZHypedNaA7PsmkU3L9iO6RonzgDFW2aKZ_ilEe\" alt=\"\" width=\"482\" height=\"253\"\/><figcaption>Modelo de pared con textura aplicada<\/figcaption><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Escenario final<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/NfqmD0jtwGP2VQjosUdXWQ_eXh7rNZDO_RANsAWxR8Xfomvxzz-TSzxBK7cLCcwIF0UmLIoy80SpTIf8GXZNJ5iQ_2lt2UdrrYDVC49dZWk2t03YJPPsW8ne7EhHvlm6Sf4YNAC5\" alt=\"\"\/><figcaption>Escenario final<\/figcaption><\/figure><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En la imagen anterior, se puede observar el escenario final, aplicando iluminaci\u00f3n y agregando diferentes tipos de modelos, que as\u00ed mismo aportan a la est\u00e9tica total del escenario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autor: <a href=\"https:\/\/niixer.com\/?s=Sebastian+Cardenas+Due%C3%B1as\">Sebasti\u00e1n C\u00e1rdenas Due\u00f1as<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Editor: Carlos Pinz\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3digo: UCMV-11<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad: <a href=\"https:\/\/www.ucentral.edu.co\/\">Universidad Central<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes:<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">blender lowpoly traffic cone. (2021, 1 septiembre). [V\u00eddeo]. YouTube. <a href=\"https:\/\/www.youtube.com\/watch?v=uDTBVspAXfs\">https:\/\/www.youtube.com\/watch?v=uDTBVspAXfs<\/a>\n<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">03 Tutorial de Blender en espa\u00f1ol, spanish - Poniendo texturas. (2013, 30 abril). [V\u00eddeo]. YouTube. <a href=\"https:\/\/www.youtube.com\/watch?v=di77T8TbTKM\">https:\/\/www.youtube.com\/watch?v=di77T8TbTKM<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Stylized Barrel in Blender 2.90 | Modelling | Sculpting | Textures. (2020, 29 septiembre). [V\u00eddeo]. YouTube. <a href=\"https:\/\/www.youtube.com\/watch?v=idOLEwF51jE\">https:\/\/www.youtube.com\/watch?v=idOLEwF51jE<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">2 ways to make a brick wall in blender 2.8. (2020, 2 junio). [V\u00eddeo]. YouTube. <a href=\"https:\/\/www.youtube.com\/watch?v=TXTTKvmGAPg\">https:\/\/www.youtube.com\/watch?v=TXTTKvmGAPg<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Stock photo tire texture. (s. f.). [Ilustraci\u00f3n]. Depositphotos. <a href=\"https:\/\/depositphotos.com\/28154737\/stock-photo-tire-texture.html\">https:\/\/depositphotos.com\/28154737\/stock-photo-tire-texture.html<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Arslan, I. (2018, 29 julio). FREE TEXTURES &gt;&gt; 3 Tire textures [Ilustraci\u00f3n]. 3DEmpire. <a href=\"https:\/\/3dempire.org\/free-textures-3-tire-textures\/\">https:\/\/3dempire.org\/free-textures-3-tire-textures\/<\/a>\n<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Modeling aand texturing a wooden crate. (2013, mayo). [Ilustraci\u00f3n]. Blenderartists.org. <a href=\"https:\/\/blenderartists.org\/t\/modeling-aand-texturing-a-wooden-crate\/574576\">https:\/\/blenderartists.org\/t\/modeling-aand-texturing-a-wooden-crate\/574576<\/a>\n<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Tuytel, R. (s. f.). Green Metal Rust [Ilustraci\u00f3n]. Poly Heaven. <a href=\"https:\/\/polyhaven.com\/a\/green_metal_rust\">https:\/\/polyhaven.com\/a\/green_metal_rust<\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Blender es una suite que nos permite visualizar objetos 3D, asi c\u00f3mo realizar animaciones, ediciones de video, entre otras funcionalidades. En esta ocasi\u00f3n, se mostrar\u00e1 un tutorial para aplicar texturas sobre modelos 2D y 3D. Tutorial: C\u00f3mo hacer un cono de tr\u00e1nsito en blender Para comenzar con el tutorial, seSeguir Leyendo<\/p>\n","protected":false},"author":46,"featured_media":24112,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[30],"tags":[1156,1352,1946],"class_list":["post-23514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-niixer","tag-iluminacion-2","tag-modelado-3d","tag-texturas-con-blender"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tutorial de texturas sobre modelos 2D y 3D en blender<\/title>\n<meta name=\"description\" content=\"Tutorial para la creaci\u00f3n de un escenario compuesto por diferentes modelos 3D y 2D aplicando texturas en blender.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tutorial de texturas sobre modelos 2D y 3D en blender\" \/>\n<meta property=\"og:description\" content=\"Tutorial para la creaci\u00f3n de un escenario compuesto por diferentes modelos 3D y 2D aplicando texturas en blender.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-09T00:56:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-09T01:13:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2022\/04\/escenario-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"995\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sebastian Cardenas Due\u00f1as\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sebastian Cardenas Due\u00f1as\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tutorial de texturas sobre modelos 2D y 3D en blender","description":"Tutorial para la creaci\u00f3n de un escenario compuesto por diferentes modelos 3D y 2D aplicando texturas en blender.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/","og_locale":"es_ES","og_type":"article","og_title":"Tutorial de texturas sobre modelos 2D y 3D en blender","og_description":"Tutorial para la creaci\u00f3n de un escenario compuesto por diferentes modelos 3D y 2D aplicando texturas en blender.","og_url":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2022-04-09T00:56:45+00:00","article_modified_time":"2022-04-09T01:13:44+00:00","og_image":[{"width":995,"height":608,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/04\/escenario-2.png","type":"image\/png"}],"author":"Sebastian Cardenas Due\u00f1as","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sebastian Cardenas Due\u00f1as","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/"},"author":{"name":"Sebastian Cardenas Due\u00f1as","@id":"https:\/\/niixer.com\/#\/schema\/person\/f45de5e04c9194c3218c16b740519871"},"headline":"Tutorial de texturas sobre modelos 2D y 3D en blender","datePublished":"2022-04-09T00:56:45+00:00","dateModified":"2022-04-09T01:13:44+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/"},"wordCount":1310,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/04\/escenario-2.png","keywords":["iluminaci\u00f3n","modelado 3D","Texturas con Blender"],"articleSection":["Niixer"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/","url":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/","name":"Tutorial de texturas sobre modelos 2D y 3D en blender","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/04\/escenario-2.png","datePublished":"2022-04-09T00:56:45+00:00","dateModified":"2022-04-09T01:13:44+00:00","description":"Tutorial para la creaci\u00f3n de un escenario compuesto por diferentes modelos 3D y 2D aplicando texturas en blender.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/04\/escenario-2.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/04\/escenario-2.png","width":995,"height":608,"caption":"Tutorial escenario final blender"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2022\/04\/08\/tutorial-de-texturas-sobre-modelos-2d-y-3d-en-blender\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Tutorial de texturas sobre modelos 2D y 3D en blender"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/f45de5e04c9194c3218c16b740519871","name":"Sebastian Cardenas Due\u00f1as","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68fbbe1ee2f8e190992a32ca1b2b67be3e5ba6a0b9c345ca5211c75b2d375db2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68fbbe1ee2f8e190992a32ca1b2b67be3e5ba6a0b9c345ca5211c75b2d375db2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68fbbe1ee2f8e190992a32ca1b2b67be3e5ba6a0b9c345ca5211c75b2d375db2?s=96&d=mm&r=g","caption":"Sebastian Cardenas Due\u00f1as"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/scardenasd\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/23514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=23514"}],"version-history":[{"count":10,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/23514\/revisions"}],"predecessor-version":[{"id":24125,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/23514\/revisions\/24125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/24112"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=23514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=23514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=23514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}