{"id":22743,"date":"2022-03-30T16:10:26","date_gmt":"2022-03-30T21:10:26","guid":{"rendered":"https:\/\/niixer.com\/?p=22743"},"modified":"2022-03-30T16:10:28","modified_gmt":"2022-03-30T21:10:28","slug":"comentarios-de-wordpress","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/","title":{"rendered":"Comentarios de WordPress"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La secci\u00f3n de comentarios en <a href=\"https:\/\/www.hostinger.co\/tutoriales\/plugin-comentarios-wordpress#:~:text=Sistema%20de%20comentarios%20original%20de%20WordPress,-Para%20comenzar%2C%20WordPress&amp;text=Puedes%20ordenar%2C%20leer%20y%20rastrear,yendo%20a%20Configuraci%C3%B3n%20%2D%3E%20Discusi%C3%B3n.\" target=\"_blank\" rel=\"noreferrer noopener\">WordPress<\/a> es un espacio qe permite a tus usuarios interactuar con los autores del contenido, dejando marcas que pueden mejorar la reputaci\u00f3n de tu sitio y convertirlo en un referente. Primero, WordPress ya viene con un sistema de comentarios nativo que le permite crear una secci\u00f3n de comentarios en cada p\u00e1gina web. Los comentarios en WordPress son una de las principales caracter\u00edsticas de los blogs, ya que permiten a los lectores dejar respuestas en las publicaciones.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/s3.amazonaws.com\/s3.timetoast.com\/public\/uploads\/photo\/2594033\/image\/057eb8086fc1b88da665c002b4cf6ec1\" alt=\"Historia de WordPress timeline | Timetoast timelines\" width=\"240\" height=\"240\" \/><figcaption>Timetoast, t. (2022). Historia de WordPress [IMAGEN]. Recuperado:https:\/\/www.timetoast.com\/timelines\/historia-de-wordpress<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A menudo, se utilizan para compartir opiniones sobre el contenido de una publicaci\u00f3n, vincular a otros recursos, generar debate o simplemente felicitar al autor por la calidad del art\u00edculo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cualquier caso, los comentarios en WordPress le permiten interactuar m\u00e1s con los visitantes de su sitio web y generar comentarios y conversaciones en su blog. Adem\u00e1s, son un factor que beneficia al <a href=\"https:\/\/platzi.com\/clases\/2314-terminos-marketing-digital\/37583-que-es-seo-posicionamiento-en-buscadores\/?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=12915366154&amp;utm_adgroup=&amp;utm_content=&amp;gclid=EAIaIQobChMIupyZxfXs9gIVSVtyCh00PAztEAAYASAAEgIGk_D_BwE&amp;gclsrc=aw.ds\" target=\"_blank\" rel=\"noreferrer noopener\">SEO<\/a> porque Google entiende que los art\u00edculos de rese\u00f1a son contenidos que aportan valor a los usuarios. As\u00ed que recuerda siempre responder a cualquier comentario que recibas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nada es m\u00e1s da\u00f1ino que un blog sin comentarios, y nada es m\u00e1s da\u00f1ino para la confianza de tus lectores que ver que no respondes. Por todas estas razones, debes saber c\u00f3mo administrar los comentarios en WordPress y fomentar el compromiso con tu contenido. Por eso, en este post te explicar\u00e9 paso a paso c\u00f3mo sacarles partido y enriquecer a\u00fan m\u00e1s tu art\u00edculo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ventajas y desventajas de la funci\u00f3n de comentarios en WordPress<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.tmwebs.es\/wp-content\/uploads\/wordpress-ventajas-desventajas.jpg\" alt=\"Ventajas y desventajas de wordpress - TM Marketing Online\" \/><figcaption>TM Marketing Online. (2019). Ventajas y desventajas de WordPress [IMAGEN]. Recuperado: https:\/\/www.tmwebs.es\/ventajas-desventajas-wordpress\/<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">La funci\u00f3n de comentar en WordPress es un arma de doble filo, tiene muchas ventajas y algunas desventajas que pueden interrumpir tu trabajo. Por un lado, la secci\u00f3n de comentarios en WordPress puede aumentar el tr\u00e1fico a tu sitio web\/blog.Por otro lado, la columna de comentarios tambi\u00e9n puede ser un foco de spam, as\u00ed como un nido de comentarios de odio y abuso que pueden tener un impacto negativo en la participaci\u00f3n de los usuarios. <\/p>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Estos comentarios son editables, pero moderar los comentarios tambi\u00e9n lleva mucho tiempo, lo que podr\u00eda ser muy problem\u00e1tico para la mayor\u00eda de las personas. Si bien es posible que no puedas evitar los riesgos anteriores, el uso de un plugin de comentarios de WordPress puede ser una soluci\u00f3n que vale la pena probar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Como Activar \/ Desactivar los comentarios de WordPress<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>WordPress tiene un sistema de comentarios nativo muy poderoso que permite respuestas e incluye ciertas etiquetas HTML (enlaces, negritas o incluso listas si el tema de WordPress que est\u00e1s usando lo permite). En primer lugar, es bueno que sepamos los estados de comentarios permitidos y cu\u00e1l se ajusta a nuestros objetivos<\/li><li>\u2022 Comentarios abiertos: los usuarios pueden comentar nuestros art\u00edculos. Esta es la opci\u00f3n por defecto, aunque tambi\u00e9n podemos filtrar qu\u00e9 usuarios pueden participar en la conversaci\u00f3n (por ejemplo, solo los usuarios registrados en nuestro WordPress)<\/li><li>\u2022 Comentarios cerrados: Hubo un tiempo en que los comentarios estaban abiertos, pero por alguna raz\u00f3n se cerraron. Todav\u00eda son legibles, pero no permiten m\u00e1s respuestas (\u00fatiles para publicaciones de tipo concurso, por ejemplo)<\/li><li><strong>Comentarios desactivados<\/strong>: los comentarios permanecen desactivados desde el primer momento de la publicaci\u00f3n del art\u00edculo.&nbsp;<strong>Nadie puede comentar ni responder.<\/strong>&nbsp;\u00datil cuando queremos hacer un anuncio o comunicado (personalmente no me gusta esta opci\u00f3n, pero entiendo puede ser \u00fatil en algunos casos)<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno, por defecto WordPress viene con una configuraci\u00f3n para habilitar los comentarios, pero puede pasar que despu\u00e9s de instalar una plantilla o deshabilitar un check, se desactiven los comentarios, ya sea para todo el sitio o para un art\u00edculo o post en espec\u00edfico. Veamos c\u00f3mo habilitar los comentarios para todo su sitio web con este art\u00edculo de nuestra serie de tutoriales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Activando \/ Desactivando comentarios para toda la web<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los comentarios se organizan desde la pesta\u00f1a&nbsp;<strong>Ajustes &gt; Comentarios del panel de Administraci\u00f3n de WordPress<\/strong>, muy cerca de los enlaces permanentes, que deber\u00edas tener ya configurados! Una vez dentro hay una serie de opciones que tenemos que comprobar c\u00f3mo marcadas o desmarcadas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"741\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/image-1.png\" alt=\"\" class=\"wp-image-22748\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/image-1.png 921w, https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/image-1-300x241.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/image-1-768x618.png 768w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><figcaption>Gobea, J. (2022). MANUAL DE WP] C\u00d3MO GESTIONAR Y EDITAR COMENTARIOS EN WORDPRESS [IMAGEN]. Recuperado:https:\/\/hormigasenlanube.com\/comentarios-en-wordpress\/ <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La fundamental es \u201cPermite que se publiquen comentarios en los art\u00edculos nuevos\u201d, que nos indica si todas las p\u00e1ginas y art\u00edculos tienen activados o desactivados los comentarios. Con esto podemos&nbsp;<strong>controlar todo nuestro sitio con un solo clic<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Activando \/ Desactivando comentarios en cada art\u00edculo, post o p\u00e1gina.<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se tiene todo <a href=\"https:\/\/niixer.com\/index.php\/2022\/03\/29\/editor-wordpress-gestion-de-contenidos\/\" target=\"_blank\" rel=\"noreferrer noopener\">WordPress<\/a> listo para que nos pueda dejar millones de comentarios (no te preocupes si nadie comenta los primeros meses, es normal, con el tiempo ver\u00e1s como se animan tus lectores!). Pero, \u00bfqu\u00e9 sucede si queremos deshabilitar los comentarios en un art\u00edculo espec\u00edfico? Pues para ello WordPress nos da la opci\u00f3n de desactivar los comentarios al detalle en cada art\u00edculo, entrada o p\u00e1gina. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para hacer esto, debe navegar hasta el art\u00edculo que desea editar en el panel de administraci\u00f3n: Publicaciones &gt; Todas las publicaciones y seleccionar el art\u00edculo que desea editar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/image-2.png\" alt=\"\" class=\"wp-image-22749\" width=\"920\" height=\"824\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/image-2.png 921w, https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/image-2-300x269.png 300w, https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/image-2-768x688.png 768w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><figcaption>Gobea, J. (2022). MANUAL DE WP] C\u00d3MO GESTIONAR Y EDITAR COMENTARIOS EN WORDPRESS [IMAGEN]. Recuperado:https:\/\/hormigasenlanube.com\/comentarios-en-wordpress\/ <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez dentro, debes hacer clic en la pesta\u00f1a \u201c<strong>Opciones de Pantalla<\/strong>\u201d ubicada en la parte superior derecha de la pantalla. Se nos desplegar\u00e1 un panel con varias opciones interesantes. Nosotros la que buscamos es \u201cComentarios\u201d. Aseg\u00farate de que est\u00e1 con el tic azul de \u201ccheck\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Gesti\u00f3n de Comentarios<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La gesti\u00f3n de los <a href=\"https:\/\/niixer.com\/index.php\/2021\/10\/06\/footer-en-wordpress\/\" target=\"_blank\" rel=\"noreferrer noopener\">comentarios<\/a> en WordPress la puedes realizar desde la opci\u00f3n &#8220;<em>Comentarios<\/em>&#8221; del men\u00fa lateral izquierdo. Una vez ah\u00ed, ver\u00e1s el listado completo de todos los comentaros, que puedes filtrar bajo los siguientes criterios:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Todos<\/strong>: listado completo con todos los comentarios que se hayan realizado.<\/li><li><strong>Pendientes<\/strong>: comentarios que se encuentran pendientes de supervisi\u00f3n. Tendr\u00e1s que decidir si aprobarlos, rechazarlos o marcarlos como spam.<\/li><li><strong>Aprobados<\/strong>: listado con todos los comentarios que est\u00e1n aprobados y, por tanto, que aparecen visibles en tu sitio web.<\/li><li><strong>Spam<\/strong>:&nbsp;comentarios considerados como SPAM. Es recomendable repasar esta lista por si se nos ha colado err\u00f3neamente alg\u00fan comentario v\u00e1lido. Si se diera el caso, al pasar el cursor por encima, ver\u00e1s la posibilidad de marcar el comentario como &#8220;<em>No es spam<\/em>&#8220;.<\/li><li><strong>Papelera<\/strong>: aqu\u00ed encontrar\u00e1s aquellos comentarios que hayas eliminado.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ajustes De Comentarios De WordPress<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En el panel de ajustes de WordPress hay un par de campos que sirven para poner cierto freno al spam y adem\u00e1s ayudar a moderar en cierta media los comentarios que dejan los usuarios en tu web o blog.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secci\u00f3n \u201c<strong>Moderaci\u00f3n de comentarios<\/strong>\u201d sirve para escribir frases o palabras clave que si apareciesen dentro de un comentario, de manera preventiva, lo dejar\u00e1 en moderaci\u00f3n para que requiera nuestra aprobaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La segunda opci\u00f3n que est\u00e1 disponible es la \u201c<strong>Lista negra de comentarios<\/strong>\u201d en la cual de forma personal se pueden a\u00f1adir frases, palabras o direcciones de correo que de aparecer en alg\u00fan campo de un comentario, lo enviar\u00e1n directamente a spam.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo Usarlos?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si, se reciben mensajes constantes siguiendo ciertos patrones, deber\u00e1s a\u00f1adir dicho patr\u00f3n o palabra clave para ahorrarte algo de trabajo.No obstante esto ser\u00e1 una soluci\u00f3n temporal que dif\u00edcilmente conseguir\u00e1 eliminar todos los intentos de los spammers por publicitarse en tu blog.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Video<\/strong>: <strong>Gesti\u00f3n de comentarios en WordPress (Tutorial)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se puede evidenciar un mejor resumen sobre los comentarios de WordPress, como es su utilidad, como se maneja mejor.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Gestio\u0301n de comentarios en WordPress (Tutorial Plugin Disqus)\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/ICi8NgSnpr8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>Fernandes, A. (2020). Gesti\u00f3n de comentarios en WordPress (Tutorial Plugin Disqus) [Video]. Recuperado: https:\/\/www.youtube.com\/watch?v=ICi8NgSnpr8<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor:<\/strong> Edinson Estid Cardenas Ram\u00edrez<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor: <\/strong>Carlos Pinz\u00f3n <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad:<\/strong> <a href=\"https:\/\/www.ucentral.edu.co\/\">Universidad Central <\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo:<\/strong> UCPW-81<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong><\/h3>\n\n\n\n<pre class=\"wp-block-preformatted\">Gobea, J. (2022). MANUAL DE WP] C\u00d3MO GESTIONAR Y EDITAR COMENTARIOS EN WORDPRESS [IMAGEN]. Recuperado:https:\/\/hormigasenlanube.com\/comentarios-en-wordpress\/ \n<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Timetoast, t. (2022). Historia de WordPress [Blog]. Recuperado:https:\/\/www.timetoast.com\/timelines\/historia-de-wordpress<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Deyimar, A. (2022). \u00bfBuscando un plugin de comentarios para WordPress? Te damos 9 alternativas [IMAGEN]. Recuperado:hostinger.co\/tutoriales\/plugin-comentarios-wordpress<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Aranda, J. (2022). Gestion de Comentarios en WordPress [Blog. Recuperado: https:\/\/wpnovatos.com\/comentarios-wordpress\/<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Lipez, J. (2017). C\u00f3mo a\u00f1adir campos personalizados en el formulario de comentarios [Bllog]. Recuperado: https:\/\/wpdirecto.com\/como-anadir-campos-personalizados-en-el-formulario-de-comentarios\/<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Fernandes, A. (2020). Gesti\u00f3n de comentarios en WordPress (Tutorial Plugin Disqus) [Video]. Recuperado: https:\/\/www.youtube.com\/watch?v=ICi8NgSnpr8<\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">M Marketing Online. (2019). Ventajas y desventajas de WordPress [IMAGEN]. Recuperado: https:\/\/www.tmwebs.es\/ventajas-desventajas-wordpress\/<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La secci\u00f3n de comentarios en WordPress es un espacio qe permite a tus usuarios interactuar con los autores del contenido, dejando marcas que pueden mejorar la reputaci\u00f3n de tu sitio y convertirlo en un referente. Primero, WordPress ya viene con un sistema de comentarios nativo que le permite crear unaSeguir Leyendo<\/p>\n","protected":false},"author":318,"featured_media":22892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1492],"tags":[1922,1555,1590,1560],"class_list":["post-22743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wordpress","tag-comentarios","tag-formulario-wordpress","tag-informacion-de-wordpress","tag-que-es-wordpress"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comentarios de WordPress<\/title>\n<meta name=\"description\" content=\"En este articulo se ver\u00e1n los comentarios de WordPress, tambi\u00e9n se ver\u00e1n ventajas y desventajas, y un video tutorial\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comentarios de WordPress\" \/>\n<meta property=\"og:description\" content=\"En este articulo se ver\u00e1n los comentarios de WordPress, tambi\u00e9n se ver\u00e1n ventajas y desventajas, y un video tutorial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T21:10:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-30T21:10:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/Sin-titulo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Edinson Estid Cardenas Ram\u00edrez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edinson Estid Cardenas Ram\u00edrez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comentarios de WordPress","description":"En este articulo se ver\u00e1n los comentarios de WordPress, tambi\u00e9n se ver\u00e1n ventajas y desventajas, y un video tutorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/","og_locale":"es_ES","og_type":"article","og_title":"Comentarios de WordPress","og_description":"En este articulo se ver\u00e1n los comentarios de WordPress, tambi\u00e9n se ver\u00e1n ventajas y desventajas, y un video tutorial","og_url":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2022-03-30T21:10:26+00:00","article_modified_time":"2022-03-30T21:10:28+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/Sin-titulo.png","type":"image\/png"}],"author":"Edinson Estid Cardenas Ram\u00edrez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Edinson Estid Cardenas Ram\u00edrez","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/"},"author":{"name":"Edinson Estid Cardenas Ram\u00edrez","@id":"https:\/\/niixer.com\/#\/schema\/person\/7bd5683aff5475d81f471c80b7ce30cd"},"headline":"Comentarios de WordPress","datePublished":"2022-03-30T21:10:26+00:00","dateModified":"2022-03-30T21:10:28+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/"},"wordCount":1377,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/Sin-titulo.png","keywords":["comentarios","formulario wordpress","Informaci\u00f3n de WordPress","que es WordPress"],"articleSection":["WordPress"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/","url":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/","name":"Comentarios de WordPress","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/Sin-titulo.png","datePublished":"2022-03-30T21:10:26+00:00","dateModified":"2022-03-30T21:10:28+00:00","description":"En este articulo se ver\u00e1n los comentarios de WordPress, tambi\u00e9n se ver\u00e1n ventajas y desventajas, y un video tutorial","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/Sin-titulo.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/03\/Sin-titulo.png","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2022\/03\/30\/comentarios-de-wordpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Comentarios de WordPress"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/7bd5683aff5475d81f471c80b7ce30cd","name":"Edinson Estid Cardenas Ram\u00edrez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9055cf0a913e56863415ced1f21a08cfccc463c4d949410b80c6f430b3c681f3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9055cf0a913e56863415ced1f21a08cfccc463c4d949410b80c6f430b3c681f3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9055cf0a913e56863415ced1f21a08cfccc463c4d949410b80c6f430b3c681f3?s=96&d=mm&r=g","caption":"Edinson Estid Cardenas Ram\u00edrez"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/ecardenasr3\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/22743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=22743"}],"version-history":[{"count":18,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/22743\/revisions"}],"predecessor-version":[{"id":23060,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/22743\/revisions\/23060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/22892"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=22743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=22743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=22743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}