{"id":19948,"date":"2020-07-28T20:16:00","date_gmt":"2020-07-29T01:16:00","guid":{"rendered":"https:\/\/niixer.com\/?p=19948"},"modified":"2021-12-28T23:41:54","modified_gmt":"2021-12-29T04:41:54","slug":"la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/","title":{"rendered":"La OMS convoc\u00f3 comit\u00e9 por el repunte de casos de coronavirus."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&nbsp;El director general de la Organizaci\u00f3n Mundial de la Salud (OMS), Tedros Adhanom Ghebreyesus, anunci\u00f3 el lunes que convocar\u00e1 al comit\u00e9 de emergencia esta semana para \u201creevaluar\u201d la pandemia del coronavirus ante el repunte de casos en varias partes del mundo<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tedros por medio de su cuenta de twitter escribi\u00f3 que: \u201cComo lo requiere el Reglamento Sanitario Internacional, me reunir\u00e9 con el Comit\u00e9 de Emergencia esta semana para reevaluar la pandemia #COVID-19 y recibir los consejos en consecuencia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este llamado se ha producido teniendo en cuenta que el jueves se cumplen seis meses a desde que la OMS declar\u00f3 el Covid-19 como emergencia de salud y de inter\u00e9s internacional, cuando sal\u00edan reportado menos dec\u00edan casos en china y ning\u00fan muerto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>El director de la OMS destac\u00f3 que<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cesta es la sexta vez que se declara una emergencia de salud mundial seg\u00fan el Reglamento Sanitario Internacional, pero f\u00e1cilmente esta es la m\u00e1s grave\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. Ha se\u00f1alado las medidas para evitar la transmisi\u00f3n del coronavirus asegurando que en donde se siguen estas medidas los casos disminuyen, y en donde no se siguen, los casos aumentan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Varios pa\u00edses, como Espa\u00f1a, Corea del sur y china, donde naci\u00f3 el virus se han reportado un aumento sus casos, locas que sugiere que podr\u00edan estar experimentando la segunda ola<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La enfermedad del coronavirus 2019 es una afecci\u00f3n respiratoria que se propaga de persona a persona. Sede identific\u00f3 por primera vez en un brote en Wuhan, china, en diciembre del a\u00f1o pasado se extend\u00eda a acerca 213 pa\u00edses y territorios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La OMS declar\u00f3 el brote como una pandemia global el 11 de marzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De m\u00e1s de 16,6 millones de casos que han sido confirmados, m\u00e1s de 10,2 millones se han recuperado, mientras que las muertes superan las 655 mil, seg\u00fan los datos recopilados por Worldometer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las naciones donde m\u00e1s v\u00edctimas ha dejado el coronavirus son: Estados Unidos, con m\u00e1s de 150 mil; Brasil, con m\u00e1s de 87 mil; Reino Unido, con m\u00e1s de 45 mil; M\u00e9xico, con m\u00e1s de 43 mil; Italia, con m\u00e1s de 35 mil muertos; e India, con m\u00e1s de 33 mil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar del creciente n\u00famero de casos, la mayor\u00eda de personas infectadas s\u00f3lo productos sufren s\u00edntomas leves y se recuperan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor:&nbsp;&nbsp;<\/strong><a href=\"https:\/\/niixer.com\/?s=Hisle+%C3%81ngela+Guti%C3%A9rrez+Garc%C3%ADa\"><strong>Hisle \u00c1ngela Guti\u00e9rrez Garc\u00eda<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor:&nbsp;<\/strong><a href=\"http:\/\/web.archive.org\/web\/20200806154301\/http:\/www.niixer.com\/author\/cpinzon19\/\"><strong>Carlos Pinz\u00f3n<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo<\/strong>: UUPP-6<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FUENTES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anadolu. (2020).&nbsp;<em>OMS convoca comit\u00e9 por repunte de casos de coronavirus.<\/em>&nbsp;Semana.&nbsp;<a href=\"https:\/\/www.semana.com\/mundo\/articulo\/comite-de-emergencia-de-oms-por-casos-covid-19--noticias-mundo\/689559\">https:\/\/www.semana.com\/mundo\/articulo\/comite-de-emergencia-de-oms-por-casos-covid-19\u2013noticias-mundo\/689559<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Padri\u00f1an. M. (2020).&nbsp;<em>oms-organizaci\u00f3n-mundial-de-la-salud<\/em>.[Fotograf\u00eda]. pixabay.&nbsp;<a href=\"https:\/\/pixabay.com\/es\/illustrations\/oms-organizaci%C3%B3n-mundial-de-la-salud-4984801\/\">https:\/\/pixabay.com\/es\/illustrations\/oms-organizaci%C3%B3n-mundial-de-la-salud-4984801\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;El director general de la Organizaci\u00f3n Mundial de la Salud (OMS), Tedros Adhanom Ghebreyesus, anunci\u00f3 el lunes que convocar\u00e1 al comit\u00e9 de emergencia esta semana para \u201creevaluar\u201d la pandemia del coronavirus ante el repunte de casos en varias partes del mundo. Tedros por medio de su cuenta de twitter escribi\u00f3Seguir Leyendo<\/p>\n","protected":false},"author":2,"featured_media":19949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[46],"tags":[75,74,1819],"class_list":["post-19948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia","tag-coronavirus","tag-covid-19","tag-oms"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La OMS convoc\u00f3 comit\u00e9 por el repunte de casos de coronavirus.<\/title>\n<meta name=\"description\" content=\"\u00a0El director de la Organizaci\u00f3n Mundial de la Salud (OMS), anunci\u00f3 que convocar\u00e1 a comit\u00e9 esta semana para \u201creevaluar\u201d la pandemia del coronavirus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La OMS convoc\u00f3 comit\u00e9 por el repunte de casos de coronavirus.\" \/>\n<meta property=\"og:description\" content=\"\u00a0El director de la Organizaci\u00f3n Mundial de la Salud (OMS), anunci\u00f3 que convocar\u00e1 a comit\u00e9 esta semana para \u201creevaluar\u201d la pandemia del coronavirus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-29T01:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-29T04:41:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/12\/who-g84ba9e03b_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hisle Angela Gutierrez Garcia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hisle Angela Gutierrez Garcia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La OMS convoc\u00f3 comit\u00e9 por el repunte de casos de coronavirus.","description":"\u00a0El director de la Organizaci\u00f3n Mundial de la Salud (OMS), anunci\u00f3 que convocar\u00e1 a comit\u00e9 esta semana para \u201creevaluar\u201d la pandemia del coronavirus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/","og_locale":"es_ES","og_type":"article","og_title":"La OMS convoc\u00f3 comit\u00e9 por el repunte de casos de coronavirus.","og_description":"\u00a0El director de la Organizaci\u00f3n Mundial de la Salud (OMS), anunci\u00f3 que convocar\u00e1 a comit\u00e9 esta semana para \u201creevaluar\u201d la pandemia del coronavirus.","og_url":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2020-07-29T01:16:00+00:00","article_modified_time":"2021-12-29T04:41:54+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/12\/who-g84ba9e03b_1280.jpg","type":"image\/jpeg"}],"author":"Hisle Angela Gutierrez Garcia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Hisle Angela Gutierrez Garcia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/"},"author":{"name":"Hisle Angela Gutierrez Garcia","@id":"https:\/\/niixer.com\/#\/schema\/person\/df077f3ee9b553b87200a4b81787df50"},"headline":"La OMS convoc\u00f3 comit\u00e9 por el repunte de casos de coronavirus.","datePublished":"2020-07-29T01:16:00+00:00","dateModified":"2021-12-29T04:41:54+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/"},"wordCount":461,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/12\/who-g84ba9e03b_1280.jpg","keywords":["coronavirus","Covid-19","oms"],"articleSection":["Ciencia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/","url":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/","name":"La OMS convoc\u00f3 comit\u00e9 por el repunte de casos de coronavirus.","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/12\/who-g84ba9e03b_1280.jpg","datePublished":"2020-07-29T01:16:00+00:00","dateModified":"2021-12-29T04:41:54+00:00","description":"\u00a0El director de la Organizaci\u00f3n Mundial de la Salud (OMS), anunci\u00f3 que convocar\u00e1 a comit\u00e9 esta semana para \u201creevaluar\u201d la pandemia del coronavirus.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/12\/who-g84ba9e03b_1280.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/12\/who-g84ba9e03b_1280.jpg","width":1280,"height":720,"caption":"oms"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2020\/07\/28\/la-oms-convoco-comite-por-el-repunte-de-casos-de-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"La OMS convoc\u00f3 comit\u00e9 por el repunte de casos de coronavirus."}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/df077f3ee9b553b87200a4b81787df50","name":"Hisle Angela Gutierrez Garcia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/478d3c52bc01fb35093a9f59a55dd22e2e9ce20c78076a1ed84601b86033c9b7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/478d3c52bc01fb35093a9f59a55dd22e2e9ce20c78076a1ed84601b86033c9b7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/478d3c52bc01fb35093a9f59a55dd22e2e9ce20c78076a1ed84601b86033c9b7?s=96&d=mm&r=g","caption":"Hisle Angela Gutierrez Garcia"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/hgutierrezga\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/19948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=19948"}],"version-history":[{"count":2,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/19948\/revisions"}],"predecessor-version":[{"id":19951,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/19948\/revisions\/19951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/19949"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=19948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=19948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=19948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}