{"id":17794,"date":"2021-11-18T15:56:19","date_gmt":"2021-11-18T20:56:19","guid":{"rendered":"https:\/\/niixer.com\/?p=17794"},"modified":"2021-11-18T16:00:30","modified_gmt":"2021-11-18T21:00:30","slug":"el-metaverso","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/","title":{"rendered":"El Metaverso"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En los \u00faltimos a\u00f1os muchas personas han estado hablando de &#8220;El <a href=\"https:\/\/niixer.com\/?s=metaverso\">metaverso<\/a>&#8221; como la pr\u00f3xima gran invenci\u00f3n que va a revolucionar la vida de las personas en l\u00ednea. Sin embargo, existen diferentes conceptos o ideas sobre lo que esto significa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El metaverso es una combinaci\u00f3n de m\u00faltiples elementos de tecnolog\u00eda, incluida la realidad virtual, la realidad aumentada y el video donde los usuarios &#8220;viven&#8221; dentro de un universo digital. As\u00ed, hay que pensar en \u00e9l como un universo paralelo digital e infinito que se conecta a nuestro mundo f\u00edsico. Igualmente, el metaverso puede considerarse como informaci\u00f3n que est\u00e1 fuera del alcance de los cuerpos f\u00edsicos y a la que se puede acceder e interactuar utilizando diferentes tecnolog\u00edas (Nover, 2021).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Puntos de acceso del metaverso<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El primer punto de acceso del Metaverso fue el computador, ya que pod\u00eda almacenar informaci\u00f3n y realizar c\u00e1lculos simples. Este fue el origen de lo que se considera el Metaverso. A medida que las computadoras se fueron volviendo m\u00e1s sofisticadas y almacenaron programas m\u00e1s complejos, crearon lo que ahora se conoce como el panorama digital moderno (Clark, 2021).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al tiempo que avanzaba el hardware inform\u00e1tico, se cre\u00f3 un &#8220;ciberespacio&#8221; aut\u00f3nomo. Un espacio metaf\u00edsico que existe dentro de la memoria almacenada de la computadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este ciberespacio adquiri\u00f3 un nuevo significado cuando las computadoras se conectaron en red para crear el Internet. El cual, es la iteraci\u00f3n original de lo que ahora se considera el Metaverso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, en los \u00faltimos a\u00f1os se cre\u00f3 un nuevo tipo de punto de acceso: El tel\u00e9fono inteligente y las redes inal\u00e1mbricas m\u00f3viles ya que brindan un nivel de acceso casi constante y sin precedentes al Metaverso. Como, por ejemplo, cargar, descargar y compartir cantidades de informaci\u00f3n nuevas dentro del ciberespacio en red (Clark, 2021).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conviene se\u00f1alar que, los usuarios de tel\u00e9fonos m\u00f3viles pueden agregar im\u00e1genes y videos al Metaverso y pueden interactuar entre s\u00ed a trav\u00e9s de chats de video, as\u00ed como tambi\u00e9n pueden interactuar entre s\u00ed en juegos en l\u00ednea multijugador masivo como Fortnite (Camacho, 2021).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/meta-1024x576.jpg\" alt=\"\" class=\"wp-image-17815\" width=\"619\" height=\"348\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/meta-1024x576.jpg 1024w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/meta-300x169.jpg 300w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/meta-768x432.jpg 768w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/meta.jpg 1280w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Realidad Aumentada VS Realidad Mixta<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con el tiempo, el hecho de que m\u00e1s personas empezaron a usar tel\u00e9fonos dio lugar a una nueva forma de interactuar con el Metaverso. Las c\u00e1maras y el acceso constante a Internet crearon herramientas que permitieron incorporar el Metaverso al mundo f\u00edsico. Esto se llama<a href=\"https:\/\/www.google.com\/search?q=realidad+aumentada&amp;oq=realidad+aumen&amp;aqs=chrome.0.0i433i512j69i57j0i512l3j69i61l3.3488j0j7&amp;sourceid=chrome&amp;ie=UTF-8\"> Realidad Aumentada<\/a> (RA), lo cual se entiende de forma coloquial como una especie de museo, donde se puede mirar y experimentar aumentos digitales en espacios f\u00edsicos, pero no pueden ser tocados f\u00edsicamente (Nover 2021).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El aspecto de la realidad aumentada se vuelve impreciso cuando se comienza a interactuar con el universo digital. En esta situaci\u00f3n se convierte en una realidad mixta (RM) la cual es creada cuando un usuario tiene la posibilidad de interactuar directamente con el Metaverso en un entorno f\u00edsico (Nover, 2021). Un ejemplo claro, es la pel\u00edcula llamada Sentencia Previa, ya que muestra c\u00f3mo es la interacci\u00f3n con los entornos digitales en un mundo f\u00edsico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En resumen, no es necesario tener un visor de realidad virtual para interactuar con el Metaverso. Independientemente de su nivel de inmersi\u00f3n, se puede interactuar con el Metaverso directamente desde un teclado (Nover 2021).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, a medida que se contin\u00faan creando nuevas formas de dispositivos conectados, el Metaverso ser\u00e1 cada vez m\u00e1s accesible para el mundo. La infraestructura de red m\u00f3vil de IoT y 5G est\u00e1 recibiendo una inversi\u00f3n significativa y seguramente crecer\u00e1 durante la pr\u00f3xima d\u00e9cada.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/hombre-con-gafas-vr-683x1024.jpg\" alt=\"\" class=\"wp-image-17816\" width=\"-263\" height=\"-394\" srcset=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/hombre-con-gafas-vr-683x1024.jpg 683w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/hombre-con-gafas-vr-200x300.jpg 200w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/hombre-con-gafas-vr-768x1151.jpg 768w, https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/hombre-con-gafas-vr.jpg 854w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor:<\/strong> Carlos Andr\u00e9s Herrera Barrera<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor: <\/strong>Carlos Ivan Pinz\u00f3n Romero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo:<\/strong> UCRV-8<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad:<\/strong> Universidad Central<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong><\/h3>\n\n\n\n<pre class=\"wp-block-preformatted\">Camacho, D. (2021). \u201cEl metaverso de Facebook est\u00e1 cada vez m\u00e1s cerca\u201d. Platzi. <a href=\"https:\/\/platzi.com\/blog\/metaverso-facebook-realidad\/?\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/platzi.com\/blog\/metaverso-facebook-realidad\/utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=12915366154&amp;utm_adgroup=&amp;utm_content=&amp;gclid=CjwKCAiA7dKMBhBCEiwAO_crFF2JxF56rODcyGRnth0pGtrUn06rIc6Gn301jnWi3S3naAo2a-CydRoCBnYQAvD_BwE&amp;gclsrc=aw.ds<\/a>\n\nClark, P. (2021). \u201cThe Metaverse Has Already Arrived. Here\u2019s What That Actually Means\u201d. Time.<a href=\"https:\/\/time.com\/6116826\/what-is-the-metaverse\/\" target=\"_blank\" rel=\"noreferrer noopener\"> https:\/\/time.com\/6116826\/what-is-the-metaverse\/<\/a>\n\nNover, S. (2021). \u201cThe meaning of the \u2018metaverse,\u2019 and all the terms you need to understand it\u201d. Quartz.  <a href=\"https:\/\/qz.com\/2089665\/everything-you-need-to-know-to-understand-the-metaverse\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/qz.com\/2089665\/everything-you-need-to-know-to-understand-the-metaverse\/<\/a>\n\nAhmad, A.(2019). Hombre Vestido Con Camisa Gris Con Auriculares De Virtual Realty. [Imagen] Pexels. <a href=\"https:\/\/qz.com\/2089665\/everything-you-need-to-know-to-understand-the-metaverse\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/qz.com\/2089665\/everything-you-need-to-know-to-understand-the-metaverse\/<\/a>\n \nMeseguer, E. (2019). Fantasia Realidad Virtual VR. [Imagen]. Pixabay. <a href=\"https:\/\/pixabay.com\/es\/photos\/fantas%c3%ada-realidad-virtual-vr-4618133\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/pixabay.com\/es\/photos\/fantas%c3%ada-realidad-virtual-vr-4618133\/ \n<\/a>\nForbes. (2021). Meta. [Imagen]. Forbes. <a href=\"https:\/\/forbes.co\/2021\/10\/31\/tecnologia\/como-funcionara-el-metaverso-de-facebook\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/forbes.co\/2021\/10\/31\/tecnologia\/como-funcionara-el-metaverso-de-facebook\/ \n<\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os muchas personas han estado hablando de &#8220;El metaverso&#8221; como la pr\u00f3xima gran invenci\u00f3n que va a revolucionar la vida de las personas en l\u00ednea. Sin embargo, existen diferentes conceptos o ideas sobre lo que esto significa. El metaverso es una combinaci\u00f3n de m\u00faltiples elementos de tecnolog\u00eda,Seguir Leyendo<\/p>\n","protected":false},"author":191,"featured_media":17814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[47],"tags":[1733,1734,65,81],"class_list":["post-17794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-realidad-virtual","tag-metaverso","tag-mundo-digital","tag-realidad-aumentada","tag-realidad-virtual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Metaverso - %<\/title>\n<meta name=\"description\" content=\"En los \u00faltimos a\u00f1os muchas personas han estado hablando de &quot;El metaverso&quot; como la pr\u00f3xima gran invenci\u00f3n que va a revolucionar la vida\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Metaverso - %\" \/>\n<meta property=\"og:description\" content=\"En los \u00faltimos a\u00f1os muchas personas han estado hablando de &quot;El metaverso&quot; como la pr\u00f3xima gran invenci\u00f3n que va a revolucionar la vida\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-18T20:56:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-18T21:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/portada-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlos Andres Herrera Barrera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Andres Herrera Barrera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Metaverso - %","description":"En los \u00faltimos a\u00f1os muchas personas han estado hablando de \"El metaverso\" como la pr\u00f3xima gran invenci\u00f3n que va a revolucionar la vida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/","og_locale":"es_ES","og_type":"article","og_title":"El Metaverso - %","og_description":"En los \u00faltimos a\u00f1os muchas personas han estado hablando de \"El metaverso\" como la pr\u00f3xima gran invenci\u00f3n que va a revolucionar la vida","og_url":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2021-11-18T20:56:19+00:00","article_modified_time":"2021-11-18T21:00:30+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/portada-2-scaled.jpg","type":"image\/jpeg"}],"author":"Carlos Andres Herrera Barrera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carlos Andres Herrera Barrera","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/"},"author":{"name":"Carlos Andres Herrera Barrera","@id":"https:\/\/niixer.com\/#\/schema\/person\/50b94cab3feb23d014d8f20270567d9c"},"headline":"El Metaverso","datePublished":"2021-11-18T20:56:19+00:00","dateModified":"2021-11-18T21:00:30+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/"},"wordCount":636,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/portada-2-scaled.jpg","keywords":["Metaverso","mundo digital","Realidad Aumentada","Realidad Virtual"],"articleSection":["Realidad Virtual"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/","url":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/","name":"El Metaverso - %","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/portada-2-scaled.jpg","datePublished":"2021-11-18T20:56:19+00:00","dateModified":"2021-11-18T21:00:30+00:00","description":"En los \u00faltimos a\u00f1os muchas personas han estado hablando de \"El metaverso\" como la pr\u00f3xima gran invenci\u00f3n que va a revolucionar la vida","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/portada-2-scaled.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/11\/portada-2-scaled.jpg","width":2560,"height":1707,"caption":"hombe_rv"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2021\/11\/18\/el-metaverso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"El Metaverso"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/50b94cab3feb23d014d8f20270567d9c","name":"Carlos Andres Herrera Barrera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/91496e44d759d26069373816ec4a6f01d69b3ae6a941cb05433afd8803be7be1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/91496e44d759d26069373816ec4a6f01d69b3ae6a941cb05433afd8803be7be1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/91496e44d759d26069373816ec4a6f01d69b3ae6a941cb05433afd8803be7be1?s=96&d=mm&r=g","caption":"Carlos Andres Herrera Barrera"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/cherrerab\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/17794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=17794"}],"version-history":[{"count":2,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/17794\/revisions"}],"predecessor-version":[{"id":17851,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/17794\/revisions\/17851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/17814"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=17794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=17794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=17794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}