{"id":1518,"date":"2020-10-16T20:31:39","date_gmt":"2020-10-17T01:31:39","guid":{"rendered":"https:\/\/niixer.com\/?p=1518"},"modified":"2020-10-16T20:31:40","modified_gmt":"2020-10-17T01:31:40","slug":"ipad-air-4-apple-lanza-nueva-version-para-este-2020","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/","title":{"rendered":"iPad Air 4, Apple lanza nueva versi\u00f3n para este 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hoy 16 de octubre la marca californiana de tecnolog\u00eda Apple, saco en preventa no solo su pr\u00f3ximo iPhone 12 con sus diferentes versiones, tambi\u00e9n dio la sorpresa de que sacara al mercado tecnol\u00f3gico su cuarta edici\u00f3n del iPad Air, en reserva al igual que el iPhone y con pocos detalles a diferencia del m\u00f3vil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Caracter\u00edsticas del iPad Air 4<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva iPad cuenta con una pantalla Liquid Retina de 10,9 pulgadas con tecnolog\u00eda True Tone y gama crom\u00e1tica amplia, con resoluci\u00f3n (2360 x 1640p) la cual permite ver im\u00e1genes con resoluci\u00f3n 4k, un avance importante con respecto a su versi\u00f3n anterior, adem\u00e1s es compatible con el Apple Pencil; mide 247,6 X 178,5 X 6,1 mm&nbsp; y pesa alrededor de 460g. Tambi\u00e9n es compatible con el Magic keyboard (el teclado de Apple para tablets) lo cual pr\u00e1cticamente lo convierte en un PC, y a continuaci\u00f3n les explicar\u00e9 el porqu\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Innovaciones de software para el iPad<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Esta nueva versi\u00f3n del iPad incluye el nuevo Chip A14 Bionic que proporciona a esta Tablet de Apple una CPU 40% m\u00e1s r\u00e1pida, gr\u00e1ficas 30% m\u00e1s r\u00e1pidas y aprendizaje autom\u00e1tico dos veces m\u00e1s r\u00e1pido gracias al Neural Engine de \u00faltima generaci\u00f3n, siendo este el avance m\u00e1s significativo en comparaci\u00f3n a la iPad 3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte proporciona dos capacidades de almacenamiento, una memoria de 256 GB y otra de 64GB; tiene un sensor Touch ID como sistema de seguridad, en el lateral superior del iPad para ganar m\u00e1s espacio de pantalla, una conexi\u00f3n de carga USB tipo C y proporciona hasta 10 horas de uso continuo, gracias a la adaptaci\u00f3n del Chip A14; para finalizar tiene un nuevo sistema operativo, el iPadOS 14 que incluye poderosas funcionalidades y apps integradas para que puedas aprovechar al m\u00e1ximo las posibilidades \u00fanicas del iPad.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>C\u00e1mara con resoluci\u00f3n 4k<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Tablet cuenta con una c\u00e1mara de sensor gran angular de 12 megap\u00edxeles, con un foco de apertura 1.8; lo cual puede que para usted no suene muy atractivo teniendo en cuenta las c\u00e1maras que manejan los dispositivos m\u00f3viles en la actualidad, pero lo que no tiene esta iPad en megap\u00edxeles lo tiene en otros aspectos. Gracias al chip A14 Bionic pone la potencia que necesita para dar vida a sus ideas, permite grabar en resoluci\u00f3n 4K y luego editarlo ah\u00ed mismo en el iPad Air, sin necesidad de usar un Mac u otro PC, solo use el Apple Pencil de segunda generaci\u00f3n para dar vida a sus ideas; con el rendimiento mejorado de gr\u00e1ficas y aprendizaje autom\u00e1tico del chip A14 Bionic, tendr\u00e1 a su alcance la posibilidad de editar fotos, crear m\u00fasica y m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autor:&nbsp;<a href=\"https:\/\/niixer.com\/?s=Andres+Felipe+Avenda%C3%B1o+Junca\">Andr\u00e9s Felipe Avenda\u00f1o Junca<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Editor: Carlos Pinz\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Codigo:UUPS-5<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong><\/h3>\n\n\n\n<pre class=\"wp-block-preformatted\">Linares, I. (2020). <em>El iPad Air de 2020 ya se puede reservar, as\u00ed puedes comprarlo<\/em>. Xataka. <a href=\"https:\/\/www.xatakamovil.com\/apple\/ipad-air-2020-se-puede-reservar-asi-puedes-comprarlo\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.xatakamovil.com\/apple\/ipad-air-2020-se-puede-reservar-asi-puedes-comprarlo<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">L\u00f3pez, M. (2020). <em>El nuevo iPad Air 4 ya se puede reservar desde la web oficial<\/em>. Applesfera. <a href=\"https:\/\/www.applesfera.com\/ipad\/nuevo-ipad-air-4-se-puede-reservar-web-oficial\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.applesfera.com\/ipad\/nuevo-ipad-air-4-se-puede-reservar-web-oficial<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Roca, A. (2020). <em>El iPad Air 2020 ya est\u00e1 a la venta, d\u00f3nde puedes comprarlo<\/em>. iPadizate. <a href=\"https:\/\/www.ipadizate.es\/2020\/10\/16\/el-ipad-air-2020-ya-esta-a-la-venta-donde-puedes-comprarlo\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.ipadizate.es\/2020\/10\/16\/el-ipad-air-2020-ya-esta-a-la-venta-donde-puedes-comprarlo\/<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Apple. (2020). <em>iPad Air<\/em>. Apple. <a href=\"https:\/\/www.apple.com\/co\/ipad-air\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.apple.com\/co\/ipad-air\/<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Sanz, J. L. (2020). <em>NUEVOS RENDERS MUESTRAN C\u00d3MO SER\u00c1 EL DISE\u00d1O DE LOS FUTUROS IPAD AIR<\/em> [Imagen]. Smartlife. <a href=\"https:\/\/cincodias.elpais.com\/cincodias\/2020\/09\/03\/tablets\/1599127026_608316.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/cincodias.elpais.com\/cincodias\/2020\/09\/03\/tablets\/1599127026_608316.html<\/a><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Hoy 16 de octubre la marca californiana de tecnolog\u00eda Apple, saco en preventa no solo su pr\u00f3ximo iPhone 12 con sus diferentes versiones, tambi\u00e9n dio la sorpresa de que sacara al mercado tecnol\u00f3gico su cuarta edici\u00f3n del iPad Air, en reserva al igual que el iPhone y con pocos detallesSeguir Leyendo<\/p>\n","protected":false},"author":72,"featured_media":1519,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[22],"tags":[62,146,385,250],"class_list":["post-1518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-product","tag-apple","tag-ios","tag-ipad","tag-tablet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>iPad Air 4, Apple lanza nueva versi\u00f3n para este 2020<\/title>\n<meta name=\"description\" content=\"Hoy 16 de octubre la marca californiana de tecnolog\u00eda Apple, saco en preventa al mercado tecnol\u00f3gico su cuarta edici\u00f3n del iPad Air.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"iPad Air 4, Apple lanza nueva versi\u00f3n para este 2020\" \/>\n<meta property=\"og:description\" content=\"Hoy 16 de octubre la marca californiana de tecnolog\u00eda Apple, saco en preventa al mercado tecnol\u00f3gico su cuarta edici\u00f3n del iPad Air.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-17T01:31:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-17T01:31:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/4.4-iPad-Air-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andres Felipe Avenda\u00f1o Junca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andres Felipe Avenda\u00f1o Junca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"iPad Air 4, Apple lanza nueva versi\u00f3n para este 2020","description":"Hoy 16 de octubre la marca californiana de tecnolog\u00eda Apple, saco en preventa al mercado tecnol\u00f3gico su cuarta edici\u00f3n del iPad Air.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/","og_locale":"es_ES","og_type":"article","og_title":"iPad Air 4, Apple lanza nueva versi\u00f3n para este 2020","og_description":"Hoy 16 de octubre la marca californiana de tecnolog\u00eda Apple, saco en preventa al mercado tecnol\u00f3gico su cuarta edici\u00f3n del iPad Air.","og_url":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2020-10-17T01:31:39+00:00","article_modified_time":"2020-10-17T01:31:40+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/4.4-iPad-Air-4.jpg","type":"image\/jpeg"}],"author":"Andres Felipe Avenda\u00f1o Junca","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andres Felipe Avenda\u00f1o Junca","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/"},"author":{"name":"Andres Felipe Avenda\u00f1o Junca","@id":"https:\/\/niixer.com\/#\/schema\/person\/2b0bafc50f372f80e7f3cd6d990128cf"},"headline":"iPad Air 4, Apple lanza nueva versi\u00f3n para este 2020","datePublished":"2020-10-17T01:31:39+00:00","dateModified":"2020-10-17T01:31:40+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/"},"wordCount":489,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/4.4-iPad-Air-4.jpg","keywords":["Apple","IOS","iPad","Tablet"],"articleSection":["Top Productos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/","url":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/","name":"iPad Air 4, Apple lanza nueva versi\u00f3n para este 2020","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/4.4-iPad-Air-4.jpg","datePublished":"2020-10-17T01:31:39+00:00","dateModified":"2020-10-17T01:31:40+00:00","description":"Hoy 16 de octubre la marca californiana de tecnolog\u00eda Apple, saco en preventa al mercado tecnol\u00f3gico su cuarta edici\u00f3n del iPad Air.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/4.4-iPad-Air-4.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/4.4-iPad-Air-4.jpg","width":800,"height":445,"caption":"iPad Air 4"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/16\/ipad-air-4-apple-lanza-nueva-version-para-este-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"iPad Air 4, Apple lanza nueva versi\u00f3n para este 2020"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/2b0bafc50f372f80e7f3cd6d990128cf","name":"Andres Felipe Avenda\u00f1o Junca","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3c94653178a34488096a3fd0171cacb6b8aeb9e64afdc4ea75959c6fe7b3e6e?s=96&d=mm&r=g","caption":"Andres Felipe Avenda\u00f1o Junca"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/aavendanoju\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/1518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=1518"}],"version-history":[{"count":2,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/1518\/revisions"}],"predecessor-version":[{"id":1531,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/1518\/revisions\/1531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/1519"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=1518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=1518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=1518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}