{"id":11161,"date":"2021-08-23T22:53:18","date_gmt":"2021-08-24T03:53:18","guid":{"rendered":"https:\/\/niixer.com\/?p=11161"},"modified":"2021-09-03T23:30:33","modified_gmt":"2021-09-04T04:30:33","slug":"data-glove","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/","title":{"rendered":"Data Glove &#8211; Realidad Virtual"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Seg\u00fan el glosario de terminolog\u00eda inform\u00e1tica Data Glove es un dispositivo de entrada o controlador que se adapta a la mano y antebrazo, que permite con los movimientos de la mano, interactuar con programas de realidad virtual.<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es Data Glove ?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con el pasar de los a\u00f1os la <a href=\"https:\/\/niixer.com\/?s=realidad+virtual\">realidad virtual<\/a> se est\u00e1 volviendo mucho m\u00e1s popular, las personas del mundo cada vez son m\u00e1s conscientes de que existe, adem\u00e1s, de interesarse por participar o interactuar con ella y sus avances. Los guantes de datos o guantes VR son uno de los medios que a\u00fan est\u00e1 en desarrollo, estos guantes son dispositivos de entrada port\u00e1tiles que cuentan con varios sensores de movimiento que se encargan de rastrear los movimientos de la mano y traducen la informaci\u00f3n de entrada a diferentes aplicaciones de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Rob%C3%B3tica\">rob\u00f3tica <\/a>y juegos de realidad virtual. Es usado para registrar movimientos f\u00edsicos como la rotaci\u00f3n de las manos o curvas de los dedos y transf\u00f3rmalo en informaci\u00f3n digital. Para capturar estos movimientos, se utilizan software de interpretaci\u00f3n o controladores que est\u00e1n hechos especialmente para los guantes, por lo que cualquier movimiento que se haga con las manos \/ guantes se puede convertir en entradas para programas de realidad virtual,<a href=\"https:\/\/www.vidaextra.com\/listas\/mejores-juegos-realidad-virtual-que-puedes-jugar\"> juegos de realidad virtual<\/a> &#8211; Data Glove  o rob\u00f3tica de control.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo se desarrollo Data Glove?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Daniel J. Sandin y Thomas DeFanti en 1977 de Universidad de Illinois en Chicago realizaron un estudio y lo llamaron, The Sayre Glove. La idea naci\u00f3 junto con su colega Richard Sayre, lo construyeron como un proyecto para el National Endowment for the Arts. Lo que han usado para hacer el guante son tubos flexibles que tienen una fotoc\u00e9lula, (un sensor peque\u00f1o y econ\u00f3mico que detecta la luz si la golpea), en un extremo y una fuente de luz en el otro, (solo para aclarar cualquier confusi\u00f3n. tubo flexible no son fibras \u00f3pticas). La luz viaja a trav\u00e9s de los tubos hasta los sensores de la fotoc\u00e9lula y, dependiendo de cu\u00e1nto doble el dedo, cuanto m\u00e1s doble menos luz recibir\u00e1n las fotoc\u00e9lulas, entonces las fotoc\u00e9lulas medir\u00e1n cu\u00e1nta luz est\u00e1 recibiendo, y en base a eso puede diga cu\u00e1nto ha doblado los dedos y transfi\u00e9ralo a la informaci\u00f3n introducida. Ese fue el proyecto de inicio del desarrollo del guante de datos en  programas de realidad virtual,<a href=\"https:\/\/www.vidaextra.com\/listas\/mejores-juegos-realidad-virtual-que-puedes-jugar\"> juegos de realidad virtual<\/a> &#8211; Data Glove  o rob\u00f3tica de control.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>En la actualidad .<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esta tecnolog\u00eda es bastante costosa ya que se proporciona en guantes de alta gama, adem\u00e1s de que dicha <a href=\"https:\/\/niixer.com\/?s=tecnologia\">tecnolog\u00eda <\/a>tambi\u00e9n funciona como dispositivo de salida y su m\u00e1s com\u00fan uso es en entornos de realidad virtual o juegos de este tipo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autor<\/strong>: Daniela Ines Iba\u00f1ez Cuevas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Editor: <\/strong>Carlos Iv\u00e1n Pinz\u00f3n Romero<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3digo:<\/strong> UCCG-91<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Universidad: <\/strong>UNIVERSIDAD CENTRAL<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fuentes<\/strong>:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<pre class=\"wp-block-preformatted\">Glosario de terminolog\u00eda Inform\u00e1tica (1996). data glove.<a href=\"http:\/\/www.tugurium.com\/gti\/termino.php?Tr=data%20glove\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.tugurium.com\/gti\/termino.php?Tr=data%20glove<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\"><a href=\"https:\/\/medium.com\/@b00062378?source=post_page-----84efe6ff72bb--------------------------------\">Abdulrahman Jan<\/a>(2019).<strong>The Evolution of Gloves as Input Devices.<\/strong><a href=\"https:\/\/medium.com\/@b00062378\/the-evolution-of-gloves-as-input-devices-84efe6ff72bb\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/medium.com\/@b00062378\/the-evolution-of-gloves-as-input-devices-84efe6ff72bb<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">Wikipedia (2021). Wired glove. <a href=\"https:\/\/en.wikipedia.org\/wiki\/Wired_glove\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/en.wikipedia.org\/wiki\/Wired_glove<\/a><\/pre>\n\n\n\n<pre class=\"wp-block-preformatted\">The engineer(2021). Grip assist robotic glove powered by AI.<a href=\"https:\/\/www.theengineer.co.uk\/grip-assist-robotic-glove-powered-by-ai\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.theengineer.co.uk\/grip-assist-robotic-glove-powered-by-ai\/<\/a><\/pre>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan el glosario de terminolog\u00eda inform\u00e1tica Data Glove es un dispositivo de entrada o controlador que se adapta a la mano y antebrazo, que permite con los movimientos de la mano, interactuar con programas de realidad virtual. \u00bfQu\u00e9 es Data Glove ? Con el pasar de los a\u00f1os la realidadSeguir Leyendo<\/p>\n","protected":false},"author":227,"featured_media":11176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1309],"tags":[892,81,228],"class_list":["post-11161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-computacion-grafica","tag-dispositivos-de-sonido","tag-realidad-virtual","tag-tecnologia-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Data Glove - Realidad Virtual &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos<\/title>\n<meta name=\"description\" content=\"Descripci\u00f3n, Historia y actualidad de de Data Glove o Guantes VR usados en videojuegos y rob\u00f3tica de realidad virtual\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Data Glove - Realidad Virtual &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"og:description\" content=\"Descripci\u00f3n, Historia y actualidad de de Data Glove o Guantes VR usados en videojuegos y rob\u00f3tica de realidad virtual\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-24T03:53:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-04T04:30:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2021\/08\/articulo1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Daniela Ines Iba\u00f1ez Cuevas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniela Ines Iba\u00f1ez Cuevas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Data Glove - Realidad Virtual &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","description":"Descripci\u00f3n, Historia y actualidad de de Data Glove o Guantes VR usados en videojuegos y rob\u00f3tica de realidad virtual","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/","og_locale":"es_ES","og_type":"article","og_title":"Data Glove - Realidad Virtual &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","og_description":"Descripci\u00f3n, Historia y actualidad de de Data Glove o Guantes VR usados en videojuegos y rob\u00f3tica de realidad virtual","og_url":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2021-08-24T03:53:18+00:00","article_modified_time":"2021-09-04T04:30:33+00:00","og_image":[{"width":660,"height":425,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/08\/articulo1-1.png","type":"image\/png"}],"author":"Daniela Ines Iba\u00f1ez Cuevas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Daniela Ines Iba\u00f1ez Cuevas","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/"},"author":{"name":"Daniela Ines Iba\u00f1ez Cuevas","@id":"https:\/\/niixer.com\/#\/schema\/person\/0ca1e3d1669d8c725c547a006c49db5f"},"headline":"Data Glove &#8211; Realidad Virtual","datePublished":"2021-08-24T03:53:18+00:00","dateModified":"2021-09-04T04:30:33+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/"},"wordCount":501,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/08\/articulo1.png","keywords":["Dispositivos de sonido","Realidad Virtual","Tecnologia"],"articleSection":["Computaci\u00f3n Gr\u00e1fica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/","url":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/","name":"Data Glove - Realidad Virtual &#8211; Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/08\/articulo1.png","datePublished":"2021-08-24T03:53:18+00:00","dateModified":"2021-09-04T04:30:33+00:00","description":"Descripci\u00f3n, Historia y actualidad de de Data Glove o Guantes VR usados en videojuegos y rob\u00f3tica de realidad virtual","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/08\/articulo1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2021\/08\/articulo1.png","width":660,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2021\/08\/23\/data-glove\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Data Glove &#8211; Realidad Virtual"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/0ca1e3d1669d8c725c547a006c49db5f","name":"Daniela Ines Iba\u00f1ez Cuevas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e422352418bf7ecf2c6e6dc3607ee4ae236828149ec1d951b79a88b07d525695?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e422352418bf7ecf2c6e6dc3607ee4ae236828149ec1d951b79a88b07d525695?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e422352418bf7ecf2c6e6dc3607ee4ae236828149ec1d951b79a88b07d525695?s=96&d=mm&r=g","caption":"Daniela Ines Iba\u00f1ez Cuevas"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/dibanezc\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/11161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/227"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=11161"}],"version-history":[{"count":15,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/11161\/revisions"}],"predecessor-version":[{"id":11934,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/11161\/revisions\/11934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/11176"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=11161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=11161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=11161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}