{"id":1019,"date":"2020-10-14T15:33:16","date_gmt":"2020-10-14T20:33:16","guid":{"rendered":"https:\/\/niixer.com\/?p=1019"},"modified":"2020-10-14T15:33:59","modified_gmt":"2020-10-14T20:33:59","slug":"fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes","status":"publish","type":"post","link":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/","title":{"rendered":"Fotograf\u00eda panor\u00e1mica, una t\u00e9cnica que da realismo a las im\u00e1genes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La fotograf\u00eda panor\u00e1mica es una t\u00e9cnica de fotograf\u00eda perfecta para capturar paisajes y espacios grandes y poder visualizarlos como si estuvi\u00e9ramos all\u00ed. Son muy \u00fatiles para momentos en los que el <a href=\"https:\/\/niixer.com\/2020\/08\/13\/objetivos-la-maleabilidad-de-las-camaras-semiprofesionales\/\">objetivo de la c\u00e1mara<\/a> no puede tomar todo el escenario del que nos interesa tener una foto o tambi\u00e9n si queremos agregar un efecto de paisaje a la foto que deseamos tomar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otras palabras, la fotograf\u00eda panor\u00e1mica viene a resolver el problema de c\u00f3mo fotografiar un \u00e1ngulo tan amplio que puede resultar imposible captar con una \u00f3ptica est\u00e1ndar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las fotograf\u00edas panor\u00e1micas se caracterizan por dar una sensaci\u00f3n de amplitud de un escenarios que hayamos tomado a diferencia de cualquier otro formato. Sin embargo, hay que tener precauciones con las fotograf\u00edas panor\u00e1micas, como evitar que la foto no quede larga y estrecha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las panor\u00e1micas verticales para interiores y exteriores vienen muy bien si queremos cercan\u00eda y detalle sin perder mucho del encuadre, sin renunciar a la imagen completa. Tampoco se presentar\u00e1n distorsiones propias de efectos como el ojo de pez que si bien proporciona mayor \u00e1ngulo de imagen tambi\u00e9n hay demasiada distorsi\u00f3n en los bordes de la imagen.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Maneras de tomar panor\u00e1micas y software<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Existen varias maneras de tomar una foto panor\u00e1mica entre las cuales tenemos simplemente utilizar una c\u00e1mara de formato panor\u00e1mico, otra forma es tomar varios fotos y luego unirlas mediante el uso de <a href=\"https:\/\/niixer.com\/2020\/05\/21\/introduccion-al-software-del-sistema\/\">software<\/a> para lograr el efecto panor\u00e1mico, por \u00faltimo, tambi\u00e9n tenemos la opci\u00f3n de recortar una fotograf\u00eda para que tome un aspecto panor\u00e1mico aunque se puede perder calidad en la imagen al realizar <a href=\"http:\/\/www.thewebfoto.com\/2-hacer-fotos\/211-profundidad-de-campo\">profundidad de campo<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunas c\u00e1maras sencillas tienen entre sus funciones el modo panor\u00e1mico similar al de los tel\u00e9fonos celulares que ayuda al usuario a hacer una foto panor\u00e1mica mediante una gu\u00eda en la pantalla . Tambi\u00e9n hay distintos tipos de software para fotos panor\u00e1micas como: <a href=\"https:\/\/www.kamaradas.com\/t\/foro-de-autopano-giga-en-espanol\/584\">Autopano<\/a>, <a href=\"https:\/\/niixer.com\/2020\/08\/13\/panoramas-de-gran-calidad-con-ptgui\/\">PTGui<\/a>, o <a href=\"https:\/\/neoattack.com\/neowiki\/photoshop\/\">Photoshop.<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conceptos para tener una buena panor\u00e1mica<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para las fotograf\u00edas panor\u00e1micas se debe tener en cuenta evitar el movimiento al tomarlas, pues personas o autos en movimiento pueden complicar el proceso de edici\u00f3n despu\u00e9s de tomarlas (<a href=\"https:\/\/art-estudio.es\/produccion-fotografica\/\">posproducci\u00f3n<\/a>). Adem\u00e1s, para la parte de posproducci\u00f3n, al tomar una primera foto, la segunda debe tener un 30% de la imagen anterior para que cuando se utilice el software de edici\u00f3n este logre reconocer las partes y unir bien la foto mejorando la calidad de esta. Tambi\u00e9n es \u00fatil que una persona este en la foto para a\u00f1adir la sensaci\u00f3n de escala a la imagen y por ende, algo m\u00e1s de realismo. Por \u00faltimo cuidar la composici\u00f3n y tener una buena nivelaci\u00f3n de la c\u00e1mara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autor: <a href=\"https:\/\/niixer.com\/?s=miguel+vargas\">Miguel \u00c1ngel Vargas P\u00e9rez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Editor: Carlos Pinz\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f3digo: UCRV-4<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Universidad: <a href=\"https:\/\/www.ucentral.edu.co\/\">Universidad Central<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuentes:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><code>De Blois, A. (2019). <em>Truco extremadamente sencillo para conseguir panor\u00e1micas espectaculares (con ejemplos)<\/em>. Blog del fot\u00f3grafo. <a href=\"https:\/\/www.blogdelfotografo.com\/panoramicas-verticales\/\">https:\/\/www.blogdelfotografo.com\/panoramicas-verticales\/<\/a><\/code><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><code>De Blois, A. (2020). <em>R\u00f3tula panor\u00e1mica, qu\u00e9 es y para que la necesitas<\/em>. Blog del fot\u00f3grafo. <a href=\"https:\/\/www.blogdelfotografo.com\/rotula-panoramica\/\">https:\/\/www.blogdelfotografo.com\/rotula-panoramica\/<\/a><\/code><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><code>Llanos, J. (s.f.). <em>C\u00f3mo hacer fotograf\u00eda panor\u00e1mica \u2013 consejos y material. <\/em>365Enfoques. <a href=\"https:\/\/365enfoques.com\/mejorar-fotos\/consejos-fotografia-panoramica\/\">https:\/\/365enfoques.com\/mejorar-fotos\/consejos-fotografia-panoramica\/<\/a><\/code><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><code>Ospina, S. (2017). <em>\u00bfC\u00f3mo hacer fotos panor\u00e1micas con mi c\u00e1mara profesional?<\/em>&nbsp; &nbsp;ENTER.CO.&nbsp;<a href=\"https:\/\/www.enter.co\/cultura-digital\/el-popurri\/fotos-panoramicas-camara-profesional\/\"> https:\/\/www.enter.co\/cultura-digital\/el-popurri\/fotos-panoramicas-camara-profesional\/<\/a><\/code><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><code>Pixexid. (2017).&nbsp;<em>Panorama Miami Florida El Agua <\/em>[Fotograf\u00eda]. Pixabay. https:\/\/pixabay.com\/es\/photos\/panorama-miami-florida-el-agua-2117310\/<\/code><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><code>S\u00e1nchez, F. (2020). <em>Seis razones a favor de usar el formato panor\u00e1mico en nuestras fotograf\u00edas<\/em>. Xataka Foto. <a href=\"https:\/\/www.xatakafoto.com\/opinion\/cinco-razones-a-favor-usar-formato-panoramico-nuestras-fotografias\">https:\/\/www.xatakafoto.com\/opinion\/cinco-razones-a-favor-usar-formato-panoramico-nuestras-fotografias<\/a><\/code><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este art\u00edculo habla sobre la fotograf\u00eda panor\u00e1mica, una t\u00e9cnica que puede dar mayor amplitud en im\u00e1genes, adem\u00e1s de nombrar sus ventajas y algunos conceptos clave.<\/p>\n","protected":false},"author":71,"featured_media":1020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[30],"tags":[236,152,238,235,237],"class_list":["post-1019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-niixer","tag-amplitud","tag-fotografia-2","tag-imagen","tag-panoramica","tag-posproduccion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fotograf\u00eda panor\u00e1mica, una t\u00e9cnica que da realismo a las im\u00e1genes<\/title>\n<meta name=\"description\" content=\"Un art\u00edculo que define la fotograf\u00eda panor\u00e1mica, como funciona, ventajas y cosas a tener en cuenta a la hora de tomar una panor\u00e1mica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotograf\u00eda panor\u00e1mica, una t\u00e9cnica que da realismo a las im\u00e1genes\" \/>\n<meta property=\"og:description\" content=\"Un art\u00edculo que define la fotograf\u00eda panor\u00e1mica, como funciona, ventajas y cosas a tener en cuenta a la hora de tomar una panor\u00e1mica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/niixer\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-14T20:33:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T20:33:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/Panoramica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miguel Angel Vargas Perez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Angel Vargas Perez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fotograf\u00eda panor\u00e1mica, una t\u00e9cnica que da realismo a las im\u00e1genes","description":"Un art\u00edculo que define la fotograf\u00eda panor\u00e1mica, como funciona, ventajas y cosas a tener en cuenta a la hora de tomar una panor\u00e1mica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/","og_locale":"es_ES","og_type":"article","og_title":"Fotograf\u00eda panor\u00e1mica, una t\u00e9cnica que da realismo a las im\u00e1genes","og_description":"Un art\u00edculo que define la fotograf\u00eda panor\u00e1mica, como funciona, ventajas y cosas a tener en cuenta a la hora de tomar una panor\u00e1mica.","og_url":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/","og_site_name":"Portal de noticias de tecnolog\u00eda, Realidad Virtual, Aumentada y Mixta, Videojuegos","article_publisher":"https:\/\/www.facebook.com\/niixer\/","article_published_time":"2020-10-14T20:33:16+00:00","article_modified_time":"2020-10-14T20:33:59+00:00","og_image":[{"width":1280,"height":474,"url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/Panoramica.jpg","type":"image\/jpeg"}],"author":"Miguel Angel Vargas Perez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Miguel Angel Vargas Perez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/#article","isPartOf":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/"},"author":{"name":"Miguel Angel Vargas Perez","@id":"https:\/\/niixer.com\/#\/schema\/person\/7ff140c188636a53248fa72f4f7f97aa"},"headline":"Fotograf\u00eda panor\u00e1mica, una t\u00e9cnica que da realismo a las im\u00e1genes","datePublished":"2020-10-14T20:33:16+00:00","dateModified":"2020-10-14T20:33:59+00:00","mainEntityOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/"},"wordCount":513,"commentCount":0,"publisher":{"@id":"https:\/\/niixer.com\/#organization"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/Panoramica.jpg","keywords":["Amplitud","Fotograf\u00eda","Imagen","Panor\u00e1mica","Posproducci\u00f3n"],"articleSection":["Niixer"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/","url":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/","name":"Fotograf\u00eda panor\u00e1mica, una t\u00e9cnica que da realismo a las im\u00e1genes","isPartOf":{"@id":"https:\/\/niixer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/#primaryimage"},"image":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/#primaryimage"},"thumbnailUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/Panoramica.jpg","datePublished":"2020-10-14T20:33:16+00:00","dateModified":"2020-10-14T20:33:59+00:00","description":"Un art\u00edculo que define la fotograf\u00eda panor\u00e1mica, como funciona, ventajas y cosas a tener en cuenta a la hora de tomar una panor\u00e1mica.","breadcrumb":{"@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/#primaryimage","url":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/Panoramica.jpg","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2020\/10\/Panoramica.jpg","width":1280,"height":474,"caption":"Fotograf\u00eda panor\u00e1mica"},{"@type":"BreadcrumbList","@id":"https:\/\/niixer.com\/index.php\/2020\/10\/14\/fotografia-panoramica-una-tecnica-que-da-realismo-a-las-imagenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/niixer.com\/"},{"@type":"ListItem","position":2,"name":"Fotograf\u00eda panor\u00e1mica, una t\u00e9cnica que da realismo a las im\u00e1genes"}]},{"@type":"WebSite","@id":"https:\/\/niixer.com\/#website","url":"https:\/\/niixer.com\/","name":"Portal de noticias de tecnolog\u00eda, ciencia, Android, iOS, Realidad Virtual, Aumentada y Mixta, Videojuegos, computadores, todo lo mas reciente en tecnolog\u00eda","description":"Portal de noticias de tecnolog\u00eda","publisher":{"@id":"https:\/\/niixer.com\/#organization"},"alternateName":"Niixer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/niixer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/niixer.com\/#organization","name":"Niixer","alternateName":"Niixer.com","url":"https:\/\/niixer.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/","url":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","contentUrl":"https:\/\/niixer.com\/wp-content\/uploads\/2022\/08\/logo-niixer-sin-fondo-1.png","width":140,"height":140,"caption":"Niixer"},"image":{"@id":"https:\/\/niixer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/niixer\/","https:\/\/www.instagram.com\/niixer.tecnologia\/"]},{"@type":"Person","@id":"https:\/\/niixer.com\/#\/schema\/person\/7ff140c188636a53248fa72f4f7f97aa","name":"Miguel Angel Vargas Perez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/52e141f21ab5901a2375bea919397da546a10b6775e3514413c8be50402d81db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52e141f21ab5901a2375bea919397da546a10b6775e3514413c8be50402d81db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52e141f21ab5901a2375bea919397da546a10b6775e3514413c8be50402d81db?s=96&d=mm&r=g","caption":"Miguel Angel Vargas Perez"},"sameAs":["http:\/\/www.niixer.com"],"url":"https:\/\/niixer.com\/index.php\/author\/mvargasp1\/"}]}},"_links":{"self":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/1019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/comments?post=1019"}],"version-history":[{"count":2,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/1019\/revisions"}],"predecessor-version":[{"id":1022,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/posts\/1019\/revisions\/1022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media\/1020"}],"wp:attachment":[{"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/media?parent=1019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/categories?post=1019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/niixer.com\/index.php\/wp-json\/wp\/v2\/tags?post=1019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}